{"id":45099,"date":"2015-02-15T14:13:40","date_gmt":"2015-02-15T13:13:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45099"},"modified":"2015-02-15T14:13:40","modified_gmt":"2015-02-15T13:13:40","slug":"ruba-24-metri-di-rame-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/15\/ruba-24-metri-di-rame-arrestato\/","title":{"rendered":"RUBA 24 METRI DI RAME. ARRESTATO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/rame.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/rame-150x150.jpg\" alt=\"\" title=\"rame\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-20262\" \/><\/a>In un cantiere della ditta \u201cIsocem\u201d nella zona industriale, intorno alle ore 9.30 di questa mattina, una volante in servizio di controllo del territorio, ha notato il cancello aperto ed un uomo all\u2019interno che stava accumulando dei cavi di rame.<\/p>\n<p>La volante sostava davanti al cancello e bloccava l\u2019uomo mentre stava uscendo con 24 metri di cavi di rame.<\/p>\n<p>R.L. del \u201969 \u00e8 stato arrestato per furto aggravato in flagranza di reato.<\/p>\n<p>Lo stesso nel mese di agosto era stato arrestato per analogo reato, sempre dalle volanti<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/15\/ruba-24-metri-di-rame-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/15\/ruba-24-metri-di-rame-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>In un cantiere della ditta \u201cIsocem\u201d nella zona industriale, intorno alle ore 9.30 di questa mattina, una volante in servizio di controllo del territorio, ha notato il cancello aperto ed un uomo all\u2019interno che stava accumulando dei cavi di rame. La volante sostava davanti al cancello e bloccava l\u2019uomo mentre stava uscendo con 24 metri [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20262,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45099"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45099"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45099\/revisions"}],"predecessor-version":[{"id":45100,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45099\/revisions\/45100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20262"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}