{"id":45130,"date":"2015-02-17T13:58:41","date_gmt":"2015-02-17T12:58:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45130"},"modified":"2015-11-23T14:18:51","modified_gmt":"2015-11-23T13:18:51","slug":"lecce-commerciante-malmenato-nei-pressi-dello-stadio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/17\/lecce-commerciante-malmenato-nei-pressi-dello-stadio\/","title":{"rendered":"LECCE: COMMERCIANTE MALMENATO NEI PRESSI DELLO STADIO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/stadio.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/stadio-300x164.png\" alt=\"\" title=\"stadio\" width=\"300\" height=\"164\" class=\"alignleft size-medium wp-image-45131\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/stadio-300x164.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/stadio-1024x560.png 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/stadio.png 1076w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(g.m.)_____Ieri sera \u00a0una persona ferita a causa di un&#8217;aggressione, era stata segnalata alla Polizia, nei pressi dello Stadio nel Piazzale Adamo.<br \/>\nUna volante recatasi sul posto \u00a0 si imbatteva in un uomo, di 44 anni, \u00a0il quale riferiva \u00a0che verso le ore 17,30 \u00a0mentre era nei pressi della sua attivit\u00e0 commerciale,\u00a0 non lontana dalla zona stadio,\u00a0 era stato avvicinato da due individui a bordo di un\u2019auto e \u00a0\u00a0con la forza, \u00a0era stato spinto all\u2019interno della stessa.<br \/>\nGiunti in Piazzale Adamo, veniva fatto oggetto di \u00a0pugni in faccia e calci da uno dei due soggetti.<br \/>\nSul posto \u00e8 giunta poi un\u2019ambulanza del 118, che provvedeva ad\u00a0 accompagnare il malcapitato presso il pronto soccorso dell\u2019Ospedale Vito Fazzi, dove si riscontravano ferite guaribili in 15 gg.<br \/>\nNull&#8217;altro al momento \u00e8 dato di sapere, sono in corso specifiche attivit\u00e0 investigative \u00a0per\u00a0 accertare la dinamica di quanto accaduto, \u00a0nonch\u00e9 le motivazioni del fatto criminoso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/17\/lecce-commerciante-malmenato-nei-pressi-dello-stadio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/17\/lecce-commerciante-malmenato-nei-pressi-dello-stadio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)_____Ieri sera \u00a0una persona ferita a causa di un&#8217;aggressione, era stata segnalata alla Polizia, nei pressi dello Stadio nel Piazzale Adamo. Una volante recatasi sul posto \u00a0 si imbatteva in un uomo, di 44 anni, \u00a0il quale riferiva \u00a0che verso le ore 17,30 \u00a0mentre era nei pressi della sua attivit\u00e0 commerciale,\u00a0 non lontana dalla zona [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45131,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45130"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45130"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45130\/revisions"}],"predecessor-version":[{"id":45133,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45130\/revisions\/45133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45131"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}