{"id":45268,"date":"2015-02-20T14:59:34","date_gmt":"2015-02-20T13:59:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45268"},"modified":"2015-02-20T14:59:34","modified_gmt":"2015-02-20T13:59:34","slug":"lecce-due-auto-bruciate","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/20\/lecce-due-auto-bruciate\/","title":{"rendered":"LECCE: DUE AUTO BRUCIATE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/auto-bruciata.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/auto-bruciata-300x138.png\" alt=\"\" title=\"auto bruciata\" width=\"300\" height=\"138\" class=\"alignleft size-medium wp-image-45269\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/auto-bruciata-300x138.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/auto-bruciata.png 322w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Questa notte nel centro storico della citt\u00e0, sono state bruciate due auto. Dalle prime indagini risulta che le auto sono di propriet\u00e0 di due persone di origine senegalese.<br \/>\nAl momento non si hanno notizie pi\u00f9 dettagliate, le forze dell&#8217;ordine procedono con le indagini.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/20\/lecce-due-auto-bruciate\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/20\/lecce-due-auto-bruciate\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Questa notte nel centro storico della citt\u00e0, sono state bruciate due auto. Dalle prime indagini risulta che le auto sono di propriet\u00e0 di due persone di origine senegalese. Al momento non si hanno notizie pi\u00f9 dettagliate, le forze dell&#8217;ordine procedono con le indagini.<\/p>\n","protected":false},"author":4,"featured_media":45269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45268"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45268"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45268\/revisions"}],"predecessor-version":[{"id":45271,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45268\/revisions\/45271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45269"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}