{"id":4531,"date":"2012-10-11T09:27:56","date_gmt":"2012-10-11T09:27:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=4531"},"modified":"2012-10-11T09:27:57","modified_gmt":"2012-10-11T09:27:57","slug":"guerra-alle-zanzare-occorre-la-collaborazione-di-tutti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/11\/guerra-alle-zanzare-occorre-la-collaborazione-di-tutti\/","title":{"rendered":"GUERRA ALLE ZANZARE: OCCORRE LA COLLABORAZIONE DI TUTTI"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/11\/guerra-alle-zanzare-occorre-la-collaborazione-di-tutti\/zanzara_tigre\/\" rel=\"attachment wp-att-4532\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/zanzara_tigre-300x221.jpg\" alt=\"\" title=\"zanzara_tigre\" width=\"300\" height=\"221\" class=\"alignnone size-medium wp-image-4532\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/zanzara_tigre-300x221.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/zanzara_tigre-1024x757.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/zanzara_tigre.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p><strong>Gli interventi effettuati e le raccomandazioni dell\u2019assessore Andrea Guido<\/strong><\/p>\n<p>Sono stati raddoppiati gli interventi straordinari di disinfestazione contro le zanzare, allo stadio larvale e alato (adulte), gi\u00e0 previsti in citt\u00e0.<\/p>\n<p>Le numerose segnalazioni e il recente fatto di cronaca riguardante la bimba di 17 mesi punta ben 22 volte in una sera hanno portato l\u2019assessore<strong> <\/strong>Andrea Guido<strong> <\/strong>a compiere ulteriori sforzi volti al contenimento del problema, con le operazioni straordinarie richieste dalle ditte specializzate Bios e Biologica, a partire dalla scorsa notte, a costo zero per l\u2019Amministrazione Comunale.<\/p>\n<p>Secondo una nota del Comune di Lecce, gi\u00e0 da qualche anno la <strong>presenza delle zanzare non \u00e8 pi\u00f9 limitata alle stagioni tradizionali<\/strong><strong> <\/strong>(tarda primavera ed estate); sono in continuo aumento, infatti, le segnalazioni in <strong>autunno<\/strong> e, addirittura, anche durante l\u2019<strong>inverno<\/strong>. La recrudescenza del fenomeno \u00e8 stata provocata essenzialmente dal cambiamento delle condizioni climatiche, da quella che gli esperti definiscono \u201ctropicalizzazione\u201d. L\u2019alto incremento del tasso di umidit\u00e0 di questi ultimi giorni, poi, ha contribuito affinch\u00e9 si creassero le condizioni ideali per la proliferazione degli insetti. Ecco il motivo per cui \u00e8 possibile vedere le zanzare anche in periodi insoliti.<\/p>\n<p><em>\u201cPurtroppo \u2013 <\/em>precisa l\u2019assessore <strong>Andrea Guido<\/strong><em> &#8211; \u00e8 possibile che si verifichi un ulteriore sviluppo nella diffusione delle zanzare nel nostro Paese. Se i cambiamenti climatici che interessano l\u2019Italia incrementeranno ulteriormente i livelli di temperatura e i tassi di umidit\u00e0, si creeranno per i culicidi condizioni ambientali sempre pi\u00f9 favorevoli. Debellare la presenza delle zanzare a Lecce, quindi, \u00e8 impossibile. Il problema c\u2019\u00e8 e rimarr\u00e0, si tratta solamente di lavorare d\u2019anticipo per contenerlo il pi\u00f9 possibile. E di seguire alcune semplici regole che ci aiuteranno a prevenirlo.<\/em><\/p>\n<p><em>Sar\u00e0 quindi fondamentale, per le amministrazioni comunali, per le aziende private che operano sul territorio comunale e per i cittadini, provvedere ad eliminare tutti i possibili ristagni d\u2019acqua, limitando cos\u00ec al meglio la proliferazione di esemplari. Occorre fare attenzione a non abbandonare contenitori di qualsiasi forma e dimensione in spazi aperti pubblici e privati, compresi terrazzi e balconi, ed in qualsiasi luogo in cui possa verificarsi raccolta di acqua piovana. Mantenere in perfetta efficienza le grondaie o i tombini presenti nei giardini o negli spazi condominiali, pulire bene vasi e sottovasi prima di collocarli all\u2019interno delle abitazioni e convogliare in appositi apparati di scarico la condensa prodotta dagli impianti di climatizzazione. Queste sono le raccomandazioni che ho il dovere di fare ai leccesi e che, vi assicuro, possono rappresentare un valido aiuto a sostegno degli interventi a carattere chimico e tecnologico\u201d.<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/11\/guerra-alle-zanzare-occorre-la-collaborazione-di-tutti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/11\/guerra-alle-zanzare-occorre-la-collaborazione-di-tutti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Gli interventi effettuati e le raccomandazioni dell\u2019assessore Andrea Guido Sono stati raddoppiati gli interventi straordinari di disinfestazione contro le zanzare, allo stadio larvale e alato (adulte), gi\u00e0 previsti in citt\u00e0. Le numerose segnalazioni e il recente fatto di cronaca riguardante la bimba di 17 mesi punta ben 22 volte in una sera hanno portato l\u2019assessore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4532,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4531"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=4531"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4531\/revisions"}],"predecessor-version":[{"id":4534,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4531\/revisions\/4534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/4532"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=4531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=4531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=4531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}