{"id":45352,"date":"2015-03-05T07:00:23","date_gmt":"2015-03-05T06:00:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45352"},"modified":"2015-02-23T11:11:31","modified_gmt":"2015-02-23T10:11:31","slug":"locali-notte-raggae-al-dopolavoro-live-club-di-brindisi-sabato-7","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/05\/locali-notte-raggae-al-dopolavoro-live-club-di-brindisi-sabato-7\/","title":{"rendered":"LOCALI \/ NOTTE RAGGAE AL DOPOLAVORO LIVE CLUB DI BRINDISI SABATO 7"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/images10.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"150\" height=\"150\" title=\"images\" class=\"alignleft size-thumbnail wp-image-45353\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/images10-150x150.jpg\" \/><\/a>Sabato 7 Marzo, alle ore 22.30, al &#8220;Dopolavoro Live Club&#8221; di Brindisi, \u00a0di piazza Crispi, n. 42, ci sar\u00e0 una\u00a0serata reggae denominata &#8220;Boom Dancehall Party&#8221;.<\/p>\n<p>Si baller\u00e0 in\u00a0stile giamaicano, sui ritmi delle nuove tendenze e sonorit\u00e0 in arrivo dall&#8217;isola caraibica, miscelate sapientemente con le grandi hit del passato (nella foto, il leader storico Bob Marley).<\/p>\n<p>Protagonisti della serata, sul palco del club brindisino, il trio romano raggamuffin composto da\u00a0Raina, Ginko e Pekoz della Villa Ada Posse.<\/p>\n<p>A fare gli onori di casa saranno Rankin Lele &amp; Papa Leu.<\/p>\n<p>Per ulteriori informazioni si pu\u00f2 chiamare il numero\u00a03497546883.<\/p>\n<p>Biglietto d&#8217; ingresso a 5 euro.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/05\/locali-notte-raggae-al-dopolavoro-live-club-di-brindisi-sabato-7\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/05\/locali-notte-raggae-al-dopolavoro-live-club-di-brindisi-sabato-7\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sabato 7 Marzo, alle ore 22.30, al &#8220;Dopolavoro Live Club&#8221; di Brindisi, \u00a0di piazza Crispi, n. 42, ci sar\u00e0 una\u00a0serata reggae denominata &#8220;Boom Dancehall Party&#8221;. Si baller\u00e0 in\u00a0stile giamaicano, sui ritmi delle nuove tendenze e sonorit\u00e0 in arrivo dall&#8217;isola caraibica, miscelate sapientemente con le grandi hit del passato (nella foto, il leader storico Bob Marley). [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45352"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45352"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45352\/revisions"}],"predecessor-version":[{"id":45357,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45352\/revisions\/45357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45353"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}