{"id":45410,"date":"2015-02-26T17:10:53","date_gmt":"2015-02-26T16:10:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45410"},"modified":"2015-02-26T17:12:13","modified_gmt":"2015-02-26T16:12:13","slug":"libri-un-libro-di-alfredo-traversa-dopo-lo-spettacolo-teatrale-racconta-la-storia-di-santa-scorese-la-ragazza-barese-prima-vittima-riconosciuta-di-femminicidio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/libri-un-libro-di-alfredo-traversa-dopo-lo-spettacolo-teatrale-racconta-la-storia-di-santa-scorese-la-ragazza-barese-prima-vittima-riconosciuta-di-femminicidio\/","title":{"rendered":"UN LIBRO DI ALFREDO TRAVERSA, DOPO LO SPETTACOLO TEATRALE, RACCONTA LA STORIA DI SANTA SCORESE, LA RAGAZZA DI PALO DEL COLLE PRIMA VITTIMA RICONOSCIUTA DI FEMMINICIDIO"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/untitled41.png\"><img decoding=\"async\" loading=\"lazy\" width=\"192\" height=\"262\" title=\"untitled\" class=\"alignleft size-full wp-image-45411\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/untitled41.png\" \/><\/a>di Alessandra Maggio______<\/strong><\/p>\n<p>16 marzo 1991. La vita terrena di colei che \u00e8 a tutti gli effetti la prima vittima riconosciuta in Italia di <strong>stalking<\/strong> finisce barbaramente, a soli 23 anni. Uccisa. Massacrata. Martirizzata. Tredici coltellate. Una pozza di oltre due litri e mezzo di sangure\u2026Ecco l\u2019 immagine che rimane di lei, di quel lontano 16 marzo.<\/p>\n<p><strong>Nomen omen<\/strong>, i Latini non sbagliavano: in quel nome, il destino. Perch\u00e9 Santa amava, amava tutto, ma amava Dio sopra ogni cosa. Aveva scelto di diventare la sua sposa, una suora, per onorarlo e servirlo e per amare il prossimo cos\u00ec come solo chi ha un cuore puro come lei pu\u00f2.<\/p>\n<p>Figlia di un poliziotto e di una casalinga, Piero e Angela, una famiglia modello, di Palo del Colle, nel barese, una sorella, Rosamaria, e Mario, il cognato.<\/p>\n<p>Poi un giorno arriva lui, l\u2019 orco, Giuseppe. Inizia a seguirla, a chiamarla, a perseguitarla ovunque. Nonostante le numerose denunce presentate e i gruppi di persone, famigliari ed amici, che a turno si occupavano della sua protezione, i suoi <strong>bodyguard<\/strong>, come era solita definirli, il mostro Giuseppe ha trovato il minuto fatale per privarla del respiro sotto la finestra di casa, davanti agli occhi del padre.<\/p>\n<p>Le urla dei famigliari che si disperano si diffondono nell\u2019 aria.<\/p>\n<p>E\u2019 ancora viva quando giunge al Policlinico di Bari. Sorride e risponde, anche solo con gli occhi, ad uno dei tanti medici, un otorinolaringoiatra che \u00e8 l\u00e0 vicino. A lui, con lo sguardo e con una voce flebile, <strong>Santa Scorese<\/strong> racconta la sua ultima storia, cos\u00ec come aveva sempre fatto con il suo diario segreto, ritrovato postumo. Gli dice che \u00e8 pronta per andare incontro al suo amato Sposo. E\u2019 serena mentre lascia questa terra mortale. Chiude gli occhi qui dove \u00e8 pace eterna.<\/p>\n<p>Santa vive ancora oggi. Nel testo teatrale \u201cSanta delle perseguitate\u201d che l\u2019 attore e regista pugliese <strong>Alfredo Traversa<\/strong> ha ricavato dalla sua storia e ha gi\u00e0 rappresentato nelle scorse settimane, a Taranto e a Bari; il prossimo 4 marzo il suo spettacolo, con Tiziana Risolo e Ciro Lupo, sar\u00e0 a Terni e alla serata parteciper\u00e0 pure Rosamaria.<\/p>\n<p>E adesso santa vive ancora\u00a0anche\u00a0nel libro <strong>\u201cSanta che voleva solo vivere\u201d<\/strong> che lo stesso Alfredo Traversa ha appena pubblicato per le edizioni La Meridiana ( 48 pagine, 10 euro) in un volumetto denso di emozioni e di significati.<\/p>\n<p>Lei vive ancora nella sua casa, meta continua di giovani in pellegrinaggio.<\/p>\n<p>Il parroco, don Tino, \u00e8 il padre postulatore della causa di beatificazione.<\/p>\n<p>Santa continua a vivere e a donare il bene della sua anima pulita, ma sacrificata, ogni attimo del giorno.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/libri-un-libro-di-alfredo-traversa-dopo-lo-spettacolo-teatrale-racconta-la-storia-di-santa-scorese-la-ragazza-barese-prima-vittima-riconosciuta-di-femminicidio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/libri-un-libro-di-alfredo-traversa-dopo-lo-spettacolo-teatrale-racconta-la-storia-di-santa-scorese-la-ragazza-barese-prima-vittima-riconosciuta-di-femminicidio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Alessandra Maggio______ 16 marzo 1991. La vita terrena di colei che \u00e8 a tutti gli effetti la prima vittima riconosciuta in Italia di stalking finisce barbaramente, a soli 23 anni. Uccisa. Massacrata. Martirizzata. Tredici coltellate. Una pozza di oltre due litri e mezzo di sangure\u2026Ecco l\u2019 immagine che rimane di lei, di quel lontano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45410"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45410"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45410\/revisions"}],"predecessor-version":[{"id":45413,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45410\/revisions\/45413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45411"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}