{"id":45588,"date":"2015-02-27T06:02:02","date_gmt":"2015-02-27T05:02:02","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45588"},"modified":"2015-02-24T22:51:11","modified_gmt":"2015-02-24T21:51:11","slug":"concerti-la-band-salentina-seahouse-presenta-il-suo-ultimo-disco-cristalli-a-novoli-domenica-1","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/concerti-la-band-salentina-seahouse-presenta-il-suo-ultimo-disco-cristalli-a-novoli-domenica-1\/","title":{"rendered":"CONCERTI \/  LA BAND SALENTINA SEAHOUSE PRESENTA IL SUO ULTIMO DISCO &#8220;CRISTALLI&#8221; A NOVOLI DOMENICA 1"},"content":{"rendered":"<p>(m.p.)______Domenica 1 marzo, <a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/SEA-FILES-di-Carmelo-Marasciulo.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" title=\"SEA FILES - di Carmelo Marasciulo\" class=\"alignleft size-large wp-image-45589\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/SEA-FILES-di-Carmelo-Marasciulo-1024x1024.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/SEA-FILES-di-Carmelo-Marasciulo-1024x1024.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/SEA-FILES-di-Carmelo-Marasciulo-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/SEA-FILES-di-Carmelo-Marasciulo-300x300.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>alle ore 19, il casello ferroviario Km97 di Novoli\u00a0 ospiter\u00e0 il listening party dei SeaHouse, con la presentazione dell\u2019ultimo disco \u201cCristalli\u201d (Rawlines New Model Label). Un appuntamento condito dalla contaminazione di diverse forme d\u2019espressione, idea di contaminazione nata dagli stessi SeaHouse, con l\u2019intento di favorire una maggiore attenzione ed educazione all\u2019ascolto musicale ed uno scambio espressivo contemporaneo.<\/p>\n<p>Disponibile in tutti gli store digitali, su cd ed usb, \u201cCristalli\u201d spazia dall\u2019ambient al rock, passando per il funk e la psichedelia. \u201cCristalli\u201d \u00e8 un viaggio in musica che attraverso le sue dieci tracce porta l\u2019ascoltatore in mondi ora soffusi e dilatati, ora spigolosi e graffianti.<\/p>\n<p>A condire il listening party dei SeaHouse, un mini set acustico della band pugliese che eseguir\u00e0 alcuni brani come intermezzo all\u2019ascolto del disco. Presente l\u2019artista mesagnese Carmelo Marasciulo, con l\u2019installazione \u201cSea Files\u201d (nella foto) e le istantanee del fotografo salentino Stefano Cacciatore; insieme a loro anche un angolo lettura, con lo scrittore brindisino Mino Pica, che presenter\u00e0 \u201cHotel, camere di riflessione\u201d (Lupo Editore, 2013) e la fotografa Daniela Errico che porter\u00e0 la sua recente pubblicazione \u201cThe Music Affair\u201d (Blurb, 2014), una raccolta fotografica sulla scena musicale pugliese di questi ultimi anni.<\/p>\n<p>Dopo aver spiegato con Ted (The emotional discount, SeaHouse, 2011) una realt\u00e0 terrena, storico e sociale, che evidentemente non appartiene alla band pugliese, i SeaHouse con \u2018Cristalli\u2019 sembrano aver voluto indossare nuovamente tute e casco spaziali, gi\u00e0 viste e sentite in Next (SeaHouse, 2007) per proteggersi e proteggere da quelle radiazioni terrestri, costellate \u2013 a loro suonare \u2013 da un vuoto interno patologico ed insano. I SeaHouse sembrano voler cos\u00ec riprendere il volo maturando, nel tempo e nella musica, un senso di estraneit\u00e0 nell\u2019espressione e pensiero comune; i loro brani si caratterizzano, al solito, per la loro sana e viva originalit\u00e0 nello scenario musicale contemporaneo e la maturit\u00e0 si esprime anche in una maggiore cura dei particolari per un lavoro di ricerca intenso.<\/p>\n<p>&#8220;La musica dei SeaHouse arricchir\u00e0 la vostra esperienza musicale. \u201cCristalli\u201d \u00e8 l\u2019album che permette ad armonie cangianti e fragili di prendere forma e di squarciare ogni tenebra. Un disco coraggioso per ascoltatori che ricercano musica di qualit\u00e0&#8221;. (Recensione di Il Megafono.org); &#8220;Un album incisivo. \u201cCristalli\u201d va percepito. Goduto. Sentito. \u201cCristalli\u201d \u00e8 una temperatura, un soffio, un tocco, un brivido, una percezione. \u201cCristalli\u201d \u00e8 emozione diretta, immediata, poderosa. Dieci tracce ricche di attesa, suspance, stimoli, ispirazioni, nervosismi, tranquillit\u00e0, ragione, pazzia. Forse appartengono al mondo del prog, se vogliamo usare questo termine come \u201ctutto quello che non \u00e8 qualcos\u2019altro\u201d (Recensione di Metalhead.it)<\/p>\n<p>Il casello ferroviario Sum Km97 \u00e8 in via della Ferrandina, 5, sulla provinciale che college Lecce a Novoli. Sum \u00e8 un progetto indisciplinato che dal 2004 si spende sul territorio per creare nuovi spazi fisici e virtuali di espressione musicale e di promozione della libera cultura.<\/p>\n<p>Formazione SeaHouse: Gianluca Grecucci (basso), Max Licchelli (chitarra), Gianluca Voglino (batteria e percussioni), Elvi Palma (tastiere e synth), Luca Antonazzo (chitarra).<\/p>\n<p>Discografia: Next (2007), The Emotional Discount (2011), Cristalli (2014)<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/concerti-la-band-salentina-seahouse-presenta-il-suo-ultimo-disco-cristalli-a-novoli-domenica-1\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/concerti-la-band-salentina-seahouse-presenta-il-suo-ultimo-disco-cristalli-a-novoli-domenica-1\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(m.p.)______Domenica 1 marzo, alle ore 19, il casello ferroviario Km97 di Novoli\u00a0 ospiter\u00e0 il listening party dei SeaHouse, con la presentazione dell\u2019ultimo disco \u201cCristalli\u201d (Rawlines New Model Label). Un appuntamento condito dalla contaminazione di diverse forme d\u2019espressione, idea di contaminazione nata dagli stessi SeaHouse, con l\u2019intento di favorire una maggiore attenzione ed educazione all\u2019ascolto musicale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45588"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45588"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45588\/revisions"}],"predecessor-version":[{"id":45632,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45588\/revisions\/45632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45589"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}