{"id":45671,"date":"2015-02-26T15:58:20","date_gmt":"2015-02-26T14:58:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45671"},"modified":"2015-02-26T15:59:11","modified_gmt":"2015-02-26T14:59:11","slug":"denunciato-un-uomo-di-trepuzzi-accusato-di-ricettazione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/denunciato-un-uomo-di-trepuzzi-accusato-di-ricettazione\/","title":{"rendered":"DENUNCIATO UN UOMO DI TREPUZZI ACCUSATO DI RICETTAZIONE DI SIGARETTE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150225-WA0001.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"959\" title=\"IMG-20150225-WA0001\" class=\"alignleft size-full wp-image-45672\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150225-WA0001.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150225-WA0001.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150225-WA0001-300x224.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150225-WA0001-1024x767.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>(g.m.)______Beh, avrebbe potuto dire di fumare come un turco&#8230;O tentare di giustificarsi, dicendo di essere particolarmente nervoso in questo periodo&#8230;Certo \u00e8 che i Carabinieri non gli avrebbero creduto, sospettandolo di ricettazione dai tanti furti avvenuti ultimamente ai danni di tabaccai.\u00a0\u00a0In ogni caso rimane difficile da spiegare il fatto di avere in casa 327 pacchetti di sigarette di diverse marche. E&#8217; accaduto\u00a0ieri mattina a R.M., 60 anni, di Trepuzzi, residente in una masseria nelle campagne di Novoli.\u00a0E&#8217; stato denunciato in stato di libert\u00e0 per il reato di ricettazione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/denunciato-un-uomo-di-trepuzzi-accusato-di-ricettazione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/26\/denunciato-un-uomo-di-trepuzzi-accusato-di-ricettazione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Beh, avrebbe potuto dire di fumare come un turco&#8230;O tentare di giustificarsi, dicendo di essere particolarmente nervoso in questo periodo&#8230;Certo \u00e8 che i Carabinieri non gli avrebbero creduto, sospettandolo di ricettazione dai tanti furti avvenuti ultimamente ai danni di tabaccai.\u00a0\u00a0In ogni caso rimane difficile da spiegare il fatto di avere in casa 327 pacchetti di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45671"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45671"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45671\/revisions"}],"predecessor-version":[{"id":45674,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45671\/revisions\/45674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45672"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}