{"id":45768,"date":"2015-02-27T15:05:24","date_gmt":"2015-02-27T14:05:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=45768"},"modified":"2015-11-23T14:25:14","modified_gmt":"2015-11-23T13:25:14","slug":"brillante-operazione-dei-nas-dei-carabinieri-sequestrato-olio-spagnolo-e-greco-venduto-invece-come-italiano-photogallery","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/brillante-operazione-dei-nas-dei-carabinieri-sequestrato-olio-spagnolo-e-greco-venduto-invece-come-italiano-photogallery\/","title":{"rendered":"BRILLANTE OPERAZIONE DEI NAS DEI CARABINIERI \/ SEQUESTRATO OLIO SPAGNOLO E GRECO VENDUTO INVECE COME ITALIANO \/ PHOTOGALLERY"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150123_163152.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"IMG_20150123_163152\" class=\"alignleft size-medium wp-image-45769\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150123_163152-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150123_163152-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150123_163152-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150203_105842.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"IMG_20150203_105842\" class=\"alignleft size-medium wp-image-45771\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150203_105842-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150203_105842-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG_20150203_105842-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0002.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"IMG-20150219-WA0002\" class=\"alignleft size-medium wp-image-45772\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0002-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0002-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0002-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0002.jpg 960w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0003.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"IMG-20150219-WA0003\" class=\"alignleft size-medium wp-image-45773\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0003-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0003-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0003-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0003.jpg 960w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0006.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"IMG-20150219-WA0006\" class=\"alignleft size-medium wp-image-45774\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0006-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0006-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0006-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/IMG-20150219-WA0006.jpg 960w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>(v.m.)______Brillante operazione dei Nas, i Nuclei Anti Sofisticazioni del Carabinieri, di Lecce. Nel corso di controlli ad alcuni oleifici della provincia, gli uomini dei Nas hanno sequestrato 2000 litri di olio di oliva extravergine di provenienza comunitaria, venduto invece come di produzione italiana e 6\u00a0tonnellate di olio comunitario sprovvisto delle\u00a0indicazioni previste dalla legge\u00a0sui contenitori.<\/p>\n<p>In particolare, i nuclei dei Carabinieri, come detto, in seguito a numerosi controlli a frantoi ed aziende di imbottigliamento di olio d\u2019oliva della provincia salentina, hanno scoperto che alcuni stabilimenti acquistavano da un grossista della zona olio extravergine di oliva comunitario, proveniente principalmente da Grecia e Spagna, per poi confezionarlo e venderlo come olio extravergine di oliva 100% italiano.<\/p>\n<p>La vasta frode \u00e8 stata scoperta grazie a mirati controlli volti a risalire all\u2019origine del prodotto attraverso verifiche sui documenti di acquisto e sui recipienti utilizzati per il confezionamento nonch\u00e9 mediante analisi di laboratorio.<\/p>\n<p>Il NAS ha sequestrato 2000 Kg di miscele di oli comunitari etichettati come \u201cExtravergine di oliva made in Italy\u201d e circa 6 tonnellate di olio contenuti in silos e fusti privi delle indicazioni relative alla categoria e provenienza.<\/p>\n<p>I militari hanno denunciato cinque persone per frode in commercio e contestato sanzioni amministrative per diverse migliaia di euro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/brillante-operazione-dei-nas-dei-carabinieri-sequestrato-olio-spagnolo-e-greco-venduto-invece-come-italiano-photogallery\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/02\/27\/brillante-operazione-dei-nas-dei-carabinieri-sequestrato-olio-spagnolo-e-greco-venduto-invece-come-italiano-photogallery\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(v.m.)______Brillante operazione dei Nas, i Nuclei Anti Sofisticazioni del Carabinieri, di Lecce. Nel corso di controlli ad alcuni oleifici della provincia, gli uomini dei Nas hanno sequestrato 2000 litri di olio di oliva extravergine di provenienza comunitaria, venduto invece come di produzione italiana e 6\u00a0tonnellate di olio comunitario sprovvisto delle\u00a0indicazioni previste dalla legge\u00a0sui contenitori. In [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45774,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45768"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=45768"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45768\/revisions"}],"predecessor-version":[{"id":45779,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/45768\/revisions\/45779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45774"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=45768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=45768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=45768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}