{"id":4626,"date":"2012-10-15T15:16:48","date_gmt":"2012-10-15T15:16:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=4626"},"modified":"2012-10-16T16:23:01","modified_gmt":"2012-10-16T16:23:01","slug":"agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/","title":{"rendered":"AGRO.GE.PA.CIOK a corredo dell&#8217;articolo di Beatrice Sicuro &#8211; Galleria di Foto &#8211; Scatti di Valerio Melcore"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-4626 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9078\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9078-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9079\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9079-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9080\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9080-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9081\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9081-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9082\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9082-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9083\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9083-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9084\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9084-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9085\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9085-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9086\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9086-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9087\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9087-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9088\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9088-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9089\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9089-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9090\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9090-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9091\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9091-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9092\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9092-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9093\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9093-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9094\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9094-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9095\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9095-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9096\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9096-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9097\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9097-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9098\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9098-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9099\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9099-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9100\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9100-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9101\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9102\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9102-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9103\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9103-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9104\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9104-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9105\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9105-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9106\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9106-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9107\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9107-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9108\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9108-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9110\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9110-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9111\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9111-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9112\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9112-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9113\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9113-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9114\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9114-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9115\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9115-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9116\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9116-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9117\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9117-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9118\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9118-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9119\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9119-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9120\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9120-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9121\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9121-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9123\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9123-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9124\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9124-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9125\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9125-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9126\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9126-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9128\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9128-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9129\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9129-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9130\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9130-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9131\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9131-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9132\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9133\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9133-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9134\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9134-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9135\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9135-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9136\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9137\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9137-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9138\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9139\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9140\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9140-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9141\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9141-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9142\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9143\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9143-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9144\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9144-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9145\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9145-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9146\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9146-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9147\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9147-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9148\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9148-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9149\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9149-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9150\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9150-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9151\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9151-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9152\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9152-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9153\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9153-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9154\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9154-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9155\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9155-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9156\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9156-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9157\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9157-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9158\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9158-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9159\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9159-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9160\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9160-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9161\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9161-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9162\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9162-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9163\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9163-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9164\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9164-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9165\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9165-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9166\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9166-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9167\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9167-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9168\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9168-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/img_9169\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/IMG_9169-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p><span style=\"font-size: medium;\">( b.s.) Alcuni scatti relativi al salone Agro.ge.pa.ciok, fiera dell&#8217;artigianato agro-gastronomico. Pi\u00f9 di cento le aziende provenienti da tutta Italia, che hanno esposto con i loro marchi.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium;\">Passeggiando per i vari stand, l&#8217;olfatto viene abbondantemente appagato e, tra le tante novit\u00e0 importanti di quest&#8217;anno, il giusto rilievo \u00e8 stato dato dal forum dei Pizzaioli Salentini al cibo senza glutine, portando alla luce la problematica ancora sommersa della celiachia.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-size: medium;\">Anche quest&#8217;anno Agro.ge.pa.ciok si \u00e8 dimostrata essere una grande opportunit\u00e0 sia per i giovani del settore agroalimentare di formarsi e informarsi, sia importante vetrina per i nostri imprenditori, che hanno potuto cosi mettersi in mostra davanti ai compratori, che sono giunti da tutta Italia nel Salento.<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/15\/agro-ge-pa-ciok-a-corredo-dellarticolo-di-beatrice-sicuro-galleria-di-foto-scatti-di-valerio-melcore\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>( b.s.) Alcuni scatti relativi al salone Agro.ge.pa.ciok, fiera dell&#8217;artigianato agro-gastronomico. Pi\u00f9 di cento le aziende provenienti da tutta Italia, che hanno esposto con i loro marchi. Passeggiando per i vari stand, l&#8217;olfatto viene abbondantemente appagato e, tra le tante novit\u00e0 importanti di quest&#8217;anno, il giusto rilievo \u00e8 stato dato dal forum dei Pizzaioli Salentini [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4626"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=4626"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4626\/revisions"}],"predecessor-version":[{"id":4717,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4626\/revisions\/4717"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=4626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=4626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=4626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}