{"id":46855,"date":"2015-03-22T10:00:06","date_gmt":"2015-03-22T09:00:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=46855"},"modified":"2015-03-22T12:15:43","modified_gmt":"2015-03-22T11:15:43","slug":"stanno-distruggendo-lolio-salentino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/22\/stanno-distruggendo-lolio-salentino\/","title":{"rendered":"STANNO DISTRUGGENDO L&#8217;OLIO SALENTINO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/ulivo-faccia-indiana.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/ulivo-faccia-indiana-150x150.jpg\" alt=\"\" title=\"ulivo faccia indiana\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-46651\" \/><\/a>Bande criminali stanno tagliando l&#8217;olio d&#8217;oliva con sostanze sconosciute ed in ambienti malsani che potrebbero danneggiare la salute dei consumatori. E&#8217; questa la notizia apparsa su alcuni quotidiani britannici e che la dice lunga sui devastanti effetti della xylella che stanno assumendo contorni internazionali.Gli investigatori britannici di frodi alimentari sono stati chiamati ad uno sforzo per cercare di scoprire questi malfattori mentre le autorit\u00e0 sanitarie avvisano gli acquirenti a diffidare dell&#8217;olio del prezzo dell&#8217;oliva che appare &#8220;troppo economico per essere vero&#8221;.<br \/>\nArriva, quindi, anche in Gran Bretagna la notizia dell&#8217;epidemia di xylella con i prezzi dell&#8217;olio di oliva italiano pi\u00f9 che raddoppiati nelle ultime settimane a causa dei milioni di alberi di ulivo che rischiano di essere spazzati via dal famigerato microbo mortale e che sinora \u00e8 stata la causando della caduta di produzione pari ad un terzo rispetto all&#8217;anno precedente. Secondo quanto apparso sui media britannici, i consumatori sarebbero a rischio di escherichia coli e salmonella, cos\u00ec come a reazioni allergiche per le sostanze contenute nell&#8217;olio adulterato.Un ricercatore italiano ha detto al The Independent: &#8220;i criminali hanno collegamenti internazionali e sono in grado di spostare questo prodotto all&#8217;estero dove altri criminali lo smerceranno. Ci sono alcune reti che sono in grado di fornire ristoranti italiani all&#8217;estero, quindi non c&#8217;\u00e8 una minaccia da quello.&#8221;L&#8217;Italia a livello globale \u00e8 considerata come l&#8217;origine per il miglior olio al mondo, ma bande di truffatori stanno mettendo a rischio la reputazione fino a minacciare la salute dei consumatori. La maxifrode vede alla base oli provenienti da altri paesi e spacciate come olio extravergine d&#8217;oliva d&#8217;alta qualit\u00e0 italiana. Sempre sui giornali inglesi si legge che la Puglia, la regione con la pi\u00f9 grande produzione d&#8217;olivicoltura dell&#8217;Italia \u00e8 particolarmente e duramente colpita dalla malattia silenziosa nota come xylella fastidiosa.E sempre i media sottolineano che non si tratta solo di una questione di prodotti sotto standardizzati, ma soprattutto \u00e8 un problema di salute e sicurezza. Una delle frodi segnalate nel Regno Unito \u00e8 quella gi\u00e0 nota dell&#8217;olio vegetale tinto con clorofilla al fine di raggiungere il colore dell&#8217;olio d&#8217;oliva ed al quale viene aggiunto betacarotene per l&#8217;aroma. E le autorit\u00e0 sanitarie inglesi ricordano che la clorofilla pu\u00f2 causare eruzioni cutanee ai soggetti con allergie.L&#8217;olio in questione \u00e8 prodotto in aree non soggette a controlli, tanto che ci sono fondati timori che corpi estranei possano entrare nel prodotto, o contaminarlo con sostanze chimiche pericolose.Uno degli ispettori ha aggiunto che &#8220;Non rispettano i requisiti di igiene per la produzione alimentare. Spesso lavorano in garage e scantinati delle case, quindi non sono posti puliti possono causare la presenza di batteri e contaminazione.&#8221;Tra i soggetti pi\u00f9 a rischio dell&#8217;olio falso: ristoratori e piccoli negozi locali. Agli acquirenti \u00e8 stato suggerito che per evitare le frodi di acquistare olio di oliva al giusto prezzo. Il costo varia tra le 4 e 6.50 sterline e con la probabilit\u00e0 di un aumento di circa il 25 % a causa del cattivo raccolto:\u00a0 bisogna diffidare di un prezzo inferiore a 5 sterline. \u00a0Insomma, per Giovanni D&#8217;Agata, le notizie apparse sulle cronache d&#8217;Oltremanica non fanno altro che destare ulteriore allarme anche qui e dimostrano che siano quantomai necessari interventi urgenti per fermare questa psicosi e debellare la malattia che sta determinando il rischio di una perdita di reputazione del nostro oro giallo che potrebbe avere effetti per decine di anni.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/22\/stanno-distruggendo-lolio-salentino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/22\/stanno-distruggendo-lolio-salentino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Bande criminali stanno tagliando l&#8217;olio d&#8217;oliva con sostanze sconosciute ed in ambienti malsani che potrebbero danneggiare la salute dei consumatori. E&#8217; questa la notizia apparsa su alcuni quotidiani britannici e che la dice lunga sui devastanti effetti della xylella che stanno assumendo contorni internazionali.Gli investigatori britannici di frodi alimentari sono stati chiamati ad uno sforzo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46651,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/46855"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=46855"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/46855\/revisions"}],"predecessor-version":[{"id":46875,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/46855\/revisions\/46875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/46651"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=46855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=46855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=46855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}