{"id":47057,"date":"2015-03-26T11:54:08","date_gmt":"2015-03-26T10:54:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=47057"},"modified":"2015-03-26T11:54:08","modified_gmt":"2015-03-26T10:54:08","slug":"province-figuraccia-del-governo-regionale-serviva-legge-di-riordino-per-mitigare-i-danni-della-delrio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/26\/province-figuraccia-del-governo-regionale-serviva-legge-di-riordino-per-mitigare-i-danni-della-delrio\/","title":{"rendered":"PROVINCE  \u201cFIGURACCIA DEL GOVERNO REGIONALE, SERVIVA LEGGE  DI RIORDINO PER MITIGARE I DANNI DELLA DELRIO\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/congedo1.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/congedo1-300x253.jpg\" alt=\"\" title=\"congedo\" class=\"alignleft size-medium wp-image-45010\" height=\"253\" width=\"300\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/congedo1-300x253.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/congedo1.jpg 318w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Congedo accusa il Governo regionale per non essere intervenuto. Adesso probabilmente toccher\u00e0 ad un Commissario ad acta.<br \/>\nIl vice presidente vicario del gruppo Pdl\/Fi alla Regione Puglia Erio Congedo punta l\u2019indice contro il Governo regionale che ha fatto trascorrere inutilmente i sei mesi di tempo a disposizione per varare una legge di riordino delle funzioni delle Province a seguito della Legge Delrio e che ora dovr\u00e0 fare i conti probabilmente con un Commissario ad acta con poteri sostitutivi nominato dal Governo.<\/p>\n<p>\u201cI limiti della Legge Delrio sono noti &#8211; premette &#8211; visto che si tratta di una pseudo riforma che trasforma le Province in enti con scarsissimo potere di rappresentanza delle istanze, delle aspettative e della volont\u00e0 dei cittadini, oltre a ridisegnare il sistema delle autonomie locali (Regioni, Province, Citt\u00e0 metropolitane, Comuni e loro Unioni), senza stabilire di fatto cosa ognuno di questi enti andr\u00e0 a fare nel nuovo assetto. In altri termini, chi deve fare cosa e con quali risorse. Una Legge che, peraltro, ha effetti ancora pi\u00f9 tangibili sui territori, come raccontano le cronache di questi giorni ad esempio relativamente alla Provincia di Lecce: livelli occupazioni delle societ\u00e0 partecipate dell\u2019ente a rischio, sopravvivenza dell\u2019Orchestra Ico Tito Schipa praticamente compromessa, scuole senza riscaldamento, stipendi dei dipendenti a rischio. Una catastrofe dal punto di vista occupazionale, dei servizi resi al cittadino, della prospettiva di contenziosi e conflittualit\u00e0 generale.<\/p>\n<p>Pertanto &#8211; continua Erio Congedo &#8211; bene ha fatto la Regione Puglia, cos\u00ec come Campania e Veneto governate da maggioranze di diversi colori politici, a impugnare la Legge presso la Corte costituzionale per gravi vizi di incostituzionalit\u00e0. Peccato poi che abbia fatto scadere i termini per varare, come previsto, una legge regionale in materia di riordino delle funzioni delle autonomie locali che avrebbe potuto mitigare, senza dubbio, i danni della Delrio. La figuraccia del Governo regionale resta, ma ci sono i tempi per rimediare. Le nostre insistenze e quelle dei presidenti delle Province in questa direzione erano e restano certamente fondate e l\u2019intervento del Governo e la minaccia dei poteri sostitutivi ne sono la dimostrazione\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/26\/province-figuraccia-del-governo-regionale-serviva-legge-di-riordino-per-mitigare-i-danni-della-delrio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/26\/province-figuraccia-del-governo-regionale-serviva-legge-di-riordino-per-mitigare-i-danni-della-delrio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Congedo accusa il Governo regionale per non essere intervenuto. Adesso probabilmente toccher\u00e0 ad un Commissario ad acta. Il vice presidente vicario del gruppo Pdl\/Fi alla Regione Puglia Erio Congedo punta l\u2019indice contro il Governo regionale che ha fatto trascorrere inutilmente i sei mesi di tempo a disposizione per varare una legge di riordino delle funzioni [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47057"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=47057"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47057\/revisions"}],"predecessor-version":[{"id":47063,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47057\/revisions\/47063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45010"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=47057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=47057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=47057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}