{"id":47163,"date":"2015-03-27T22:00:45","date_gmt":"2015-03-27T21:00:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=47163"},"modified":"2015-03-27T22:00:45","modified_gmt":"2015-03-27T21:00:45","slug":"accolto-il-reclamo-delle-svicat-rugby","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/27\/accolto-il-reclamo-delle-svicat-rugby\/","title":{"rendered":"Accolto il reclamo delle Svicat Rugby"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/svicatrugbyasd.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/02\/svicatrugbyasd.png\" alt=\"\" title=\"svicatrugbyasd\" width=\"194\" height=\"188\" class=\"alignleft size-full wp-image-45367\" \/><\/a>La Corte Sportiva di Appello ha ridotto da otto a due giornate la squalifica del tallonatore De Gioa.<strong><br \/>\n<\/strong>E\u2019 stato accolto il reclamo proposto dalla societa\u2019 salentina del patron <strong>Fabrizio Romano Camilli<\/strong> avverso la lunga squalifica comminata al tallonatore De Gioia in occasione della gara dell\u20198 marzo, disputata a Ragusa contro il Padua Ragusa.<\/p>\n<p>In occasione dell\u2019incontro, in particolare, il De Gioia era stato espulso per un presunto calcio sferrato sul volto di un avversario. Da qui la decisione impugnata con cui il Giudice sportivo nazionale, presso la Federazione Italiana Rugby, ha comminato al De Gioia, sulla base del referto arbitrale, la squalifica per otto turni dal campionato di serie B, considerata anche la recidiva del giocatore.<\/p>\n<p>La Svicat decideva cosi\u2019 di proporre reclamo avverso la decisione, rilevando che non si era trattato di un calcio sferrato sul volto di un avversario dal proprio atleta, bensi\u2019 solo del tentativo del De Gioia di svincolarsi da un avversario che lo aveva preso per una gamba e che in tale frangente sfiorava il viso dell\u2019avversario.<\/p>\n<p>Del resto, ha osservato la reclamante alcun danno era stato riportato dal giocatore avversario.<\/p>\n<p>Sorprendentemente, quindi, a seguito dell\u2019ascolto dell\u2019arbitro, da parte della Corte di Appello riunitasi nella Camera di Consiglio del 24 marzo, il Giudice di secondo grado ha accolto il reclamo proposto dalla Svicat, per il tramite dell\u2019<strong>Avv. Alfredo Matranga<\/strong>, riducendo sensibilmente la squalifica del De Gioia.<\/p>\n<p>In particolare, si legge nel provvedimento della Corte, l\u2019arbitro, sentito telefonicamente, ha sostanzialmente confermato la versione fornita nel reclamo riguardo all\u2019episodio del De Gioia che \u201c<em>per liberarsi da una presa al piede del tallonatore avversario che gli teneva la gamba alzata, ha mosso la stessa gamba in modo incauto sfiorando con il piede il viso dell\u2019avversario, il quale non riportava alcun infortunio<\/em>\u201d.<\/p>\n<p>Pertanto, l\u2019atleta a seguito di tale decisone potr\u00e0 gi\u00e0 tornare in campo subito dopo la pausa pasquale.<\/p>\n<p>A seguito dell\u2019accoglimento del reclamo la Corte Sportiva di Appello ha disposto altresi\u2019 la restituzione della tassa di reclamo.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/27\/accolto-il-reclamo-delle-svicat-rugby\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/27\/accolto-il-reclamo-delle-svicat-rugby\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Corte Sportiva di Appello ha ridotto da otto a due giornate la squalifica del tallonatore De Gioa. E\u2019 stato accolto il reclamo proposto dalla societa\u2019 salentina del patron Fabrizio Romano Camilli avverso la lunga squalifica comminata al tallonatore De Gioia in occasione della gara dell\u20198 marzo, disputata a Ragusa contro il Padua Ragusa. In [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47163"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=47163"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47163\/revisions"}],"predecessor-version":[{"id":47165,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47163\/revisions\/47165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/45367"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=47163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=47163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=47163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}