{"id":47200,"date":"2015-03-29T11:57:02","date_gmt":"2015-03-29T09:57:02","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=47200"},"modified":"2015-03-29T11:57:02","modified_gmt":"2015-03-29T09:57:02","slug":"alle-sorelle-e-ai-fratelli-di-buona-volonta-messaggio-per-la-domenica-della-palme","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/29\/alle-sorelle-e-ai-fratelli-di-buona-volonta-messaggio-per-la-domenica-della-palme\/","title":{"rendered":"Alle sorelle e ai fratelli di buona volont\u00e0 &#8211; Messaggio per la domenica della Palme"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/comboniani.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/comboniani-300x209.png\" alt=\"\" title=\"comboniani\" width=\"300\" height=\"209\" class=\"alignleft size-medium wp-image-47202\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/comboniani-300x209.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/03\/comboniani.png 434w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Oggi, domenica delle Palme, la chiesa cattolica celebra l\u2019entrata di Ges\u00f9 in Gerusalemme accompagnato come un liberatore e messia nel luogo dove risiede il potere. Il luogo del potere, oggi, \u00e8 abitato da imprese e multinazionali che non hanno scrupoli nel perseguire i loro affari a spese della vita, da scienziati che maneggiano i codici della vita, da grandi organizzazioni compiacenti, da alcuni politici corrotti che vendono la propria coscienza (attraverso silenzi o sproloqui, inerzia o solerzia) per pochi spiccioli, incuranti dei danni causati alla loro gente e alla loro terra, e che rendono le istituzioni strumenti dei loro piani. Il luogo del potere \u00e8 abitato anche da noi quando, per superficialit\u00e0 o ingordigia, ci adeguiamo alla mercificazione dei beni comuni, sacrificando il bene comune alla logica del profitto o quando, per indifferenza o per senso di impotenza, scegliamo il silenzio.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ultimo \u201cattacco\u201d -solo in senso cronologico \u2013 si consuma nei confronti di un insetto \u201cla sputtachina\u201d reo di diffondere il batterio della \u201cXylella fastidiosa\u201d ritenuto responsabile del disseccamento degli ulivi e che, proveniente dall\u2019America del Sud, sarebbe arrivato fino a noi secondo circostanze talmente oscure da indurre la Procura della Repubblica di Lecce ad aprire un fascicolo di indagine. Al riguardo, une serie di atti governativi e determine regionali prevedono l\u2019attuazione obbligatoria di espianti e misure fitosanitarie per il controllo e l\u2019eradicazione della Xylella fastidiosa e per la lotta agli insetti vettori nei comuni della Provincia di Lecce, e in alcuni comuni delle provincie di Brindisi e Taranto. Tutto questo avviene nonostante l\u2019audit della Commissione Europea (2014) evidenzi la presenza di funghi (presenti in ognuno degli alberi analizzati) quali possibili cause del disseccamento e diversi casi (sempre in Salento) mostrino come negli ulivi curati dai suddetti funghi la malattia sia arretrata e le piante rinate.<\/p>\n<p>&nbsp;<\/p>\n<p>Se il Piano fosse attuato non si conterebbero le piante eliminate (olivi, macchia mediterranea e flora spontanea), gli insetti impollinatori come le api che morirebbero e i danni che i pesticidi causerebbero all\u2019ambiente (inquinamento delle falde acquifere) e alla salute (andandosi ad aggiungere alle centinaia di sostanze tossiche gi\u00f9 rilevate nell\u2019ultimo rapporto dell\u2019Istituto Superiore per la protezione e la ricerca ambientale), i danni all\u2019economia agricola e al turismo, con conseguenze pensanti per la popolazione che, direttamente e indirettamente, vive di questo.<\/p>\n<p>&nbsp;<\/p>\n<p>Oggi, unendoci a chi gi\u00e0 difende la nostra Terra, la Madre Terra, proponiamo alcuni punti di conoscenza e azione restando disponibili a ulteriore approfondimento per far s\u00ec che la terra salentina resti vivibile e non ridotta a un deserto:<\/p>\n<p>&nbsp;<\/p>\n<p>-INFORMARCI, partecipando e organizzando incontri sul proprio territorio perch\u00e9 la conoscenza corretta dei fatti \u00e8 indispensabile per una chiara visione sulla base della quale poter scegliere e decidere;<\/p>\n<p>&nbsp;<\/p>\n<p>-PRENDERE COSCIENZA dei nostri comportamenti nocivi (sul piano individuale e collettivo) e assumerci la RESPONSABILITA\u2019 di cambiarli;<\/p>\n<p>&nbsp;<\/p>\n<p>-SMETTERE DI AVVELENARE LA TERRA, direttamente (attraverso il diserbo e la concimazione chimica) e indirettamente (acquistando e consumando prodotti trattati con fitofarmaci, pesticidi,\u2026);<\/p>\n<p>&nbsp;<\/p>\n<p>-NON ACCETTARE PASSIVAMENTE le scelte imposte dall\u2019alto, interrogandoci sugli effetti che tali scelte potrebbero comportare;<\/p>\n<p>&nbsp;<\/p>\n<p>-NON ESSERE COMPLICI del sistema di dominazione e di distruzione del Creato, n\u00e9 con in comportamenti, n\u00e9 con l\u2019indifferenza;<\/p>\n<p>&nbsp;<\/p>\n<p>-OPPORCI a ogni scelta politica, pronti a disobbedire alle misure anche coercitive che portino all\u2019alterazione<\/p>\n<p>&nbsp;<\/p>\n<p>irreversibile dell\u2019equilibrio ecosistemico (attraverso il danneggiamento del ciclo idrico e biodiversit\u00e0) e della<\/p>\n<p>&nbsp;<\/p>\n<p>catena alimentare con effetti devastanti sulla salute e sulla vita.<\/p>\n<p>&nbsp;<\/p>\n<p>-PROPORRE e PRATICARE relazioni rispettose della vita, prendendoci cura della Terra che abitiamo e di cui siamo chiamati a essere custodi e non dominatori.<\/p>\n<p>&nbsp;<\/p>\n<p>Vogliamo concludere questo appello con quanto ci hanno insegnato le nostre sorelle e fratelli indigeni d\u2019America e con quanto detto ai coltivatori diretti a gennaio da Papa Francesco: &lt;&lt;Vorrei rivolgere un invito e una proposta. L\u2019invito \u00e8 quello di ritrovare l\u2019amore per la terra come &#8220;madre&#8221; \u2013 direbbe san Francesco \u2013 dalla quale siamo tratti e a cui siamo chiamati a tornare costantemente. E da qui viene anche la proposta: custodire la terra, facendo alleanza con essa, affinch\u00e9 possa continuare ad essere, come Dio la vuole, fonte di vita per l\u2019intera famiglia umana. Questo va contro lo sfruttamento della terra, come se fosse una cosa senza rapporto con noi -non pi\u00f9 la madre -, e poi lasciarla indebolire e abbandonarla perch\u00e9 non serve a niente&gt;&gt;.<\/p>\n<p>&nbsp;<\/p>\n<p>Missionari e Laici Comboniani \u2013 Lecce<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/29\/alle-sorelle-e-ai-fratelli-di-buona-volonta-messaggio-per-la-domenica-della-palme\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/03\/29\/alle-sorelle-e-ai-fratelli-di-buona-volonta-messaggio-per-la-domenica-della-palme\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Oggi, domenica delle Palme, la chiesa cattolica celebra l\u2019entrata di Ges\u00f9 in Gerusalemme accompagnato come un liberatore e messia nel luogo dove risiede il potere. Il luogo del potere, oggi, \u00e8 abitato da imprese e multinazionali che non hanno scrupoli nel perseguire i loro affari a spese della vita, da scienziati che maneggiano i codici [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47200"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=47200"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47200\/revisions"}],"predecessor-version":[{"id":47203,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47200\/revisions\/47203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/47202"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=47200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=47200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=47200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}