{"id":47446,"date":"2015-04-04T14:38:12","date_gmt":"2015-04-04T12:38:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=47446"},"modified":"2015-04-04T14:38:12","modified_gmt":"2015-04-04T12:38:12","slug":"muri-maestri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/04\/muri-maestri\/","title":{"rendered":"MURI MAESTRI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/Schermata-2015-04-04-a-14.34.53.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/Schermata-2015-04-04-a-14.34.53-300x216.png\" alt=\"\" title=\"Schermata 2015-04-04 a 14.34.53\" width=\"300\" height=\"216\" class=\"alignleft size-medium wp-image-47447\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/Schermata-2015-04-04-a-14.34.53-300x216.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/Schermata-2015-04-04-a-14.34.53.png 486w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/enrico.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/enrico-259x300.jpg\" alt=\"\" title=\"enrico\" width=\"259\" height=\"300\" class=\"alignleft size-medium wp-image-47448\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/enrico-259x300.jpg 259w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/enrico.jpg 500w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/a>&#8220;Anche a\u00a0 Casarano abbiamo presentato la richiesta affinch\u00e8\u00a0 il Comune partecipi al <strong>bando regionale<\/strong>, che permetterebbe la realizzazione GRATUITA di progetti di miglioramento e\/o ristrutturazione degli edifici scolastici locali&#8221;, questo \u00e8 quanto \u00a0riferisce <strong>Enrico Giuranno<\/strong>, del Meetup Casarano 5 Stelle.<\/p>\n<p>&#8220;Grazie al M5S dopo decenni finalmente \u00e8 stata data la possibilit\u00e0 di versare l&#8217;8&#215;1000 all&#8217;edilizia scolastica&#8221;, continua <strong>Giuranno,<\/strong>\u00a0&#8220;Continuiamo a lavorare per il bene delle nostre scuole e per la sicurezza dei nostri figli con l&#8217;iniziativa Muri maestri&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/04\/muri-maestri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/04\/muri-maestri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&#8220;Anche a\u00a0 Casarano abbiamo presentato la richiesta affinch\u00e8\u00a0 il Comune partecipi al bando regionale, che permetterebbe la realizzazione GRATUITA di progetti di miglioramento e\/o ristrutturazione degli edifici scolastici locali&#8221;, questo \u00e8 quanto \u00a0riferisce Enrico Giuranno, del Meetup Casarano 5 Stelle. &#8220;Grazie al M5S dopo decenni finalmente \u00e8 stata data la possibilit\u00e0 di versare l&#8217;8&#215;1000 all&#8217;edilizia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47448,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47446"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=47446"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47446\/revisions"}],"predecessor-version":[{"id":47450,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47446\/revisions\/47450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/47448"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=47446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=47446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=47446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}