{"id":47782,"date":"2015-04-10T12:29:51","date_gmt":"2015-04-10T10:29:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=47782"},"modified":"2015-04-10T14:01:19","modified_gmt":"2015-04-10T12:01:19","slug":"ultimora-la-politica-che-diventa-mafia-in-manette-ex-sindaco-ed-ex-assessori-di-forza-italia-di-cellino-san-marco-uno-spaccato-inquietante-del-sistema-che-regola-e-governa-la-vit-amministrativ","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/10\/ultimora-la-politica-che-diventa-mafia-in-manette-ex-sindaco-ed-ex-assessori-di-forza-italia-di-cellino-san-marco-uno-spaccato-inquietante-del-sistema-che-regola-e-governa-la-vit-amministrativ\/","title":{"rendered":"ULTIM&#8217;ORA \/ LA POLITICA CHE DIVENTA MAFIA \/ IN MANETTE EX SINDACO ED EX ASSESSORI DI FORZA ITALIA DI CELLINO SAN MARCO \/ UNO SPACCATO INQUIETANTE DEL SISTEMA CHE REGOLA E GOVERNA LA VITA AMMINISTRATIVA E SOCIALE DI TANTI PAESI DEL SALENTO"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/g.e..jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"261\" height=\"193\" title=\"g.e.\" class=\"alignleft size-full wp-image-47783\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/g.e..jpg\" \/><\/a>(t.l.<\/strong>)______\u201cDo ut des\u201d, io do a te, affinch\u00e9 tu dia a me. Nel motto latino, con cui gli inquirenti hanno battezzato la clamorosa operazione con cui questa mattina sono state arrestate 14 persone, c\u2019\u00e8 tutto quanto il senso delle accuse a carico dell\u2019 ex giunta comunale di Cellino San Marco, comune commissariato per corruzione mafiosa da un anno e adesso retto da un commissario prefettizio. Ma il clan si era gi\u00e0 portato avanti col lavoro: si stava preparando per le prossime elezioni, per ricominciare tutto come se nulla fosse.<\/p>\n<p>Appalti e concorsi pilotati, in cambio di tangenti.<\/p>\n<p>Le ordinanze di custodia cautelare in carcere parlano di associazione a delinquere, peculato, corruzione, turbata libert\u00e0 di incanti e calunnia e hanno in pratica colpito tutti gli esponenti della passata amministrazione, fra cui l\u2019 ex sindaco Francesco Cascione, avvocato penalista, di Forza Italia, e l\u2019 ex assessore Gabriele Elia, 31 anni (nella foto), ammanettato nella tenuta di Albano, dove risulta domiciliato.<\/p>\n<p>Proprio al cantante, come \u00e8 noto, che l\u00e0 \u00e8 nato e l\u00e0, dopo il successo, ha avviato nel corso degli anni tutta una serie di attivit\u00e0 imprenditoriali, \u00e8 dovuta la fama del paese, che dal punto di vista amministrativo si trova in provincia di Brindisi, ma che in pratica gravita su Lecce, da cui dist pochi chilometri.<\/p>\n<p>Proprio la procura di Brindisi, nella persona del pubblico ministero Antonio Costantini, e disposti dal giudice per le indagini preliminari Paola Liaci, ha richiesto i provvedimenti eseguiti all\u2019 alba dai Carabinieri.<\/p>\n<p>Oltre ai politici e agli amministratori, in carcere sono finiti anche quattro imprenditori delle province di Brindisi, Bari e Lecce e una persona ritenuta vicina alla organizzazione di tipo mafioso Sacra corona unita.<\/p>\n<p>Fra gli arrestati c&#8217;\u00e8 anche, come detto, Gabriele Elia, ex assessore di Cellino San Marco, noto alle cronache per aver girato l&#8217;Italia con un camper bianco per festeggiare il ventennale della discesa in campo di Silvio Berlusconi e proporre, agli inizi del 2014, la candidatura della figlia Marina come premier. Elia \u00e8 stato di recente nominato da Luigi Vitali, segretario regionale di Fi Puglia, suo &#8220;vice-coordinatore&#8221; cittadino a Brindisi, insieme ad altre due persone.<\/p>\n<p>Nel novero degli arrestati, tra cui tutti gli ex assessori comunali di Cellino San Marco, a esclusione dell&#8217;ex componente dell&#8217;esecutivo con delega all&#8217;Urbanistica, Marina Del Foro, ci sono anche, come detto, quattro imprenditori del settore edile. Destinatario dell&#8217;ordinanza pure Omero Molendini, gi\u00e0 coordinatore cittadino di Forza Italia a Cellino San Marco, vittima, tra l&#8217;altro, di una violenta aggressione nel settembre di due anni fa.<\/p>\n<p>Si attendono altri sviluppi.<\/p>\n<p>Comunque \u2013 Cellino San Marco non \u00e8 certo, purtroppo, un caso isolato &#8211; ce n\u2019\u00e8 gi\u00e0 abbastanza per gettare una luce inquietante sulla realt\u00e0 delle infiltrazioni politico \u2013 mafiose che reggono e regolano la vita amministrativa e sociale di tanti nostri comuni del Salento, con una commistione nell\u2019 attualit\u00e0 dei fatti quotidiani oramai consolidata, fra esponenti politici, dal Pd a Forza Italia, che dalla mafia acquisiscono coperture e, soprattutto, le logiche clientelari e affaristiche con cui instaurano veri e propri sistemi totalitari di potere.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/10\/ultimora-la-politica-che-diventa-mafia-in-manette-ex-sindaco-ed-ex-assessori-di-forza-italia-di-cellino-san-marco-uno-spaccato-inquietante-del-sistema-che-regola-e-governa-la-vit-amministrativ\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/10\/ultimora-la-politica-che-diventa-mafia-in-manette-ex-sindaco-ed-ex-assessori-di-forza-italia-di-cellino-san-marco-uno-spaccato-inquietante-del-sistema-che-regola-e-governa-la-vit-amministrativ\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______\u201cDo ut des\u201d, io do a te, affinch\u00e9 tu dia a me. Nel motto latino, con cui gli inquirenti hanno battezzato la clamorosa operazione con cui questa mattina sono state arrestate 14 persone, c\u2019\u00e8 tutto quanto il senso delle accuse a carico dell\u2019 ex giunta comunale di Cellino San Marco, comune commissariato per corruzione mafiosa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47783,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47782"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=47782"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47782\/revisions"}],"predecessor-version":[{"id":47792,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/47782\/revisions\/47792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/47783"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=47782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=47782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=47782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}