{"id":48419,"date":"2015-04-17T09:49:23","date_gmt":"2015-04-17T07:49:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=48419"},"modified":"2015-04-17T15:02:11","modified_gmt":"2015-04-17T13:02:11","slug":"10-euro-a-voto-per-emiliano-un-esposto-del-deputato-pugliese-giuseppe-dambrosio-sulla-vergognosa-pratica-della-compravendita-dei-voti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/17\/10-euro-a-voto-per-emiliano-un-esposto-del-deputato-pugliese-giuseppe-dambrosio-sulla-vergognosa-pratica-della-compravendita-dei-voti\/","title":{"rendered":"10 EURO A VOTO. PER EMILIANO. UN ESPOSTO DEL DEPUTATO PUGLIESE GIUSEPPE D&#8217;AMBROSIO SULLA VERGOGNOSA PRATICA DELLA COMPRAVENDITA DEI VOTI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/11017493_877865535588545_6470753633437702503_n.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"239\" height=\"319\" title=\"11017493_877865535588545_6470753633437702503_n\" class=\"alignleft size-full wp-image-48420\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/11017493_877865535588545_6470753633437702503_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/11017493_877865535588545_6470753633437702503_n.jpg 239w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/11017493_877865535588545_6470753633437702503_n-224x300.jpg 224w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/a>(Rdl)______Il portavoce alla Camera dei Deputati del M5S Giuseppe D&#8217; Ambrosio, deputato pugliese, di Andria, ha pubblicato sul suo profilo Facebook il seguente post______<\/p>\n<p>&#8220;Ho pubblicato un estratto di una conversazione privata in cui si promuove il voto di scambio.<\/p>\n<p>Qualcuno ha addirittura avuto il coraggio di &#8220;spacciarla&#8221; per mera propaganda del MoVimento 5 Stelle.\u00a0 Sia chiaro.<\/p>\n<p>Il sottoscritto e tutto il MoVimento 5 Stelle non scherza sulla legalit\u00e0. Oggi pomeriggio ho presentato un esposto presso le autorit\u00e0 competenti in merito a questo episodio.<\/p>\n<p>Nella conversazione, che potete osservare integralmente nella foto, sembra che il voto di scambio &#8220;coinvolga&#8221; Emiliano, candidato Presidente alla Regione Puglia del Partito Democratico.<\/p>\n<p>Michele Emiliano ed il Partito Democratico &#8220;vantano&#8221; una difesa della legalit\u00e0 ed una seria azione effettuata con l&#8217;approvazione di diverse norme.<\/p>\n<p>Ed allora la mia sfida a Michele Emiliano \u00e8 quella di contattarmi per ricevere la conversazione integrale e poter agire di conseguenza e pubblicamente, smentendo ogni coinvolgimento all&#8217;interno di questo sporco gioco che sarebbe relativo all&#8217;art.86 dpr. 570 del 1960.<\/p>\n<p>Emiliano poi, ad esempio, aveva dichiarato che sul 416-ter il MoVimento 5 Stelle aveva ragione a protestare e votare contro, perch\u00e9 il ribasso effettuato sulle pene era frutto di un accordo tra PD e Forza Italia.<\/p>\n<p>Ora dimostri di non usufruire lui di quell&#8217;accordo.\u00a030 Euro per 3 voti. La nostra dignit\u00e0 non ha prezzo.<\/p>\n<p>Il nostro futuro non ha prezzo&#8221;.<\/p>\n<p>Da parte nostra, seguiremo gli sviluppi della clamorosa vicenda.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/17\/10-euro-a-voto-per-emiliano-un-esposto-del-deputato-pugliese-giuseppe-dambrosio-sulla-vergognosa-pratica-della-compravendita-dei-voti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/17\/10-euro-a-voto-per-emiliano-un-esposto-del-deputato-pugliese-giuseppe-dambrosio-sulla-vergognosa-pratica-della-compravendita-dei-voti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Il portavoce alla Camera dei Deputati del M5S Giuseppe D&#8217; Ambrosio, deputato pugliese, di Andria, ha pubblicato sul suo profilo Facebook il seguente post______ &#8220;Ho pubblicato un estratto di una conversazione privata in cui si promuove il voto di scambio. Qualcuno ha addirittura avuto il coraggio di &#8220;spacciarla&#8221; per mera propaganda del MoVimento 5 Stelle.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48420,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48419"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=48419"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48419\/revisions"}],"predecessor-version":[{"id":48422,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48419\/revisions\/48422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/48420"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=48419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=48419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=48419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}