{"id":48854,"date":"2015-04-23T14:34:42","date_gmt":"2015-04-23T12:34:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=48854"},"modified":"2015-04-23T14:36:00","modified_gmt":"2015-04-23T12:36:00","slug":"giu-le-mani-dal-nostro-mare-manifestazione-del-m5s-a-santa-maria-di-leuca-domenica-26","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/giu-le-mani-dal-nostro-mare-manifestazione-del-m5s-a-santa-maria-di-leuca-domenica-26\/","title":{"rendered":"&#8220;Gi\u00f9 le mani dal nostro mare!&#8221; \/ MANIFESTAZIONE DEL M5S A SANTA MARIA DI LEUCA DOMENICA 26"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/images4.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"251\" height=\"201\" title=\"images\" class=\"alignleft size-full wp-image-48855\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/images4.jpg\" \/><\/a>Riceviamo e volentieri pubblichiamo. Il M5S ci manda il seguente comunicato______<\/p>\n<p>&#8220;Gi\u00f9 le mani dal nostro mare!&#8221; \u00e8 il messaggio che il M5S intende lanciare a gran voce domenica 26 aprile da Santa Maria di Leuca contro le trivellazioni petrolifere approvate dal governo Renzi nei mari al largo del Salento.<\/p>\n<p>A pi\u00f9 di vent&#8217;anni dal Summit della Terra, in cui le istituzioni a livello mondiale sembrarono acquisire la consapevolezza di dover abbandonare la strategia energetica fondata sulle fonti fossili, la politica a tutti i livelli, europeo, nazionale e regionale, dietro l&#8217;ipocrita propaganda di facciata sulla \u201cgreen economy\u201d, agisce nei fatti in una cieca continuit\u00e0 col passato.<\/p>\n<p>Per le forze politiche al governo, in primis il PD di Renzi, energia significa ancora cercare il petrolio, importare metano, distruggere gli cosistemi e scavalcare i presupposti necessari per tutelare la salute umana e non solo.<\/p>\n<p>Il M5S rimane l&#8217;unica forza politica credibile determinata a superare il \u201cpensiero fossile\u201d verso una politica energetica basata sulle fonti rinnovabili, sull&#8217;auto-produzione e sullo scambio in rete. Una politica energetica che recepisce i principi, i metodi e gli strumenti gi\u00e0 delineati dagli esperti della \u201cterza rivoluzione industriale\u201d come Jeremy Rifkin <strong>(nella foto, ndr)<\/strong> , e che si oppone fermamente ad opere inutili e dannose come il TAP e al folle programma di trivellazioni nei mari italiani, vocati a tutt&#8217;altra funzione, alla valorizzazione turistica, alla piccola pesca e alla ricerca scientifica.<\/p>\n<p>E&#8217; necessario dare forza a una nuova visione di sviluppo e per farlo abbiamo bisogno della consapevolezza e della partecipazione dei cittadini, ai quali chiediamo di unirsi numerosi alla manifestazione \u201cGIU\u2019 LE MANI DAL NOSTRO MARE\u201d, programmata per domenica 26 aprile a Santa Maria di Leuca.<\/p>\n<p>Si parte in corteo alle ore 17.00 da punta Ristola, estremo sud dell&#8217;Italia, e si prosegue sul lungomare C. Colombo dove interverranno il dr. Giovanni Micaletto (biologo marino), il dr. Giuseppe Negro (medico), i pescatori del basso Salento, i portavoce al Parlamento del M5S Paola Taverna, Maurizio Buccarella, Diego De Lorenzis e Daniela Donno, e la candidata del M5S alla Presidenza della Regione Puglia Antonella Laricchia. Saranno presenti anche le band salentine Officina Zo\u00e8 e No Oil No Petroil Blues Band.<\/p>\n<p>I cittadini, le associazioni, i comitati e gli organi di stampa sono invitati a partecipare&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/giu-le-mani-dal-nostro-mare-manifestazione-del-m5s-a-santa-maria-di-leuca-domenica-26\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/giu-le-mani-dal-nostro-mare-manifestazione-del-m5s-a-santa-maria-di-leuca-domenica-26\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il M5S ci manda il seguente comunicato______ &#8220;Gi\u00f9 le mani dal nostro mare!&#8221; \u00e8 il messaggio che il M5S intende lanciare a gran voce domenica 26 aprile da Santa Maria di Leuca contro le trivellazioni petrolifere approvate dal governo Renzi nei mari al largo del Salento. A pi\u00f9 di vent&#8217;anni dal [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48854"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=48854"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48854\/revisions"}],"predecessor-version":[{"id":48857,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48854\/revisions\/48857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/48855"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=48854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=48854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=48854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}