{"id":48870,"date":"2015-04-23T16:30:24","date_gmt":"2015-04-23T14:30:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=48870"},"modified":"2015-04-23T19:01:11","modified_gmt":"2015-04-23T17:01:11","slug":"la-macchina-per-le-radiografie-al-fazzi-si-rompe-i-pazienti-vengono-dirottati-al-pronto-soccorso-disagi-e-proteste","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/la-macchina-per-le-radiografie-al-fazzi-si-rompe-i-pazienti-vengono-dirottati-al-pronto-soccorso-disagi-e-proteste\/","title":{"rendered":"LA MACCHINA PER LE RADIOGRAFIE AL FAZZI SI ROMPE, I PAZIENTI VENGONO DIROTTATI AL PRONTO SOCCORSO: DISAGI E PROTESTE"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/macradio.png\"><img decoding=\"async\" loading=\"lazy\" width=\"150\" height=\"150\" title=\"macradio\" class=\"alignleft size-thumbnail wp-image-48871\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/macradio-150x150.png\" \/><\/a>di Roberto De Salvatore______<\/p>\n<p style=\"text-align: justify;\">Non si pu\u00f2 chiedere sempre ai cittadini pazienza e rassegnazione. Un paio di giorni fa al presidio ospedaliero Vito Fazzi di Lecce una delle due macchine per le radiografie del reparto Radiologia \u00e8 andata in tilt, il primario dottor Massimo Torsello aveva escogitato un espediente per alleviare questo disagio utilizzando la macchina \u2018superstite\u2019 di Radiologia e dirottando altri pazienti in attesa verso la macchina presente in Pronto Soccorso. E\u2019 andata avanti per un paio di giorni, ma stamattina la situazione \u00e8 divenuta insostenibile per la presenza di oltre 30 pazienti in Pronto Soccorso dirottati da Radiologia.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Il tecnico ha ritirato le richieste alla rinfusa<\/em> \u2013 riferisce indignato un signore di Lecce che ha accompagnato la mamma 80enne \u2013 <em>Quindi \u00e8 successo che chi \u00e8 arrivato prima si ritrova a dover attendere di pi\u00f9<\/em>\u00bb. E gi\u00f9 altre lamentele. \u00ab<em>Devo andare in bagno e non so come fare<\/em> \u2013 ha detto un signore 70enne rivolgendosi ad un altro in attesa &#8211; <em>Vado a cercare una toilette; per favore, se mi chiamano spieghi che mi sono assentato un attimo<\/em>\u00bb. Un altro paziente ancora lamentava il fatto che non poteva rimanere in piedi per tanto tempo. Qualcuno ha portato le sedie dalla sala di attesa del Pronto soccorso e qualcun altro ha telefonato ai carabinieri. Intanto \u00e8 intervenuto il poliziotto del posto fisso che ha tenuto a bada i pi\u00f9 agitati.<\/p>\n<p style=\"text-align: justify;\">Scene allucinanti di mala sanit\u00e0 cui \u00e8 difficile abituarsi. Alla gente non importa nulla se per anni la sanit\u00e0 \u00e8 stata la greppia a cui si sono rimpinzati politici e faccendieri. Intanto resta da capire come \u00e8 possibile che un macchinario indispensabile resti inoperante per oltre due giorni. Si dovrebbe indagare meglio sui contratti stipulati per la fornitura tra chi\u00a0produce i macchinari e l\u2019istituzione sanitaria, oltre che sui contratti di manutenzione, e soprattutto quanto costa tale manutenzione, e come mai i tecnici preposti alla riparazione ci mettano cos\u00ec tanto. Saranno mica macchinari tanto obsoleti che invece di essere dirottati in Congo sono stati appioppati agli ospedali italiani? Certo, pu\u00f2 essere che il continuo funzionamento di questi macchinari sia la causa di soventi avarie, ma non si pu\u00f2 certo giustificare il ritardo nelle riparazioni che devono essere effettuate entro tempi brevissimi. Non ce la sentiamo di imputare alcuna colpa ai medici stavolta, fanno quello che possono in una situazione allucinante, ma dall\u2019amministrazione si, ci aspetteremmo qualche risposta non fumosa o politichese.<\/p>\n<p style=\"text-align: justify;\">I leccesi e tutti gli italiani hanno dato e continuano a dare sempre di pi\u00f9 ad uno stato latitante che non da nulla. Ci aspettiamo da un giorno o l\u2019altro che ci venga dato il consiglio di andarci a fare assistere in Africa da Medici Senza Frontiere, forse sarebbe la soluzione.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/la-macchina-per-le-radiografie-al-fazzi-si-rompe-i-pazienti-vengono-dirottati-al-pronto-soccorso-disagi-e-proteste\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/la-macchina-per-le-radiografie-al-fazzi-si-rompe-i-pazienti-vengono-dirottati-al-pronto-soccorso-disagi-e-proteste\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Roberto De Salvatore______ Non si pu\u00f2 chiedere sempre ai cittadini pazienza e rassegnazione. Un paio di giorni fa al presidio ospedaliero Vito Fazzi di Lecce una delle due macchine per le radiografie del reparto Radiologia \u00e8 andata in tilt, il primario dottor Massimo Torsello aveva escogitato un espediente per alleviare questo disagio utilizzando la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48870"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=48870"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48870\/revisions"}],"predecessor-version":[{"id":48892,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48870\/revisions\/48892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/48871"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=48870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=48870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=48870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}