{"id":48883,"date":"2015-04-23T18:59:47","date_gmt":"2015-04-23T16:59:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=48883"},"modified":"2015-04-23T19:00:11","modified_gmt":"2015-04-23T17:00:11","slug":"presunto-spacciatore-arrestato-a-nardo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/presunto-spacciatore-arrestato-a-nardo\/","title":{"rendered":"PRESUNTO SPACCIATORE ARRESTATO A NARDO&#8217;"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/untitled22.png\"><img decoding=\"async\" loading=\"lazy\" width=\"270\" height=\"186\" title=\"untitled\" class=\"alignleft size-full wp-image-48888\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/untitled22.png\" \/><\/a>(t.l.)______Questa mattina i carabinieri\u00a0di Nard\u00f2 hanno arrestato Michele Antonio Spenga, 45 anni,\u00a0di Nard\u00f2, trovato in possesso di trentacinque grammi di hashish.<\/p>\n<p>L\u2019uomo \u00e8 stato sottoposto a controllo negli ultimi giorni, poich\u00e9 da qualche tempo la sua abitazione era diventata m\u00e8ta di molte persone, ad ogni ora del giorno e della notte.<\/p>\n<p>Insospettiti dal via-vai, i\u00a0militari hanno predisposto un specifica attivit\u00e0 e questa mattina, con l\u2019unit\u00e0 cinofila del Nucleo di Modugno (nella foto)\u00a0sono intervenuti, circondando la casa. Spenga, alla vista dei militari, ha temporeggiato, prima di aprire ed \u00e8 stato visto uscire sul balcone e gettare un involucro, subito raccolto dai militari che hanno scoperto all\u2019interno trentacinque grammi di hashish.<\/p>\n<p>A quel punto, vista la situazione, Spenga ha aperto la porta e la perquisizione \u00e8 proseguita. Il fiuto del cane Amun ha permesso di rinvenire il materiale per il confezionamento nella camera da letto. Nella gabbia dei canarini, sotto il giornale utilizzato come base, \u00e8 stato trovato\u00a0il bilancino.<\/p>\n<p>Da qui l&#8217; arresto dell&#8217; uomo, al quale sono stati concessi i domiciliari.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>AREA CENTRO SUD<\/p>\n<p>&nbsp;<\/p>\n<p>Nessuna informazione<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>AREA DEL CAPO<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/presunto-spacciatore-arrestato-a-nardo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/23\/presunto-spacciatore-arrestato-a-nardo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Questa mattina i carabinieri\u00a0di Nard\u00f2 hanno arrestato Michele Antonio Spenga, 45 anni,\u00a0di Nard\u00f2, trovato in possesso di trentacinque grammi di hashish. L\u2019uomo \u00e8 stato sottoposto a controllo negli ultimi giorni, poich\u00e9 da qualche tempo la sua abitazione era diventata m\u00e8ta di molte persone, ad ogni ora del giorno e della notte. Insospettiti dal via-vai, i\u00a0militari [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48883"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=48883"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48883\/revisions"}],"predecessor-version":[{"id":48890,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/48883\/revisions\/48890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/48888"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=48883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=48883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=48883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}