{"id":49145,"date":"2015-04-27T10:19:26","date_gmt":"2015-04-27T08:19:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=49145"},"modified":"2015-04-28T19:36:36","modified_gmt":"2015-04-28T17:36:36","slug":"ciclismo-gloria-per-la-gs-piconese-nellottavo-trofeo-citta-di-statte-primo-premio-per-de-santis-e-marrocco","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/27\/ciclismo-gloria-per-la-gs-piconese-nellottavo-trofeo-citta-di-statte-primo-premio-per-de-santis-e-marrocco\/","title":{"rendered":"CICLISMO\/ GLORIA PER LA GS PICONESE NEL TROFEO &#8220;CITTA&#8217; DI STATTE&#8221;. PRIMO PREMIO PER DE SANTIS E MARROCCO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/cosimo-de-santis-statte-1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"208\" title=\"cosimo de santis statte 1\" class=\"alignleft size-medium wp-image-49146\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/cosimo-de-santis-statte-1-300x208.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/cosimo-de-santis-statte-1-300x208.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/cosimo-de-santis-statte-1.jpg 749w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(l.r.) Regalo di compleanno anticipato, quello di oggi, per \u00a0<strong>Cosimo De Santis<\/strong>: il ciclista della\u00a0<strong>GS Piconese<\/strong>, infatti, ha vinto con merito la gara valida per l\u2019<strong><em>Ottavo Trofeo \u201cCitt\u00e0 di Statte\u201d<\/em><\/strong>\u00a0(circuito ondulato urbano ed extraurbano di km<strong>\u00a012,800<\/strong>\u00a0da ripetere n. 6 volte per complessivi km 77 circa).<\/p>\n<p>Nella categoria donne, sempre a Statte, la<strong>\u00a0GS Piconese<\/strong>\u00a0registra con soddisfazione un altro primo posto: ad ottenere la prima piazza, infatti, \u00e8 stata\u00a0<strong>Lucia Marrocco\u00a0<\/strong>(nella foto), protagonista di una gara attenta e sin da subito impostata su alti livelli agonostici. Il team melendugnese ha partecipato anche alla tappa del\u00a0<strong>Giro dell\u2019Arcobaleno<\/strong>\u00a0che si \u00e8 tenuta a Canosa dove\u00a0<strong>Bartolomeo Giorgio<\/strong>\u00a0si \u00e8 classificato settimo; al 13\u00b0 e al 15\u00b0 posto si sono classificati invece<strong>\u00a0Emanuele Piconese e Ciro Greco<\/strong>.<\/p>\n<p>I baby della\u00a0<strong>GS Piconese Pedale Jonico<\/strong>, poi, hanno vinto il Torneo per Societ\u00e0 in quel di Carovigno grazie anche al secondo posto ottenuto dal debuttante\u00a0<strong>Emanuele Trisolino<\/strong>.<\/p>\n<p>Per quanto riguarda la<strong>\u00a0categoria MTB<\/strong>, infine,\u00a0<strong>Andrea Cret\u00ec<\/strong>\u00a0chiude la tappa della Salento Cup di Santa Marina in seconda posizione, seguito da\u00a0<strong>Brizio Tommasi<\/strong>\u00a0e\u00a0<strong>Vito Cisternino<\/strong>, rispettivamente all\u2019undicesimo e al trentaduesimo posto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/27\/ciclismo-gloria-per-la-gs-piconese-nellottavo-trofeo-citta-di-statte-primo-premio-per-de-santis-e-marrocco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/27\/ciclismo-gloria-per-la-gs-piconese-nellottavo-trofeo-citta-di-statte-primo-premio-per-de-santis-e-marrocco\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(l.r.) Regalo di compleanno anticipato, quello di oggi, per \u00a0Cosimo De Santis: il ciclista della\u00a0GS Piconese, infatti, ha vinto con merito la gara valida per l\u2019Ottavo Trofeo \u201cCitt\u00e0 di Statte\u201d\u00a0(circuito ondulato urbano ed extraurbano di km\u00a012,800\u00a0da ripetere n. 6 volte per complessivi km 77 circa). Nella categoria donne, sempre a Statte, la\u00a0GS Piconese\u00a0registra con soddisfazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49145"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=49145"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49145\/revisions"}],"predecessor-version":[{"id":49153,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49145\/revisions\/49153"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=49145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=49145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=49145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}