{"id":49189,"date":"2015-04-29T13:02:24","date_gmt":"2015-04-29T11:02:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=49189"},"modified":"2015-04-29T18:03:24","modified_gmt":"2015-04-29T16:03:24","slug":"il-sedicente-comitato-per-la-salute-delle-piante-dlla-comun-ita-europea-insiste-nel-chidere-l-abbattimento-degli-ulivi-sia-pur-in-misura-mirata-nel-nord-salento-rosa-damato-una-decisio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/29\/il-sedicente-comitato-per-la-salute-delle-piante-dlla-comun-ita-europea-insiste-nel-chidere-l-abbattimento-degli-ulivi-sia-pur-in-misura-mirata-nel-nord-salento-rosa-damato-una-decisio\/","title":{"rendered":"IL SEDICENTE COMITATO &#8216;PER LA SALUTE DELLE PIANTE&#8217; DELLA COMUNITA&#8217; EUROPEA INSISTE NEL CHIEDERE L&#8217; ABBATTIMENTO DEGLI ULIVI, SIA PUR IN MISURA MIRATA, NEL NORD SALENTO. ROSA D&#8217;AMATO: &#8220;Una decisione ambigua, che non tiene conto delle buone pratiche agricole e delle ricerche scientifiche&#8221;. ANGELO BONELLI: &#8220;Bisognava attuare misure di contenimento. Adesso bisogna individuare i resposabili e difendere la Puglia&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/f8f00bd430bd6cb175877b07c2166938.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"338\" title=\"++ Xylella: Ue decide eradicazione in raggio 100 metri ++\" class=\"alignleft size-full wp-image-49190\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/f8f00bd430bd6cb175877b07c2166938.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/f8f00bd430bd6cb175877b07c2166938.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/f8f00bd430bd6cb175877b07c2166938-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>(Rdl)______Nella tarda serata di ieri, sono arrivate da Bruxelles le decisioni della commissione europea incaricata di stabilire quali misure concrete far adottare all&#8217; Italia, dopo le polemiche, i ricorsi, le perplessit\u00e0 e le critiche dei giorni scorsi alle prime misure che la Comunit\u00e0 Europea aveva chiesto.<\/p>\n<p>In sintesi estrema, da questa notte pare che quanto acquisito e assodato finora, non ultimo il pronunciamento dei giudici amministrativi del Tar del Lazio, che ha bloccato gli abbattimenti, almeno fino al 6 di maggio, e a cominciare dall&#8217; inchiesta penale in corso da parte della magistratura ordinaria,\u00a0oltre naturalmente alle manifestazioni e alle acquisizioni scientifiche di associazioni, contadini e cittadini, tutte concordi nel ritenere le buone pratiche agricole capaci di arginare e sconfiggere il fenomeno, sia stato tutto inutile.<\/p>\n<p>Il Comitato dell&#8217; Unione Europea per la salute delle piante, dopo una riunione fiume durata due giorni, alla fine ha deciso misure pi\u00f9 radicali per le zone del nord Salento colpite dai focolai di Xylella, con l&#8217;eradicazione non solo degli ulivi malati, ma anche di tutte le piante ospiti nel raggio di\u00a0cento metri, e una tutela del Salento, dove dovranno essere tagliate solo le piante malate ed eseguiti test su quelle circostanti in una fascia di venti km tra Brindisi e Taranto.<\/p>\n<p>L&#8217;obiettivo\u00a0sarebbe quello di\u00a0evitare la diffusione del batterio killer degli ulivi con azioni drastiche e allo stesso tempo cercare di preservare il patrimonio olivicolo ma anche paesaggistico salentino.<\/p>\n<p>Per questo <em>&#8220;le nuove misure Ue richiedono agli stati membri di notificare nuovi focolai, di condurre test ufficiali e di demarcare le aree infette&#8221; in cui &#8220;rigide misure di eradicazione sono messe in piedi, che includono la rimozione e la distruzione delle piante infette e di tutte le piante ospiti in un raggio di\u00a0cento metri, a prescindere dal loro stato di salute&#8221;.<\/em><\/p>\n<p>Per il Salento, invece, l&#8217;Italia \u00e8 riuscita ad ottenere &#8220;<em>la possibilit\u00e0 di applicare misure di contenimento nell&#8217;intera provincia di Lecce, dove l&#8217;eradicazione non \u00e8 pi\u00f9 possibile<\/em>&#8220;.<\/p>\n<p>Ad eccezione, per\u00f2, della fascia settentrionale &#8220;<em>di 20 km adiacente alle province di Brindisi e Taranto&#8221;<\/em> in cui &#8220;<em>viene mantenuto il requisito di rimuovere sistematicamente tutte le piante infette e di testare le piante circostanti nell&#8217;arco di 100 metri<\/em>&#8220;.<\/p>\n<p>Giro di vite, invece, sia sulle importazioni di piante da paesi terzi, in particolare il blocco di quelle di caff\u00e8 da Honduras e Costa Rica, ma anche sulle esportazioni pugliesi verso i paesi Ue..<\/p>\n<p>Per la portavoce al parlamento europeo del M5s <strong>Rosa D&#8217; Amato<\/strong>, <em>&#8220;la decisione presa\u00a0all&#8217;Ue \u00e8 ambigua e poco chiara, in particolare per quanto riguarda l&#8217;entit\u00e0 delle eradicazioni da effettuare nelle province di Lecce, Brindisi e Taranto. <\/em><\/p>\n<p><em>Nel testo comunicato da Bruxelles, non si dice nulla di specifico sulle misure di contenimento da adottare, si parla in modo generico di restrizioni al movimento di piante all&#8217;interno dell&#8217;Unione europea e soprattutto si continua ad accostare il ceppo della Xylella che ha colpito gli ulivi a quelli delle viti e degli agrumi, senza che vi sia ancora una prova scientifica a riguardo. A causa di questo accostamento, si chiede alla Puglia di abbattere le viti che si trovano in un raggio di 100 metri dagli ulivi infetti. Per tutte queste ragioni, occorre che l&#8217;Ue chiarisca subito tali punti. Gli agricoltori pugliesi vogliono risposte<\/em>.<\/p>\n<p><em>Nel testo non vengono prese in considerazione le uniche misure che esperti e organizzazioni del settore di tutta Europa chiedono a gran voce: la promozione delle buone pratiche per contenere la diffusione del batterio e la ricerca su cause ed eventuali cure contro il disseccamento. <\/em><\/p>\n<p><em>Nell&#8217;attesa di chiarimenti, noi continuiamo la nostra battaglia. Ho invitato i miei colleghi del Parlamento, esperti e organizzazioni del settore a una tavola rotonda per affrontare il caso e trovare delle soluzioni comuni per il bene dell&#8217;agricoltura europea&#8221;.\u00a0\u00a0\u00a0<\/em><\/p>\n<p><em><\/em>Il leader dei Verdi <strong>Angelo Bonelli<\/strong>,\u00a0&#8220;<em>per quanto accaduto e sta accadendo in Pu<\/em>glia&#8221; chiede di individuare &#8220;<em>le responsabilit\u00e0 e comprendere la ragione per la quale le istituzioni regionali e nazionali che erano a conoscenza dell&#8217;emergenza Xylella da oltre tre anni hanno atteso cos\u00ec tanto tempo per adottare misure che si sono poi tradotte nel piano Siletti di massiccia eradicazione poi bocciato dal Tar del Lazio.<\/em><\/p>\n<p><em>La decisione della UE dimostra che se si fosse intervenuti in tempo, le eradicazione degli ulivi si sarebbero potute evitar, attuando politiche di contenimento e buone pratiche per tutelare le piante dal contagio. Ritengo che sia in corso un attacco contro il patrimonio storico-ambientale ed economico della Puglia rappresentato dai secolari ulivi.\u00a0Difendiamo la Puglia e la sua storia&#8221;.<\/em><\/p>\n<p><em><\/em>Le associazioni ambientaliste si stanno nel frattempo gi\u00e0 organizzando per contrastare le decisioni della comunit\u00e0 europea.<br \/>\n<em><!-- attacment management --><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/29\/il-sedicente-comitato-per-la-salute-delle-piante-dlla-comun-ita-europea-insiste-nel-chidere-l-abbattimento-degli-ulivi-sia-pur-in-misura-mirata-nel-nord-salento-rosa-damato-una-decisio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/29\/il-sedicente-comitato-per-la-salute-delle-piante-dlla-comun-ita-europea-insiste-nel-chidere-l-abbattimento-degli-ulivi-sia-pur-in-misura-mirata-nel-nord-salento-rosa-damato-una-decisio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Nella tarda serata di ieri, sono arrivate da Bruxelles le decisioni della commissione europea incaricata di stabilire quali misure concrete far adottare all&#8217; Italia, dopo le polemiche, i ricorsi, le perplessit\u00e0 e le critiche dei giorni scorsi alle prime misure che la Comunit\u00e0 Europea aveva chiesto. In sintesi estrema, da questa notte pare che quanto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49189"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=49189"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49189\/revisions"}],"predecessor-version":[{"id":49199,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49189\/revisions\/49199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/49190"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=49189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=49189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=49189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}