{"id":49255,"date":"2015-04-30T15:01:05","date_gmt":"2015-04-30T13:01:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=49255"},"modified":"2015-04-30T15:01:05","modified_gmt":"2015-04-30T13:01:05","slug":"violenta-tentata-rapina-di-miggiano-dello-scorso-marzo-arrestati-questa-mattina-i-presunti-autori","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/30\/violenta-tentata-rapina-di-miggiano-dello-scorso-marzo-arrestati-questa-mattina-i-presunti-autori\/","title":{"rendered":"VIOLENTA TENTATA RAPINA DI MIGGIANO DELLO SCORSO MARZO, ARRESTATI QUESTA MATTINA I PRESUNTI AUTORI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/sequestro-abiti-2.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" title=\"sequestro abiti 2\" class=\"alignleft size-large wp-image-49256\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/sequestro-abiti-2-1024x768.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/sequestro-abiti-2-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/sequestro-abiti-2-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/04\/sequestro-abiti-2.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>(t.l.)______Scoperti e arrestati\u00a0i presunti\u00a0autori di una tentata rapina particolarmente odiosa ai danni di una persona anziana, una donna di 89 anni,\u00a0avvenuta all&#8217; interno della sua abitazione a Miggiano lo scorso 25 marzo. Questa mattina i\u00a0Carabinieri di Specchia, con la collaborazione del Nucleo Cinofili Carabinieri Modugno, hanno eseguito\u00a0quattro ordinanze di custodia cautelare emesse dal giudice del Tribunale di Lecce Giovanni Gallo,\u00a0su richiesta del\u00a0\u00a0procuratore \u00a0della Repubblica Roberta Licci, a carico di Simone Rubesa, 49 anni, Lucio Sammati, 32, Leonardo Sammati, 30,\u00a0 e Luigi Rizzalo, 30, tutti di Miggiano.<\/p>\n<p>La sera del 25 marzo\u00a0due uomini, armati di coltello e a volto coperto da un passamontagna, avevano fatto irruzione all\u2019interno\u00a0di abitazione di Miggiano, dove vivono un&#8217; donna anziana e la figlia; dopo aver afferrato\u00a0la madre cingendole il collo, trattenendole con forza il braccio sinistro e puntandole un coltello alla gola, avevano minacciato ripetutamente le donne chiedendo di consegnare loro i soldi; uno dei malviventi, inoltre, durante l\u2019azione aveva anche poggiato sul tavolo un rotolo di nastro adesivo di colore azzurro, presumibilmente per legare e imbavagliare le vittime.<\/p>\n<p>Mentre i malviventi si erano volti verso una porta che consente l\u2019accesso alle stanze interne dell\u2019abitazione, la giovane donna era riuscita a liberarsi ed a fuggire nel cortile antistante l\u2019abitazione, dove aveva cominciato a chiedere soccorso; in quel momento i due si erano precipitosamente allontanati, passando per il giardino retrostante l\u2019abitazione.<\/p>\n<p>Le indagini erano partite da un paio di occhiali ritrovato sul posto e dalla descrizione dei rapinatori, e sono proseguite con le analisi degli abiti adoperati nella tentata rapina (nella foto) successivamente ritrovati.<\/p>\n<p>Pochi elementi, ma che sono bastati ai Carabinieri a individuare in prima battura Simone Rubesa e Lucio Sammati e raccogliere elementi per l&#8217; accusa anche per gli altri due.<\/p>\n<p>Questa mattina gli arresti. Ai quattro sono stati concessi i domiciliari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/30\/violenta-tentata-rapina-di-miggiano-dello-scorso-marzo-arrestati-questa-mattina-i-presunti-autori\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/04\/30\/violenta-tentata-rapina-di-miggiano-dello-scorso-marzo-arrestati-questa-mattina-i-presunti-autori\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Scoperti e arrestati\u00a0i presunti\u00a0autori di una tentata rapina particolarmente odiosa ai danni di una persona anziana, una donna di 89 anni,\u00a0avvenuta all&#8217; interno della sua abitazione a Miggiano lo scorso 25 marzo. Questa mattina i\u00a0Carabinieri di Specchia, con la collaborazione del Nucleo Cinofili Carabinieri Modugno, hanno eseguito\u00a0quattro ordinanze di custodia cautelare emesse dal giudice del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49256,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49255"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=49255"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49255\/revisions"}],"predecessor-version":[{"id":49258,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49255\/revisions\/49258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/49256"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=49255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=49255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=49255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}