{"id":49368,"date":"2015-05-02T17:29:31","date_gmt":"2015-05-02T15:29:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=49368"},"modified":"2015-05-02T17:29:31","modified_gmt":"2015-05-02T15:29:31","slug":"due-giovani-denunciati-per-droga-a-campi-salentina-e-a-carmiano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/02\/due-giovani-denunciati-per-droga-a-campi-salentina-e-a-carmiano\/","title":{"rendered":"DUE GIOVANI DENUNCIATI PER DROGA A CAMPI SALENTINA E A CARMIANO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/1_1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"157\" title=\"1_1\" class=\"alignleft size-medium wp-image-49370\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/1_1-300x157.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/1_1-300x157.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/1_1.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(t.l.)_______Due giovani sono stati denunciati da Carabinieri, intervenuti anche con l&#8217; ausilio delle unit\u00e0 cinofili di Modugno (nella foto),\u00a0per detenzione di stupefacenti a fini di spaccio.<\/p>\n<p>Il primo \u00e8 G.N., 28 anni, di\u00a0Campi Salentina, con precedenti: aveva in casa 28 grammi di hashish.<\/p>\n<p>Il secondo \u00e8 S.G., 28 anni, di Carmiano: aveva in casa\u00a0sei dosi di cocaina confezionate \u2013 per un totale di quasi quattro grammi \u2013 e poco meno di un grammo di hashish, oltre a materiale da confezionamento, a trituratori e alla somma contante di 610 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/02\/due-giovani-denunciati-per-droga-a-campi-salentina-e-a-carmiano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/02\/due-giovani-denunciati-per-droga-a-campi-salentina-e-a-carmiano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)_______Due giovani sono stati denunciati da Carabinieri, intervenuti anche con l&#8217; ausilio delle unit\u00e0 cinofili di Modugno (nella foto),\u00a0per detenzione di stupefacenti a fini di spaccio. Il primo \u00e8 G.N., 28 anni, di\u00a0Campi Salentina, con precedenti: aveva in casa 28 grammi di hashish. Il secondo \u00e8 S.G., 28 anni, di Carmiano: aveva in casa\u00a0sei dosi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49370,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49368"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=49368"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49368\/revisions"}],"predecessor-version":[{"id":49372,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49368\/revisions\/49372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/49370"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=49368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=49368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=49368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}