{"id":49660,"date":"2015-05-05T13:02:01","date_gmt":"2015-05-05T11:02:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=49660"},"modified":"2015-05-05T13:27:01","modified_gmt":"2015-05-05T11:27:01","slug":"preso-un-giovane-presunto-spacciatore-a-melpignano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/05\/preso-un-giovane-presunto-spacciatore-a-melpignano\/","title":{"rendered":"PRESO UN GIOVANE PRESUNTO SPACCIATORE DI HASHISH E MARIJUANA A MELPIGNANO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/FIORENTINO-FRANCESCO.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"234\" height=\"300\" title=\"FIORENTINO FRANCESCO\" class=\"alignright  wp-image-49661\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/FIORENTINO-FRANCESCO-234x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/FIORENTINO-FRANCESCO-234x300.jpg 234w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/FIORENTINO-FRANCESCO-799x1024.jpg 799w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/FIORENTINO-FRANCESCO.jpg 1371w\" sizes=\"(max-width: 234px) 100vw, 234px\" \/><\/a>(t.l.)______I Carabinieri di Martano hanno tratto in arresto per detenzione ai fini di spaccio di sostanze stupefacenti Francesco Fiorentino (nella foto), 22 anni, di Melpignano, celibe, operaio, gi\u00e0 noto alle forze dell\u2019ordine.<\/p>\n<p>I Carabinieri lo seguivano da tempo. Dopo essere entrati in casa del giovane, hanno iniziato una perquisizione locale che ha portato al rinvenimento di una intercapedine nascosta, accessibile attraverso una porticina ricavata nel bagno, dove c&#8217;era, opportunamente occultato, un involucro contenente gr 160 di hashish, un involucro contenente 210 grammi di marijuana, 305 euro in contanti, ritenuti provento dell\u2019attivit\u00e0 di spaccio, nonch\u00e9 tutto l\u2019occorrente per il confezionamento delle dosi, tra cui un bilancino, un tritaerba, un coltellino, buste di cellophane ed un barattolo di vetro.<\/p>\n<p>Il giovane, pertanto, \u00e8 stato tratto in arresto con l\u2019accusa di detenzione ai fini di spaccio di sostanze stupefacenti e, su disposizione del\u00a0pubblico ministero di turno, \u00e8 stato accompagnato presso la casa circondariale di\u00a0Lecce a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/05\/preso-un-giovane-presunto-spacciatore-a-melpignano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/05\/preso-un-giovane-presunto-spacciatore-a-melpignano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______I Carabinieri di Martano hanno tratto in arresto per detenzione ai fini di spaccio di sostanze stupefacenti Francesco Fiorentino (nella foto), 22 anni, di Melpignano, celibe, operaio, gi\u00e0 noto alle forze dell\u2019ordine. I Carabinieri lo seguivano da tempo. Dopo essere entrati in casa del giovane, hanno iniziato una perquisizione locale che ha portato al rinvenimento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49661,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49660"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=49660"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49660\/revisions"}],"predecessor-version":[{"id":49663,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/49660\/revisions\/49663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/49661"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=49660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=49660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=49660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}