{"id":4987,"date":"2012-10-23T16:31:01","date_gmt":"2012-10-23T16:31:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=4987"},"modified":"2012-10-23T16:31:03","modified_gmt":"2012-10-23T16:31:03","slug":"lautomobile-club-di-lecce-mette-in-pista-i-ragazzi-delle-scuole","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/23\/lautomobile-club-di-lecce-mette-in-pista-i-ragazzi-delle-scuole\/","title":{"rendered":"L&#8217;Automobile Club di Lecce  mette in pista i ragazzi delle scuole"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/23\/lautomobile-club-di-lecce-mette-in-pista-i-ragazzi-delle-scuole\/valentina-albanese\/\" rel=\"attachment wp-att-4988\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/Valentina-Albanese-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-4988\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/Valentina-Albanese-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/Valentina-Albanese-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/Valentina-Albanese.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Fa tappa domani a Lecce il tour 2012 del Sara Safe Factor, che per l\u2019ottavo anno consecutivo \u201cmette in pista\u201d i ragazzi all&#8217;ultimo anno delle scuole superiori per formarli e sollecitarli a una guida pi\u00f9 sicura e responsabile. L\u2019iniziativa scaturisce dall\u2019impegno statutario dell\u2019Automobile Club d\u2019Italia per la sicurezza stradale e schiera in prima linea Sara Assicurazioni \u2013 compagnia assicuratrice ufficiale dell\u2019ACI \u2013 insieme ad ACI Sport e Automobile Club di Lecce. Un progetto educativo e sociale la cui qualit\u00e0 traspare dal patrocinio del Dipartimento della Giovent\u00f9 e che quest&#8217;anno pu\u00f2 contare su due sponsor tecnici: SEAT, che mette a disposizione auto e piloti, e Michelin.\u2028La prova di guida sicura, che si terr\u00e0 in tarda mattinata nel piazzale antistante lo stadio di via del Mare in un circuito appositamente attrezzato, \u00e8 preceduta da una parte teorica in cui vengono illustrati semplici ma fondamentali accorgimenti, da come si impugna il volante e ci si siede correttamente, a come si esegue una efficace frenata di emergenza. Pilota istruttore sar\u00e0 Valentina Albanese, campione italiano CITE 2009 categoria Diesel e casco d&#8217;oro 2010 come miglior pilota donna. L&#8217;appuntamento \u00e8 dunque per mercoled\u00ec 24 ottobre alle 9 nell&#8217;auditorium dell&#8217;IT \u201cGrazia Deledda\u201d (piazza Palio), dove si ritroveranno circa 250 studenti dell&#8217;Istituto e di numerose altre scuole superiori di citt\u00e0 e provincia: i Licei classici \u201cPalmieri\u201d, \u201cVirgilio\u201d e \u201cPagano\u201d, il Liceo scientifico \u201cBanzi\u201d, l&#8217;ITC \u201cCosta\u201d, l&#8217;ITG \u201cGalilei\u201d, il Polo professionale \u201cScarambone\u201d, gli Istituti di istruzione superiore \u201cde Pace\u201d e \u201cRedi\u201d (inclusi il Liceo scientifico di Squinzano e l&#8217;ITC di Campi Salentina), l&#8217;Istituto professionale per i servizi commerciali \u201cIlaria Alpi\u201d di Carmiano.\u2028All&#8217;iniziativa, realizzata con il patrocinio di Provincia e Comune di Lecce e con la collaborazione degli Assessorati alla Mobilit\u00e0 e ai Trasporti competenti, insieme alla Polizia Municipale di Lecce, interverranno il direttore generale di ACI Sport, Marco Rogano, Marco Brachini, direttore marketing di Sara Assicurazioni e Aurelio Filippi, presidente AC Lecce, che illustreranno le finalit\u00e0 del progetto e i pi\u00f9 recenti dati ACI-Istat sui sinistri in Italia.\u2028Ma dove allenarsi a guidare in maniera sicura e corretta? Su Facebook, naturalmente. Sul popolare social network, infatti, alla pagina del Sara Safe Factor si pu\u00f2 giocare a \u201cSicuro sicuro\u201d, versione rinnovata e ancora pi\u00f9 coinvolgente di un concorso online che ha riscosso grande successo gli scorsi anni e che permetter\u00e0 di testare le proprie competenze al volante, oltre che di vincere 100 corsi di guida sicura al Centro ACI-Sara di Vallelunga, 100 tessere Aci Okkei e di partecipare all&#8217;estrazione di un&#8217;auto Seat Mii.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/23\/lautomobile-club-di-lecce-mette-in-pista-i-ragazzi-delle-scuole\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/23\/lautomobile-club-di-lecce-mette-in-pista-i-ragazzi-delle-scuole\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Fa tappa domani a Lecce il tour 2012 del Sara Safe Factor, che per l\u2019ottavo anno consecutivo \u201cmette in pista\u201d i ragazzi all&#8217;ultimo anno delle scuole superiori per formarli e sollecitarli a una guida pi\u00f9 sicura e responsabile. L\u2019iniziativa scaturisce dall\u2019impegno statutario dell\u2019Automobile Club d\u2019Italia per la sicurezza stradale e schiera in prima linea Sara [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4988,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4987"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=4987"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4987\/revisions"}],"predecessor-version":[{"id":4991,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4987\/revisions\/4991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/4988"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=4987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=4987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=4987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}