{"id":50166,"date":"2015-05-11T19:21:46","date_gmt":"2015-05-11T17:21:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=50166"},"modified":"2015-05-11T19:21:46","modified_gmt":"2015-05-11T17:21:46","slug":"le-idee-serge-latouche-ecco-perche-non-siamo-piu-felici","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/11\/le-idee-serge-latouche-ecco-perche-non-siamo-piu-felici\/","title":{"rendered":"LE IDEE \/ SERGE LATOUCHE, ECCO PERCHE&#8217; NON SIAMO PIU&#8217; FELICI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/Serge_Latouche.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"793\" title=\"Serge_Latouche\" class=\"alignleft size-full wp-image-50167\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/Serge_Latouche.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/Serge_Latouche.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/05\/Serge_Latouche-242x300.jpg 242w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>(Rdl)______Serge Latouche, francese, 75 anni, l &#8216;economista-filosofo teorico della decrescita felice e dell&#8217;abbondanza frugale &#8220;che serve a costruire una societ\u00e0 solidale, \u00e8 in Italia, per partecipare\u00a0al &#8216;Bergamo Festival&#8217; dedicato al tema &#8220;Fare la pace&#8221;.<\/p>\n<p>Ha consegnato ieri la &#8220;summa&#8221; del suo pensiero a\u00a0un&#8217; intervista a Giuliano Balestreri di &#8216;Repubblica&#8217;, di cui riproduciamo alcuni brevi passaggi, scelti fra i pi\u00f9 significativi, per il contemporaneo dibattito delle idee.<\/p>\n<p><em>&#8220;Stiamo facendo la guerra agli uomini. Anche un bambino capirebbe quello che politici ed economisti fingono di non vedere: una crescita infinita \u00e8 per definizione assurda in un pianeta finito, ma non lo capiremo finch\u00e9 non lo avremo distrutto. Per fare la pace dobbiamo abbandonarci all&#8217;abbondanza frugale, accontentarci. Dobbiamo imparare a ricostruire i rapporti sociali.\u00a0<\/em><\/p>\n<p><em>Un cambio rotta radicale. Sapersi accontentare.<\/em><\/p>\n<p><em>Il 40% del cibo prodotto va direttamente nella spazzatura: scade senza che nessuno lo comperi. La globalizzazione estremizza la concorrenza, perch\u00e9 superando i confini azzera i limiti imposti dalla stato sociale e diventa distruttiva. Sapersi accontentare \u00e8 una forma di ricchezza: non si tratta di rinunciare, ma semplicemente di non dare alla moneta pi\u00f9 dell&#8217;importanza che ha realmente.&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/11\/le-idee-serge-latouche-ecco-perche-non-siamo-piu-felici\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/05\/11\/le-idee-serge-latouche-ecco-perche-non-siamo-piu-felici\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Serge Latouche, francese, 75 anni, l &#8216;economista-filosofo teorico della decrescita felice e dell&#8217;abbondanza frugale &#8220;che serve a costruire una societ\u00e0 solidale, \u00e8 in Italia, per partecipare\u00a0al &#8216;Bergamo Festival&#8217; dedicato al tema &#8220;Fare la pace&#8221;. Ha consegnato ieri la &#8220;summa&#8221; del suo pensiero a\u00a0un&#8217; intervista a Giuliano Balestreri di &#8216;Repubblica&#8217;, di cui riproduciamo alcuni brevi passaggi, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":50167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/50166"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=50166"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/50166\/revisions"}],"predecessor-version":[{"id":50168,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/50166\/revisions\/50168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/50167"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=50166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=50166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=50166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}