{"id":5040,"date":"2012-10-24T10:44:01","date_gmt":"2012-10-24T10:44:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=5040"},"modified":"2012-10-24T10:46:27","modified_gmt":"2012-10-24T10:46:27","slug":"dal-giorno-8-novembre-e-fino-al-14-dicembre-invito-a-brindisi-a-vedere-speculum-animae","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/dal-giorno-8-novembre-e-fino-al-14-dicembre-invito-a-brindisi-a-vedere-speculum-animae\/","title":{"rendered":"DAL GIORNO 8 NOVEMBRE E FINO AL 14 DICEMBRE  INVITO A BRINDISI A VEDERE \u201cSPECULUM ANIMAE\u201d"},"content":{"rendered":"<p><strong>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-5040 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/P.-Guastamacchia-Logica-2007-olio-e-smalti-su-legno-cm-78x84.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/P.-Guastamacchia-Logica-2007-olio-e-smalti-su-legno-cm-78x84-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/P.-Guastamacchia-Anime-Vaganti-2008-olio-e-smalti-su-cartone-cm-78x84.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/10\/P.-Guastamacchia-Anime-Vaganti-2008-olio-e-smalti-su-cartone-cm-78x84-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mostra personale dell\u2019artista pugliese Pasquale Guastamacchia<\/strong><\/p>\n<p>____________________________________________<\/p>\n<p>Inaugurazione: gioved\u00ec 8 novembre 2012, ore 19.00<\/p>\n<p>Bastione san Giacomo, Brindisi, via Nazario Sauro, 1<\/p>\n<p>La mostra sar\u00e0 visitabile tutti i giorni (fino al 4 dicembre) dalle 17.30 alle 20.30.<\/p>\n<p>Luned\u00ec chiuso<\/p>\n<p>\u201cDotato bronzista con una solida formazione alle spalle \u2013 scrive il curatore della mostra Carmelo Cipriani \u2013 Guastamacchia \u00e8 innanzitutto scultore. In lui l\u2019attivit\u00e0 pittorica e quella plastica si susseguono senza soluzione di continuit\u00e0, facendo apparire la prima emancipata affiliazione della seconda. Dalla scultura il pittore desume compattezza delle forme e precisione del tratto, percepibile sia nelle linee taglienti che nelle lievi virgole che puntellano la superficie pittorica. Alla semplicit\u00e0 del segno corrisponde l\u2019essenzialit\u00e0 del colore, mai materico e sempre dominato.<\/p>\n<p>In pittura fugge dalla mimesi, pur adottandola nella scultura. Nella giustapposizione di ampie e regolari masse cromatiche vi \u00e8 un ordine strutturale superiore, genesi di un luogo pittorico trascendente, immateriale, in cui coesistono valori percettivi e stimolazioni interiori. Conquistata la profondit\u00e0 della superficie, all\u2019artista non interessano pi\u00f9 i corpi ma l\u2019infinit\u00e0 dello spazio e il limite dell\u2019orizzonte.<\/p>\n<p>Guastamacchia concepisce la superficie pittorica come una gigantesca pagina bianca su cui tracciare linee e forme minimali, sintetiche. Nelle sue composizioni, larghe campiture sono attraversate da segni rettilinei, generalmente neri, che solo di rado si chiudono in forme geometriche note. Autentici tagli grafici, quasi sempre affastellati lungo i margini, fino a determinare al centro del supporto il vuoto assoluto, recuperando il valore estetico e concettuale della mancanza e dell\u2019assenza. [\u2026].<\/p>\n<p>L\u2019alto discorso di Guastamacchia, pur scaturito da un travaglio solitario e orgoglioso, \u00e8 sereno, privo di implicazioni morali o polemiche politiche o sociali. Un percorso coerente, una cifra stilistica riconoscibile eppure sempre originale. Stesure cromatiche sature, vibranti nella resa pittorica, e andamenti lineari spigolosi, raramente curvilinei, connotano i suoi dipinti, serene visioni interiori, da cui trapela evidente lo sforzo di chi all\u2019arte della Natura ha preferito la natura dell\u2019Arte.\u201d.<\/p>\n<p>___________________________________<\/p>\n<p>PASQUALE GUASTAMACCHIA<\/p>\n<p>Nasce a Terlizzi (BA) nel 1949. Trasferitosi giovanissimo a Roma, frequenta la sezione scultura dell\u2019Accademia di Belle Arti, conoscendo artisti del calibro di Pericle Fazzini ed Emilio Greco. Nel 1973 si diploma con lode, seguendo gli insegnamenti di Venanzo Crocetti.<\/p>\n<p>Dedito sia all\u2019attivit\u00e0 plastica che pittorica, \u00e8 docente di discipline scultoree negli istituti d\u2019istruzione secondari. Mentre in scultura si dedica ad una plastica dinamica, generata da forme aperte, in pittura costituisce una cifra stilistica personale, approdando ad una figurazione concreta, pi\u00f9 ragionata che gestuale. Dal 1979 \u00e8 impegnato in un\u2019intensa attivit\u00e0 espositiva in Italia e all\u2019estero, raccogliendo consensi dal pubblico e riconoscimenti dalla critica. Ha partecipato e vinto concorsi nazionali indetti dallo Stato per opere pubbliche per le citt\u00e0 di Velletri, Frosinone, Viterbo, Lecce, Potenza.<\/p>\n<p>Si ricorda la sua partecipazione a Idea di Roma (Roma, 1985), Un mondo di giochi (Saint Vincent \u2013 Aosta, 1990), Senza Titolo. II Rassegna d\u2019arte contemporanea (Imperia, 1991), Second Fujisankei Biennial (Tokyo, 1995), Costellazioni (Terlizzi, 1996), Frammenti di Arte Sacra (Potenza, 2001).<\/p>\n<p>Significative le sue personali presso il Chiostro di San Cristoforo a Siena (1986), il Monastero di Santa Maria di Colonna a Trani (1990) e la Galleria \u201cLa Chimera\u201d di Roma (1998). Tre le personali alla Galleria \u201cTrifalco\u201d di Roma (1985, 1987, 1994). Le sue opere figurano in collezioni pubbliche e private.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/dal-giorno-8-novembre-e-fino-al-14-dicembre-invito-a-brindisi-a-vedere-speculum-animae\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/dal-giorno-8-novembre-e-fino-al-14-dicembre-invito-a-brindisi-a-vedere-speculum-animae\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Mostra personale dell\u2019artista pugliese Pasquale Guastamacchia ____________________________________________ Inaugurazione: gioved\u00ec 8 novembre 2012, ore 19.00 Bastione san Giacomo, Brindisi, via Nazario Sauro, 1 La mostra sar\u00e0 visitabile tutti i giorni (fino al 4 dicembre) dalle 17.30 alle 20.30. Luned\u00ec chiuso \u201cDotato bronzista con una solida formazione alle spalle \u2013 scrive il curatore della mostra Carmelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5041,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5040"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=5040"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5040\/revisions"}],"predecessor-version":[{"id":5044,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5040\/revisions\/5044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/5041"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=5040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=5040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=5040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}