{"id":5142,"date":"2012-10-26T08:48:44","date_gmt":"2012-10-26T08:48:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=5142"},"modified":"2012-11-15T17:13:01","modified_gmt":"2012-11-15T17:13:01","slug":"primarie-del-centro-destra-commenti-e-reazioni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/26\/primarie-del-centro-destra-commenti-e-reazioni\/","title":{"rendered":"PRIMARIE DEL CENTRO \u2013 DESTRA: commenti e reazioni"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>redazione di leccecronaca.it \u2013 Adriano Napoli \u2013 Roberto Tundo<\/strong><\/p>\n<p><strong>A poche ore dall\u2019annuncio fatidico, \u00e8 gi\u00e0 scattata la mobilitazione sul fronte del centro \u2013 destra.<\/strong><\/p>\n<p><strong>Abbiamo\u00a0 ragionato di politica insieme a voi l\u2019altro giorno:<\/strong><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/palermo-milano-sola-andata-passando-per-roma-e-pensando-a-lecce\/\"><strong>https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/palermo-milano-sola-andata-passando-per-roma-e-pensando-a-lecce\/<\/strong><\/a><strong><\/strong><\/p>\n<p><strong>e lo faremo nuovamente la prossima settimana, quando saranno resi noti i risultati delle elezioni regionali siciliane.<\/strong><\/p>\n<p><strong>Intanto, alla luce dell\u2019ultim\u2019ora, soltanto qualche\u00a0 appunto, in estrema sintesi e di prudenza: gi\u00e0 molte altre volte Silvio Berlusconi \u00e8 stato indicato come \u201cfinito\u201d; certo \u00e8 finito il suo sistema, il cos\u00ec detto \u201cberlusconismo\u201d, ma non lui; entrare in campo, come dice, o uscirne, \u00e8 la sua specialit\u00e0, e non ci stupiremmo che, ove i sondaggi, sempre i suoi fondamentali sondaggi, dessero il Pdl, adesso ai minimi storici, in risalita; se si creassero le condizioni per riportare tutti insieme Monti al potere\u00a0\u00a0 (horresco dicens, ma questo ha tentato di organizzare, prima di annunciare il suo presunto addio; se dalle primarie del pdl, ammesso che si facciano in maniera seria, uscisse un quadro frammentato; o se si volesse divertire con una sua lista elettorale ad personam; ecco, se si verificasse anche solo una di queste varianti, non ci stupiremmo che si rispedisse in campo, tornando ad abbeverarsi all\u2019amaro calice\u2026<\/strong><\/p>\n<p><strong>Con un sorriso, la finiamo qui al momento, con la politica, da parte nostra, e diamo spazio alle reazioni che, senza sollecitare, abbiamo ricevuto e quindi volentieri pubblichiamo, in ordine di arrivo, come continueremo a fare, se ne arriveranno altre, anche con i semplici commenti direttamente on line, purch\u00e9, per quanto gli animi siano esacerbati e l\u2019argomento esplosivo, espongano le proprie tesi senza volgarit\u00e0 e senza offendere nessuno.<\/strong><\/p>\n<p><strong>_______________________________________________________________________________________<\/strong><\/p>\n<p><strong>Ci scrive il coordinatore regionale dei circoli \u201cDestra di base\u201d Adriano Napoli<\/strong><\/p>\n<p><strong><em>LE PRIMARIE DEL CENTRODESTRA: inutili e tardive.<\/em><\/strong><\/p>\n<p><strong><em>Destra di Base si smarca da ogni vincolo politico ed elettorale col Pdl.<\/em><\/strong><\/p>\n<p>Ormai \u00e8 tardi per fare primarie del centrodestra, a qualsiasi livello.<\/p>\n<p>Il danno \u00e8 stato fatto ed \u00e8 irrecuperabile. L&#8217;unica cosa da fare \u00e8 azzerare<\/p>\n<p>tutto e ripartire da zero, senza trucchi e senza inganni, stavolta.<\/p>\n<p>Il Pdl a tutti i livelli non rappresenta pi\u00f9 il centrodestra, tutt&#8217;altro, bens\u00ec opportunismo e affarismo senza limiti e senza vergogna.<\/p>\n<p>Pochissimi sono quelli che si salvano, troppo pochi, a tutti i livelli.<\/p>\n<p>Chi credeva nella politica valoriale e nella partecipazione, cio\u00e8 quelli<\/p>\n<p>che fanno politica in buona fede, come servizio civile, sono gi\u00e0 usciti da un<\/p>\n<p>pezzo dal Pdl e da questo falso centrodestra.<\/p>\n<p>O sono stati epurati o sono stati messi in condizione di andarsene perch\u00e9<\/p>\n<p>costantemente ignorati e prevaricati da una gestione esageratamente<\/p>\n<p>personalistica, che a partire da Berlusconi si \u00e8 infine riverberata in ogni<\/p>\n<p>ambito.<\/p>\n<p>Creando ingiustizie, malumori, scontento e disaffezione per una politica<\/p>\n<p>non pi\u00f9 ideologica. E questa decadenza culturale del partito berlusconiano e<\/p>\n<p>del centrodestra non ha certo risparmiato la Puglia, e tantomeno la provincia<\/p>\n<p>di Lecce, tutt&#8217;altro.<\/p>\n<p>Fare quindi le primarie con i candidati scelti o votati da questo sistema<\/p>\n<p>di partito, ancora oggi, cos\u00ec impostato e cos\u00ec gestito, \u00e8 una grossolana e<\/p>\n<p>totale presa in giro.<\/p>\n<p>Cos\u00ec come a livello nazionale vincerebbe a mani basse Alfano, a livello<\/p>\n<p>regionale o provinciale vincerebbe a mani basse un candidato qualsiasi<\/p>\n<p>designato dall&#8217;on. Fitto.<\/p>\n<p>Quindi Destra di Base ritiene che \u00e8 ormai giunto il momento di svincolarsi<\/p>\n<p>completamente e definitivamente da ogni legame politico ed elettorale con<\/p>\n<p>un centro destra che \u00e8 tale ormai solo a parole.<\/p>\n<p>E non basta la presenza dell&#8217;on. Mantovano a cambiare la situazione ormai<\/p>\n<p>irreversibilmente compromessa. Anche perch\u00e9 il nostro ex sottosegretario \u00e8<\/p>\n<p>il solo rappresentante nazionale, ma anche del suo stesso gruppo, che pratichi<\/p>\n<p>sul nostro territorio una politica decorosa e disinteressata.<\/p>\n<p>Destra di Base a novembre ufficializzer\u00e0 la costituzione di un movimento<\/p>\n<p>politico elettorale, per ora di dimensioni regionali, che non sar\u00e0 organico<\/p>\n<p>n\u00e9 al centrodestra e n\u00e9 al centrosinistra. Non avr\u00e0 vincoli elettorali di<\/p>\n<p>alcun tipo, ma solo il compito di rappresentare la buona politica, quella fatta<\/p>\n<p>di impegno sincero e spirito di servizio per il proprio territorio. E&#8217; un<\/p>\n<p>progetto a cui si sta lavorando da mesi assieme ad altri gruppi e movimenti politici<\/p>\n<p>locali e che gi\u00e0 a partire dalle prossime consultazioni elettorali sar\u00e0<\/p>\n<p>presente e attivo, in assoluta autonomia. Anche se vi sono da tempo<\/p>\n<p>contatti interessanti e proficui con altre realt\u00e0 politico-elettorali gi\u00e0 presenti<\/p>\n<p>nelle istituzioni locali e nazionali.<\/p>\n<p>____________________________________________________________________<\/p>\n<p><strong>Ci scrive il dirigente provinciale del Pdl Roberto Tundo<\/strong><\/p>\n<p><strong><em>Finalmente!<\/em><\/strong><\/p>\n<p>Dopo tanti tatticismi, finalmente Berlusconi \u2013 a cui riconosciamo anche le grandi doti proprie di un leader politico- si \u00e8 deciso. Non si ricandider\u00e0 a premier in nome del Popolo della Libert\u00e0 e ha anche fissato la data del 16 dicembre per le primarie. Ancora una volta ha deciso a modo suo, \u201cscavalcando\u201d il partito che lui stesso ha voluto creare: l\u2019importante, per\u00f2, \u00e8 che il \u201cvia libera\u201d sia stato dato.<\/p>\n<p>Erano mesi, ormai, che il PdL era paralizzato per scelte che non venivano effettuate. L\u2019attendismo ha solo provocato l\u2019allontanamento di tanti delusi da quello che un tempo era stato il partito \u201cdel fare\u201d.<\/p>\n<p>Certo, non di sole primarie ha bisogno il pi\u00f9 grande partito del centrodestra italiano, si deve tornare a guardare la realt\u00e0 con quello spirito critico, con quella volont\u00e0 \u201calternativa\u201d, con quella capacit\u00e0 creativa che sono state alle origini delle scelte politiche che hanno segnato intere generazioni.<\/p>\n<p>Intanto, da oggi, il PdL torna in \u2026 movimento.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/26\/primarie-del-centro-destra-commenti-e-reazioni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/26\/primarie-del-centro-destra-commenti-e-reazioni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; redazione di leccecronaca.it \u2013 Adriano Napoli \u2013 Roberto Tundo A poche ore dall\u2019annuncio fatidico, \u00e8 gi\u00e0 scattata la mobilitazione sul fronte del centro \u2013 destra. Abbiamo\u00a0 ragionato di politica insieme a voi l\u2019altro giorno: https:\/\/www.leccecronaca.it\/index.php\/2012\/10\/24\/palermo-milano-sola-andata-passando-per-roma-e-pensando-a-lecce\/ e lo faremo nuovamente la prossima settimana, quando saranno resi noti i risultati delle elezioni regionali siciliane. Intanto, alla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5142"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=5142"}],"version-history":[{"count":8,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5142\/revisions"}],"predecessor-version":[{"id":6458,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5142\/revisions\/6458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/1551"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=5142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=5142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=5142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}