{"id":5681,"date":"2012-11-06T18:54:08","date_gmt":"2012-11-06T18:54:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=5681"},"modified":"2012-11-06T18:54:11","modified_gmt":"2012-11-06T18:54:11","slug":"consulenze-notarili-gratuite-per-i-cittadini","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/06\/consulenze-notarili-gratuite-per-i-cittadini\/","title":{"rendered":"CONSULENZE NOTARILI GRATUITE PER I CITTADINI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/06\/consulenze-notarili-gratuite-per-i-cittadini\/notai2\/\" rel=\"attachment wp-att-5682\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/notai2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-5682\" \/><\/a><\/p>\n<p>Il Comune di Lecce rende noto (nella foto, un momento della conferenza \u2013 stampa odierna) che a partire da mercoled\u00ec 14 novembre e, con cadenza quindicinale &#8211; nella\u00a0 sala polifunzionale Open Space \u201dLecce Giovani\u201d &#8211;\u00a0 riprender\u00e0 il servizio \u201cChiedilo al Notaio\u201d per consulenze personalizzate e gratuite finalizzate a fornire informazioni di massima su materie che rientrano nella sfera delle competenze notarili.<\/p>\n<p>Dal 2011 sono stati numerosi i cittadini che si sono rivolti al servizio potendo cos\u00ec conoscere meglio questioni giuridiche e tributarie in materia di acquisto abitazioni, tassazione relativa all&#8217;acquisto prima casa, compravendita e problemi connessi all&#8217;urbanistica, compravendite immobiliari, detrazioni fiscali per manutenzioni, finanziamento mutui, rinegoziazione dei mutui, ipoteche, regimi patrimoniali dei coniugi, successioni, testamenti e relative imposte, diritti reali di godimento (es. usufrutto).<\/p>\n<p>L&#8217;iniziativa \u00e8 rivolta in particolare ai giovani ed agli anziani della cittadinanza, i quali &#8211; trovandosi nella necessit\u00e0 di consultare un professionista del diritto su queste materie &#8211; non sempre hanno la disponibilit\u00e0 per richiedere un parere qualificato nel momento in cui devono prendere comunque decisioni importanti, quali redigere un valido testamento, acquistare una casa, trasmettere beni ai figli o contrarre un mutuo. Per questo motivo, i notai del Consiglio Notarile di Lecce hanno deciso di mettere a disposizione\u00a0 la loro esperienza e la loro cultura giuridica. Sar\u00e0 anche l&#8217;occasione per un incontro ravvicinato e informale degli esponenti del Notariato con i cittadini per sensibilizzare la collettivit\u00e0 ad avvalersi della consulenza del notaio.<\/p>\n<p>Inoltre, venerd\u00ec 9 novembre, alle ore 18, sulla base del Protocollo d\u2019intesa stilato tra Comune di Lecce e Consiglio Notarile, partir\u00e0 un ciclo di Seminari Informativi grazie ai quali verr\u00e0 illustrato il contenuto di alcune guide edite dal Consiglio Nazionale, su tematiche di particolare interesse per il cittadino.<\/p>\n<p>\u201cLe guide \u2013 fa sapere Andrea Tavassi, segretario del Consiglio Notarile di Lecce \u2013 contengono informazioni chiare e semplici utili per orientarsi negli aspetti tecnici relativi a diverse questioni\u201d.<\/p>\n<p>Il primo argomento trattato \u00e8 riferito alle \u201cDonazioni consapevoli\u201d. Per disporre dei propri beni in sicurezza.<\/p>\n<p>Un riferimento concreto per i cittadini che &#8211; per riconoscenza, affetto, beneficenza o altro &#8211; scelgono la donazione per trasferire un proprio bene senza pretendere nulla in cambio. \u00c8 allora necessario conoscerne ogni aspetto:<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 i soggetti che possono donare e ricevere<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 la forma idonea affinch\u00e9 il contratto di donazione sia valido<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 la commerciabilit\u00e0 dei beni<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 le disposizioni fiscali<\/p>\n<p>Gli incontri rappresentano un momento di confronto aperto a tutta la cittadinanza, una significativa iniziativa a valenza sociale che consente di accostarsi, seppur marginalmente e, comunque in modo preventivo, a materie ritenute ostiche e da lasciare &#8211;\u00a0 come \u00e8, peraltro, sempre consigliabile &#8211; in mano agli addetti ai lavori ma, che \u00e8 necessario conoscere per potersi \u201cmuovere\u201d nella sempre pi\u00f9 complessa societ\u00e0 odierna.<\/p>\n<p>Per\u00a0\u00a0 ulteriori\u00a0\u00a0 informazioni\u00a0\u00a0 ed\u00a0\u00a0 eventuali\u00a0\u00a0 prenotazioni\u00a0\u00a0\u00a0 telefonare\u00a0\u00a0 al\u00a0\u00a0 numero verde 800 215259\u00a0 o recarsi personalmente al front-office\u00a0 \u201cLecce giovani\u201d , all\u2019Urp ubicato al piano terra di Palazzo Carafa, oppure scaricare il modulo di prenotazione dal sito internet del Comune (www.comune.lecce.it)\u00a0 ed inviarlo via e-mail a: politichegiovanili@comune.lecce.it o via fax al n. 0832 682364. Il personale addetto provveder\u00e0 a fissare un appuntamento per far incontrare il cittadino con il notaio.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/06\/consulenze-notarili-gratuite-per-i-cittadini\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/06\/consulenze-notarili-gratuite-per-i-cittadini\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il Comune di Lecce rende noto (nella foto, un momento della conferenza \u2013 stampa odierna) che a partire da mercoled\u00ec 14 novembre e, con cadenza quindicinale &#8211; nella\u00a0 sala polifunzionale Open Space \u201dLecce Giovani\u201d &#8211;\u00a0 riprender\u00e0 il servizio \u201cChiedilo al Notaio\u201d per consulenze personalizzate e gratuite finalizzate a fornire informazioni di massima su materie che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5681"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=5681"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5681\/revisions"}],"predecessor-version":[{"id":5685,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/5681\/revisions\/5685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/5682"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=5681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=5681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=5681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}