{"id":57397,"date":"2015-08-08T15:57:16","date_gmt":"2015-08-08T13:57:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=57397"},"modified":"2015-08-08T15:57:16","modified_gmt":"2015-08-08T13:57:16","slug":"una-paziente-impaziente-perseguita-l-infermiera-che-la-cura-al-vito-fazzi-denunciata-per-stalking","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/08\/08\/una-paziente-impaziente-perseguita-l-infermiera-che-la-cura-al-vito-fazzi-denunciata-per-stalking\/","title":{"rendered":"UNA PAZIENTE IMPAZIENTE PERSEGUITA L&#8217; INFERMIERA CHE LA CURA AL &#8216;VITO FAZZI&#8217;: DENUNCIATA PER STALKING"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"224\" title=\"ospedale-vito-fazzi-lecce\" class=\"alignleft size-medium wp-image-57398\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/08\/ospedale-vito-fazzi-lecce-300x224.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/08\/ospedale-vito-fazzi-lecce-300x224.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/08\/ospedale-vito-fazzi-lecce.jpg 448w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(t.l.)______Una paziente in cura presso l&#8217; ospedale &#8220;Vito Fazzi&#8221; di Lecce (nella foto)\u00a0\u00e8 stata denunciata per stalking, cio\u00e8 persecuzioni continuate, nei confronti di una infermiera professionale, dagli agenti della polizia di stato, intervenuti dopo l&#8217; ennesimo episodio di offese, insulti e minacce, che si protraevano da mesi.<\/p>\n<p>La donna, infatti, si reca ciclicamente presso il nosocomio leccese, per sottoporsi a terapie specifiche. Qui aveva avuto un diverbio per banali motivi con l&#8217; infermiera, che non aveva soddisfatto alcune sue richieste, perch\u00e9 contrarie alle prescrizioni mediche.<\/p>\n<p>Da allora aveva cominciato con aggressioni verbali, insulti e dispetti di ogni tipo, che, a lungo andare, avevano costretta l&#8217; infermniera, per evitarla, a chiedere cambi di turno e spostamenti di reparto.<\/p>\n<p>Tutto inutile.<\/p>\n<p>La paziente ha cercato di raggiungerla al piano superiore, dove si trovava a lavorare,\u00a0per aggredirla. L&#8217; intervento del personale medico ha evitato il peggio, ma l&#8217; infermiera per lo choc ha avuto un malore, con un\u00a0referto medico di sette giorni di prognosi.<\/p>\n<p>Da qui, come\u00a0 detto, l&#8217; intervento dei poliziotti e l denuncia a carico della paziente.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/08\/08\/una-paziente-impaziente-perseguita-l-infermiera-che-la-cura-al-vito-fazzi-denunciata-per-stalking\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/08\/08\/una-paziente-impaziente-perseguita-l-infermiera-che-la-cura-al-vito-fazzi-denunciata-per-stalking\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Una paziente in cura presso l&#8217; ospedale &#8220;Vito Fazzi&#8221; di Lecce (nella foto)\u00a0\u00e8 stata denunciata per stalking, cio\u00e8 persecuzioni continuate, nei confronti di una infermiera professionale, dagli agenti della polizia di stato, intervenuti dopo l&#8217; ennesimo episodio di offese, insulti e minacce, che si protraevano da mesi. La donna, infatti, si reca ciclicamente presso il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":57398,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/57397"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=57397"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/57397\/revisions"}],"predecessor-version":[{"id":57400,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/57397\/revisions\/57400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/57398"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=57397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=57397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=57397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}