{"id":59586,"date":"2015-09-06T23:00:06","date_gmt":"2015-09-06T21:00:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=59586"},"modified":"2015-09-07T17:22:20","modified_gmt":"2015-09-07T15:22:20","slug":"oltre-diecimila-spettatori-al-via-del-mare-ma-il-lecce-stecca-la-prima-di-campionato-contro-landria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/09\/06\/oltre-diecimila-spettatori-al-via-del-mare-ma-il-lecce-stecca-la-prima-di-campionato-contro-landria\/","title":{"rendered":"OLTRE DIECIMILA SPETTATORI AL VIA DEL MARE, MA IL LECCE &#8220;STECCA&#8221; LA PRIMA DI CAMPIONATO CONTRO L&#8217;ANDRIA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/09\/FullSizeRender-7-300x225.jpg\" alt=\"\" title=\"FullSizeRender (7)\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-59605\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/09\/FullSizeRender-7-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/09\/FullSizeRender-7-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/09\/FullSizeRender-7.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>di <strong>Laura Ricci<\/strong>____<\/p>\n<p>&#8220;Stecca&#8221; alla prima giornata di Lega Pro 2015\/16 il nuovo Lecce targato Asta, che davanti alla &#8220;bolgia&#8221; del Via del Mare che ha ospitato circa diecimilaseicento spettatori non \u00e8 riuscito a trovare la vittoria a cui tutti i tifosi speravano di assistere.<\/p>\n<p>Il match contro la Fidelis Andria finisce con la sonora sconfitta per tre a uno.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>TABELLINI<\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">LECCE<\/span><\/strong> allenatore Asta; 4-3-1-2: Benassi, Lo Bue, Liviero, Gigli, Camisa, Papini, Pessina, Suciu, Surraco,\u00a0 Moscardelli, Curiale.<\/p>\n<p><strong><span style=\"text-decoration: underline;\">FIDELIS ANDRIA<\/span><\/strong> allenatore D&#8217;Angelo; 4-3-1-2: Poluzzi, Cortellini, Stendardo, Bisoli, Tartaglia, Fissore, Grandolfo, Morra, Strambelli, Onescu, Piccinni.<\/p>\n<p><strong><span style=\"text-decoration: underline;\">ARBITRO<\/span><\/strong> Carmine di Ruberto della sezione di Nocera Inferiore, accompagnato dagli assistenti di gara Abbrescia e Abagnara.<\/p>\n<p>Partenza &#8220;lampo&#8221; per la squadra ospite che subito si propone in avanti relegando il Lecce nella propria met\u00e0 campo; al 5&#8242; un cross dall&#8217;out di sinistra attraversa tutta l&#8217;area di rigore giallorossa, arrivando tra i piedi di Onescu che insacca il pallone superando i guantoni di Benassi, sorpreso dal tiro ravvicinato.<\/p>\n<p>Si sveglia la squadra di Asta che inizia a macinare gioco e a creare azioni da goal: al 12&#8242; Curiale sfiora nella mischia la zampata vincente, ma Poluzzi devia miracolosamente il pallone e tiene in vantaggio i suoi. Al 19&#8242; torna alla carica la Fidelis Andria che sfiora il clamoroso raddoppio con una deviazione di Morra che spiazza completamente Benassi, ma non centra la porta. La seconda rete per\u00f2 non tarda ad arrivare: al 25&#8242; Strambelli pesca Grandolfo, lasciato tutto solo dalla difesa leccese che si addormenta permettendo all&#8217;attaccante dell&#8217;Andria di spiazzare ancora una volta il portiere salentino che non riesce, ancora, a trovare le misure.<\/p>\n<p>Il Lecce, travolto dal risultato avverso, ma sempre sostenuto dal proprio pubblico, cerca la luce nel buio profondo con un notevole gesto atletico da parte di Moscardelli che, dalla fascia esterna, tenta il tiro al volo sfiorando il palo esterno. Pochi minuti dopo \u00e8 Surraco a provarci con tiro potente ma troppo centrale che viene perci\u00f2 respinto dall&#8217;impeccabile portiere dell&#8217;Andria.<\/p>\n<p>All&#8217;inizio della seconda frazione di gioco mister Asta decide di richiamare in panchina Suciu, che sulla fascia di centrocampo non convince e lascia il posto ad Alessandro Carrozza. Il Lecce entra con la voglia di recuperare dallo svantaggio e spinge in avanti, cercando di trovare il goal al 46&#8242; con un tiro di Gigli che su calcio d&#8217;angolo non riesce a spiazzare Poluzzi.<\/p>\n<p>Al 50&#8242; viene sfumata una potenziale azione del Lecce grazie all&#8217;intervento della difesa dell&#8217;Andria che ferma sul nascere il tentativo di Curiale di servire Moscardelli, smarcatosi nell&#8217;area piccola avversaria. Pochi minuti dopo, Moscardelli impegna seriamente il portiere della squadra ospite con un altro tiro dalla distanza; il bomber giallorosso non demorde ed \u00e8 al 62&#8242; che trova la rete, dimezzando lo svantaggio e riportando fiducia tra i suoi.<\/p>\n<p>Sulle ali dell&#8217;entusiasmo gli uomini di Asta cercano disperatamente il goal del pareggio ed \u00e8 proprio Moscardelli a ritrovarselo tra i piedi nuovamente, ma fallendo questa volta una rete praticamente gi\u00e0 fatta, a tu per tu con Poluzzi. Si infiamma il pubblico del Via del Mare che spinge i propri giocatori a continuare a lottare; i salentini all&#8217; 80&#8242; mettono alle strette l&#8217; Andria che riesce per\u00f2 ad arginare le fiammate degli avversari.<\/p>\n<p>Quattro minuti di recupero per le speranze del Lecce si tramutano invece nell&#8217;affondo definitivo della nave giallorossa: allo scadere del tempo i biancoblu conquistano un calcio di rigore che chiude i conti con la rete conclusiva di Nicola Strambelli, autore di una doppietta personale.<\/p>\n<p><strong>DA RICORDARE<\/strong><\/p>\n<p>Il pienone al Via del Mare, coronato dalla presenza di oltre diecimila spettatori, \u00e8 qualcosa che mancava da tanto, troppo tempo. Dopo la risposta positiva alla campagna abbonamenti da parte di circa seimilaseicento tifosi, anche le famiglie e gli appassionati del calcio salentino sono tornati a riempire i gradoni dello stadio. Merito della nuova societ\u00e0, che \u00e8 riuscita a infondere fiducia ed entusiasmo a questa piazza che ha bisogno di essere scaldata per tornare ardente.<\/p>\n<p><strong>DA DIMENTICARE<\/strong><\/p>\n<p>Esordio decisamente deludente viste le aspettative di tutti; mister Asta aveva avvertito: <em>&#8220;non ci sar\u00e0 un inizio scoppiettante&#8221;<\/em>. Il gruppo giallorosso ha bisogno di tempo per riuscire a trovare la giusta sintonia, per potersi conoscere e rendere come potrebbe. Il rischio di una campagna acquisti cos\u00ec &#8220;radicale&#8221;, fondata sul rivoluzionare completamente gli interpreti in campo, era questo, e si sapeva. La &#8220;cenerentola&#8221; Andria ottiene una netta vittoria contro una delle squadre favorite per la promozione e con il potenziale tecnico pi\u00f9 alto del girone; sulla carta, per\u00f2, non si vince.<\/p>\n<p>La strada \u00e8 ancora lunga, l&#8217;importante \u00e8 non perdersi.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/09\/06\/oltre-diecimila-spettatori-al-via-del-mare-ma-il-lecce-stecca-la-prima-di-campionato-contro-landria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/09\/06\/oltre-diecimila-spettatori-al-via-del-mare-ma-il-lecce-stecca-la-prima-di-campionato-contro-landria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Laura Ricci____ &#8220;Stecca&#8221; alla prima giornata di Lega Pro 2015\/16 il nuovo Lecce targato Asta, che davanti alla &#8220;bolgia&#8221; del Via del Mare che ha ospitato circa diecimilaseicento spettatori non \u00e8 riuscito a trovare la vittoria a cui tutti i tifosi speravano di assistere. Il match contro la Fidelis Andria finisce con la sonora [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/59586"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=59586"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/59586\/revisions"}],"predecessor-version":[{"id":59732,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/59586\/revisions\/59732"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=59586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=59586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=59586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}