{"id":61384,"date":"2015-10-10T17:46:45","date_gmt":"2015-10-10T15:46:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=61384"},"modified":"2015-10-10T19:58:37","modified_gmt":"2015-10-10T17:58:37","slug":"nubifragio-nel-salento-crolla-stazione-eni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/nubifragio-nel-salento-crolla-stazione-eni\/","title":{"rendered":"NUBIFRAGIO NEL SALENTO: CROLLA STAZIONE DI SERVIZIO, FULMINE SU UN RISTORANTE, MELENDUGNO SOMMERSA DALL&#8217; ACQUA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/85dadbb42a28c967d40639dc3caa5177.jpg\" alt=\"\" title=\"La stazione di servizio scoperchiata da una tromba d'aria nel Salento\" width=\"457\" height=\"343\" class=\"alignleft size-full wp-image-61385\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/85dadbb42a28c967d40639dc3caa5177.jpg 457w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/85dadbb42a28c967d40639dc3caa5177-300x225.jpg 300w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/>di <strong>Emanuele Lezzi<\/strong>______<\/p>\n<p>Come preannunciato dalle previsioni meteo, che questa volta non hanno fallito, il maltempo \u00e8 arrivato anche nel Salento. Da questa mattina il nostro servizio sulla home page di leccecronaca.it dava segni grafici inequivocabili della tempesta in arrivo. Infatti da dopo mezzogiorno un violentissimo nubifragio si \u00e8 abbattuto sul Salento.<\/p>\n<p>In molte localit\u00e0 si sono registrati danni e disagi di vario genere e tanta paura, senza che per\u00f2 al momento si registrino gravi danni o feriti.<\/p>\n<p>Il caso che ha destato pi\u00f9 preoccupazione \u00e8 stato il crollo della tettoia di una stazione di servizio ENI sulla Maglie-Lecce, subito dopo l&#8217;uscita per Melpignano (nella foto), che \u00e8 stata completamente divelta e scaraventata a terra,\u00a0distruggendo le colonnine di sotto.<\/p>\n<p>Paura anche ad Alliste, dove nella marina di Capilungo un fulmine a colpito un chiosco sul lungomare Cristoforo Colombo causando un incendio che si \u00e8 propagato\u00a0fino a lambire due bombole di gas presenti all&#8217;interno del locale; l&#8217;intervento dei vigili del fuoco ha evitato il peggio.<\/p>\n<p>Le altre zone pi\u00f9 colpite dal maltempo risultano sono quelle intorno a Gallipoli e quelle ancora pi\u00f9 a sud sulla costa ionica.<\/p>\n<p>Disagi a Lecce citt\u00e0 e in un po&#8217; tutti\u00a0i centri abitati, oltre che\u00a0su tutte le strade della provincia. In particolare si segnalano grossi allagamenti nelle vie di Melendugno (nella foto).<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/nubifragio-nel-salento-crolla-stazione-eni\/schermata-2015-10-10-a-18-29-13\/\" rel=\"attachment wp-att-61395\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/Schermata-2015-10-10-a-18.29.13.jpg\" title=\"Schermata 2015-10-10 a 18.29.13\" width=\"455\" height=\"241\" class=\"alignnone  wp-image-61395\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/Schermata-2015-10-10-a-18.29.13.jpg 929w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/Schermata-2015-10-10-a-18.29.13-300x158.jpg 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/nubifragio-nel-salento-crolla-stazione-eni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/nubifragio-nel-salento-crolla-stazione-eni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Emanuele Lezzi______ Come preannunciato dalle previsioni meteo, che questa volta non hanno fallito, il maltempo \u00e8 arrivato anche nel Salento. Da questa mattina il nostro servizio sulla home page di leccecronaca.it dava segni grafici inequivocabili della tempesta in arrivo. Infatti da dopo mezzogiorno un violentissimo nubifragio si \u00e8 abbattuto sul Salento. In molte localit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61395,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61384"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=61384"}],"version-history":[{"count":15,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61384\/revisions"}],"predecessor-version":[{"id":61413,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61384\/revisions\/61413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/61395"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=61384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=61384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=61384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}