{"id":61390,"date":"2015-10-10T18:20:12","date_gmt":"2015-10-10T16:20:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=61390"},"modified":"2015-10-10T18:57:01","modified_gmt":"2015-10-10T16:57:01","slug":"dimesso-ieri-in-codice-verde-ritrovato-morto-oggi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/dimesso-ieri-in-codice-verde-ritrovato-morto-oggi\/","title":{"rendered":"DIMESSO IERI IN CODICE VERDE, RITROVATO MORTO OGGI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/prontosoccorso.jpg\" alt=\"\" title=\"prontosoccorso\" width=\"288\" height=\"175\" class=\"alignleft size-full wp-image-61391\" \/>(e.l.)______<\/p>\n<p><span style=\"font-size: 13px;\">&#8220;<em>Vada a casa, con l&#8217;antidolorifico che le abbiamo somministrato passer\u00e0 tutto<\/em>&#8220;. Ma la mattina dopo essere stato dimesso dal pronto soccorso, viene ritrovato morto.<\/span><\/p>\n<p><span style=\"font-size: 13px;\">E&#8217; accaduto oggi a Novoli, dove ha cos\u00ec perso la vita<\/span><span style=\"font-size: 13px;\">\u00a0un giovane di 25 anni,\u00a0Emanuele Levante, che ieri sera si era recato al Pronto soccorso dell&#8217;ospedale Vito Fazzi di Lecce per un dolore ad una gamba che durava da tre giorni. Il medico di turno ha valutato di visitarlo in &#8220;codice verde&#8221;, gli ha somministrato un antidolorifico e lo ha dimesso. Non sappiamo ancora se la cosa \u00e8 direttamente collegata (questo lo accerter\u00e0 quasi certamente l&#8217;autopsia), fatto sta che questa mattina ha fatto colazione ed \u00e8 tornato a dormire, per essere poi ritrovato senza vita dal padre poco dopo. La procura della Repubblica ha aperto un&#8217; inchiesta.<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/dimesso-ieri-in-codice-verde-ritrovato-morto-oggi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/10\/dimesso-ieri-in-codice-verde-ritrovato-morto-oggi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______ &#8220;Vada a casa, con l&#8217;antidolorifico che le abbiamo somministrato passer\u00e0 tutto&#8220;. Ma la mattina dopo essere stato dimesso dal pronto soccorso, viene ritrovato morto. E&#8217; accaduto oggi a Novoli, dove ha cos\u00ec perso la vita\u00a0un giovane di 25 anni,\u00a0Emanuele Levante, che ieri sera si era recato al Pronto soccorso dell&#8217;ospedale Vito Fazzi di Lecce [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61391,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61390"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=61390"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61390\/revisions"}],"predecessor-version":[{"id":61409,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/61390\/revisions\/61409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/61391"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=61390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=61390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=61390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}