{"id":62645,"date":"2015-10-29T07:01:46","date_gmt":"2015-10-29T06:01:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=62645"},"modified":"2015-10-29T15:05:56","modified_gmt":"2015-10-29T14:05:56","slug":"diario-del-giorno-dopo-iniziative-spettacolo-per-mario-toma-a-lecce-venerdi-30","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/29\/diario-del-giorno-dopo-iniziative-spettacolo-per-mario-toma-a-lecce-venerdi-30\/","title":{"rendered":"DIARIO DEL GIORNO DOPO \/ INIZIATIVE \/ SPETTACOLO PER ANTONIO A LECCE VENERDI&#8217; 30"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"249\" height=\"300\" title=\"479761_107081372792059_2033419942_n\" class=\"alignright size-medium wp-image-62647\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/479761_107081372792059_2033419942_n-249x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/479761_107081372792059_2033419942_n-249x300.jpg 249w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/10\/479761_107081372792059_2033419942_n.jpg 742w\" sizes=\"(max-width: 249px) 100vw, 249px\" \/>Venerd\u00ec 30 ottobre, alle 21,\u00a0a Lecce, al teatro Paisiello, va in scena lo spettacolo \u201cAntonio e Marianne: Il suono rivoluzionario nella citt\u00e0 che dorme\u201d. Si tratta di un omaggio ad Antonio\u00a0Toma, imprenditore edile morto anni fa che,\u00a0insieme alla pittrice olandese Marianne Clous, &#8220;fece della loro casa di via Regina Elena il punto d&#8217;incontro degli intellettuali leccesi, dei musicisti, dei poeti, dei letterati, dei filosofi, dei pensatori&#8221;.<\/p>\n<p>Alla presenza della figlia, Barbara Toma, ballerina e coreografa, la serata si articoler\u00e0 con le esibizioni di Mino Toriano, Elio Giordano (nella foto), Roberto Gagliardi, Roberto Vantaggiato, Mauro Tre, Cesare dell&#8217;Anna, Tobia Lamare, Anima Lunae trio; le immagini video saranno curate da Fernando Bevilacqua e Paolo Pisanelli; i testi, da Astr\u00e0gali Teatro, tratti\u00a0dai carteggi di Antonio Toma con Antonio Verri a Bruno Brancher e le testimonianze di Massimo Melillo e Pietro Fumarola.<\/p>\n<p>Ingresso gratuito.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/29\/diario-del-giorno-dopo-iniziative-spettacolo-per-mario-toma-a-lecce-venerdi-30\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/10\/29\/diario-del-giorno-dopo-iniziative-spettacolo-per-mario-toma-a-lecce-venerdi-30\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 30 ottobre, alle 21,\u00a0a Lecce, al teatro Paisiello, va in scena lo spettacolo \u201cAntonio e Marianne: Il suono rivoluzionario nella citt\u00e0 che dorme\u201d. Si tratta di un omaggio ad Antonio\u00a0Toma, imprenditore edile morto anni fa che,\u00a0insieme alla pittrice olandese Marianne Clous, &#8220;fece della loro casa di via Regina Elena il punto d&#8217;incontro degli intellettuali [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62647,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/62645"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=62645"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/62645\/revisions"}],"predecessor-version":[{"id":62649,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/62645\/revisions\/62649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/62647"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=62645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=62645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=62645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}