{"id":63536,"date":"2025-11-03T00:01:00","date_gmt":"2025-11-02T23:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=63536"},"modified":"2025-11-02T09:56:36","modified_gmt":"2025-11-02T08:56:36","slug":"buongiorno-per-tutto-il-giorno-24","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/03\/buongiorno-per-tutto-il-giorno-24\/","title":{"rendered":"DIARIO DEL GIORNO \/ LUNEDI&#8217; 3 NOVEMBRE 2025"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-63537\" title=\"CARCIOFO-COP-Copia\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/CARCIOFO-COP-Copia-300x214.jpg\" alt=\"\" width=\"300\" height=\"214\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/CARCIOFO-COP-Copia-300x214.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/CARCIOFO-COP-Copia.jpg 785w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Buongiorno!<\/p>\n<p>Oggi \u00e8 luned\u00ec 3 novembre 2025.<\/p>\n<p>La Chiesa festeggia Santa Silvia, buon onomastico a tutte le nostre amiche e a tutte le nostre lettrici che portano questo nome.<\/p>\n<p>A Trieste si festeggia San Giusto (uno dei tre Patroni anche di Lecce).<\/p>\n<p>3 novembre 1917. Fronte italiano della Prima Guerra Mondiale. Come oggi, cento e otto fa, uno dei tanti episodi di quell&#8217;assurda carneficina che fu la cos\u00ec detta Grande Guerra.\u00a0 L&#8217;artigliere Alessandro Ruffini viene fucilato per non essersi tolto il sigaro dalla bocca al passaggio del generale Andrea Graziani.<\/p>\n<p>Lavori agricoli da iniziare oggi e da ultimare nel corso del mese.<\/p>\n<p>In giardino si interrano i bulbi delle piante a fioritura primaverile.<\/p>\n<p>Nell&#8217; orto:\u00a0si raccolgono\u00a0i carciofi appena giungono a maturazione, senza lasciarli indurire. Si seminano\u00a0in terreno aperto: fave, piselli, spinaci, aglio e cipolla. Seminano in ambiente protetto: valeriana, lattughe, cicorie, radicchi, rucola, ravanelli, spinaci.<\/p>\n<p>Proverbio salentino:\u00a0<strong>MEGGHIU INVIDIA CA PIETA&#8217;<\/strong><br \/>\nMeglio invidia che piet\u00e0.<br \/>\nErano dei profondi conoscitori dell&#8217;animo umano coloro che coniarono questo modo di dire.<br \/>\nInfatti quando siamo in disgrazia, tutti, conoscenti e amici si impietosiscono, a parole ci esprimono la loro solidariet\u00e0, ma poi o prendono le distanze per non essere in qualche modo coinvolti, o addirittura approfittano del momento di debolezza dell&#8217;altro per trarne vantaggio.<br \/>\nQuando invece si \u00e8 in una situazione invidiabile, finanziariamente, o perch\u00e9 si occupa una posizione di prestigio, \u00a0tutti si mettono a disposizione.<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/03\/buongiorno-per-tutto-il-giorno-24\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/03\/buongiorno-per-tutto-il-giorno-24\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 luned\u00ec 3 novembre 2025. La Chiesa festeggia Santa Silvia, buon onomastico a tutte le nostre amiche e a tutte le nostre lettrici che portano questo nome. A Trieste si festeggia San Giusto (uno dei tre Patroni anche di Lecce). 3 novembre 1917. Fronte italiano della Prima Guerra Mondiale. Come oggi, cento e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63537,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63536"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=63536"}],"version-history":[{"count":16,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63536\/revisions"}],"predecessor-version":[{"id":250945,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63536\/revisions\/250945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/63537"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=63536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=63536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=63536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}