{"id":63798,"date":"2025-11-06T00:01:00","date_gmt":"2025-11-05T23:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=63798"},"modified":"2025-11-05T11:56:01","modified_gmt":"2025-11-05T10:56:01","slug":"buongiorno-per-tutto-il-giorno-27","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/buongiorno-per-tutto-il-giorno-27\/","title":{"rendered":"DIARIO DEL GIORNO \/ GIOVEDI&#8217;\u00a06 NOVEMBRE 2025"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-63800\" title=\"Esate-di-San-Martino-sullEuropa-e-il-Mediterraneo-per-la-prossima-settimana\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/Esate-di-San-Martino-sullEuropa-e-il-Mediterraneo-per-la-prossima-settimana.jpg\" alt=\"\" width=\"480\" height=\"324\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/Esate-di-San-Martino-sullEuropa-e-il-Mediterraneo-per-la-prossima-settimana.jpg 480w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/Esate-di-San-Martino-sullEuropa-e-il-Mediterraneo-per-la-prossima-settimana-300x202.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>Buongiorno!<\/p>\n<p>Oggi \u00e8 gioved\u00ec 6 novembre 2025.<\/p>\n<p>La Chiesa festeggia San Leonardo.<\/p>\n<p>Buon onomastico a chi porta questo nome.<\/p>\n<p>Auguri al nostro amico Antonio Grieco, di Lecce, che compie 61\u00a0 anni: buon compleanno!<\/p>\n<p>Nell&#8217; antica Europa dei Celti, era periodo di festeggiamenti, che duravano una decade, dal primo del mese, al giorno di San Martino.<\/p>\n<p>Siamo gi\u00e0 entrati (nel nostro emisfero boreale)\u00a0nella cos\u00ec detta &#8220;estate di San Martino&#8221;, il nome con cui, come \u00e8 noto,\u00a0viene indicato il\u00a0periodo autunnale in cui, dopo le prime gelate, si verificano condizioni climatiche di bel tempo e relativo tepore.<\/p>\n<p>6 novembre 1994. Ad\u00a0Asti e ad Alessandria, e nelle loro\u00a0province, ad\u00a0Alba\u00a0e in una parte della\u00a0provincia di Cuneo\u00a0esonda il fiume\u00a0Tanaro, che allaga gran parte del territorio, causando oltre settanta vittime ed enormi danni.<\/p>\n<p>Proverbio salentino:<strong> CI CHIANTA FAE COGGHIE UNGULI<\/strong><br \/>\nChi pianta fave raccoglie baccelli.<br \/>\nInsomma si raccoglie ci\u00f2 che si semina, per cui se vuoi raccogliere i frutti devi affrontare la fatica di coltivarne le piante.<br \/>\nE a questo proposito i nostri vecchi raccontavano &#8220;nnu culacchiu&#8221;.<\/p>\n<p>Un giorno un poveraccio preso dai morsi della fame si inoltr\u00f2 in un campo di fave nel periodo in cui questi gustosi legumi erano buoni da mangiare. Dopo averne mangiato a saziet\u00e0 prese la bisaccia che aveva sulla spalla e cominci\u00f2 a riempirla di fave, mentre lo faceva gridava dalla contentezza: &#8221; FAE FAE E FAZZA &#8211; CENTU TUMENI CU NDE FAZZA&#8221; e poi ancora:&#8221; FAE FAEE E FAZZA CENTU&#8230;&#8221;.<\/p>\n<p>Il proprietario del terreno, sopraggiunto sul posto, sentendo questo poveraccio, che implorava ad alta voce la Provvidenza di dare\u00a0&#8220;centu tumeni&#8221; ossia di dare un raccolto abbondante, ne ebbe compassione e rimase nascosto a godersi la scena. Perch\u00e9, se era vero che lo stava derubando, era pur vero che nei confronti di questi chiedeva che il buon Dio fosse generoso.<br \/>\nDopo aver mangiato a saziet\u00e0 ed essersi riempita la bisaccia il motivetto per\u00f2 cambi\u00f2 e da: &#8221; FAE FAE E FAZZA &#8211; CENTU TUMENI CU NDE FAZZA&#8221; pass\u00f2 a: &#8221; E MO CA AGGIU CHINU LA MIA BISAZZA &#8211; QUANTU CAZZU OLE CU NDE FAZZA FAZZA&#8221; &#8230;&#8221; E MO CA AGGIU CHINU LA MIA BISAZZA&#8230;&#8221;, ossia &#8220;ora che ho riempito la mia bisaccia quante ne vuol fare ne faccia&#8221;. Ma non fece in tempo a ripetere il ritornello, che il contadino, proprietario del campo, armato di un nodoso bastone, gli tolse tutte le fave raccolte, e gli mand\u00f2 di traverso quelle che aveva mangiato.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/buongiorno-per-tutto-il-giorno-27\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/buongiorno-per-tutto-il-giorno-27\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 gioved\u00ec 6 novembre 2025. La Chiesa festeggia San Leonardo. Buon onomastico a chi porta questo nome. Auguri al nostro amico Antonio Grieco, di Lecce, che compie 61\u00a0 anni: buon compleanno! Nell&#8217; antica Europa dei Celti, era periodo di festeggiamenti, che duravano una decade, dal primo del mese, al giorno di San Martino. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63798"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=63798"}],"version-history":[{"count":14,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63798\/revisions"}],"predecessor-version":[{"id":251049,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/63798\/revisions\/251049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/63800"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=63798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=63798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=63798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}