{"id":638,"date":"2012-05-03T16:07:09","date_gmt":"2012-05-03T16:07:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/?p=638"},"modified":"2012-11-15T17:15:08","modified_gmt":"2012-11-15T17:15:08","slug":"lecce-candidata-a-capitale-europea-della-cultura-2019","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/03\/lecce-candidata-a-capitale-europea-della-cultura-2019\/","title":{"rendered":"Lecce candidata a capitale europea della cultura 2019"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/Lecce-2019-droppedImage.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft  wp-image-793\" title=\"Lecce 2019 droppedImage\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/Lecce-2019-droppedImage.png\" alt=\"\" width=\"176\" height=\"142\" \/><\/a>La scorsa estate \u00e8 stata lanciata ufficialmente la candidatura di Lecce quale capitale europea della cultura per il 2019.<br \/>\nNon tutti hanno ben chiaro di che cosa si tratti.<br \/>\nProviamo dunque a spiegarlo, sia pure in estrema sintesi. E a contribuire con un nostro progetto specifico.<!--more--><\/p>\n<p>La <strong><em>Capitale europea della cultura<\/em><\/strong> \u00e8 una citt\u00e0 designata dall\u2019Unione Europea\u2026<\/p>\n<p>\u2026che per il periodo di un anno ha la possibilit\u00e0 di mettere in mostra la sua vita e il suo sviluppo culturale. Diverse citt\u00e0 europee hanno sfruttato questo periodo per trasformare completamente la loro base di produzione ed offerta culturale, e facendo ci\u00f2, la loro visibilit\u00e0 internazionale.<\/p>\n<p>Dal 1985, da quando fu lanciata, l&#8217;iniziativa ha avuto sempre pi\u00f9 successo tra i cittadini europei e un crescente impatto culturale sui numerosi visitatori che ha attratto nella localit\u00e0 di volta in volta designata, a sua volta, come \u00e8 facilmente comprensibile, beneficiata da tutta una serie di contributi finalizzati per l\u2019allestimento delle iniziative, ma soprattutto da grandi risvolti di benefici socio \u2013 economici, che si protraggono nel tempo.<\/p>\n<p>Le dimensioni dell\u2019evento, che si svolge nell\u2019arco di un intero anno, rappresenta una sfida considerevole, per cui esiste un sistema di sostegno messo in opera dalla Commissione europea e destinato a supportare la citt\u00e0 nel corso del periodo di preparazione.<\/p>\n<p>Il titolo di capitale europea della cultura insomma\u00a0 genera importanti effetti culturali e socio-economici ed ha straordinarie conseguenze favorevoli sul turismo.<\/p>\n<p>Per Lecce un riconoscimento del genere sarebbe la ciliegina sulla torta della promozione turistica, non solo, ma pure la consacrazione di un processo di crescita, di modernizzazione e di rottura dell\u2019isolamento, attraverso la promozione e la valorizzazione della propria identit\u00e0, iniziato negli ultimi tre lustri.<\/p>\n<p>***<\/p>\n<p>Per ottenere la designazione, anticipata molti anni prima, occorre partecipare a un vero e proprio bando di selezione, comparandosi con le numerose, come \u00e8 facile intuire, citt\u00e0 che si candidano e superarle nel giudizio di un\u2019apposita commissione istituita in sede di Comunit\u00e0 europea.<\/p>\n<p>Attualmente sono state designate le sedi fini al 2016.<\/p>\n<p>Lecce vuole partecipare all\u2019 edizione 2019, quella in fase di organizzazione, il cui bando \u00e8 stato varato nei mesi scorsi e che \u00e8 riservato a una citt\u00e0 italiana.<\/p>\n<p>Si tratta di superare nella fattispecie le vicine Brindisi e Bari, ma pure le agguerrite Venezia, L\u2019Aquila, Matera, Palermo, Perugia, Assisi, Amalfi, Ravenna, Siena, Terni, Torino, Urbino, Catanzaro.<\/p>\n<p>Come si vede, una concorrenza nutrita e qualificata, che, per di pi\u00f9, \u00e8 gi\u00e0 nella fase di avanzata elaborazione sostanziale.<\/p>\n<p>Ma c\u2019\u00e8 tempo fino a dicembre di questo 2012 per formalizzare presso le competenti commissioni nazionale ed europea la prima fase della candidatura, per poi accedere alle fasi successive di quello che sar\u00e0 un vero e proprio concorso per esami duro e difficile.<\/p>\n<p>E\u2019 necessario quindi urgentemente, gi\u00e0 dai prossimi giorni, una concertazione fra enti, associazioni e personalit\u00e0, che elaborino idee concrete con relativi piani di fattibilit\u00e0 da sottoporre alla prossima amministrazione che uscir\u00e0 dalle elezioni dei primi di maggio.<\/p>\n<p>Al nuovo sindaco e al nuovo assessore alla cultura poi il compito di predisporre una sintesi di provvedimenti a breve e medio termine utili a vincere la competizione e ad ottenere la designazione ufficiale della apposita commissione dell\u2019Unione Europea.<\/p>\n<p>Aspettiamo pure che venga scelto il logo ufficiale \u2013 il relativo concorso \u00e8 stato bandito dal comune di Lecce ed \u00e8 scaduto a fine febbraio: a giorni dovremmo conoscerne gli esiti \u2013 se non altro quale primo gesto concreto, una specie di bandiera dietro cui far sfilare le truppe.<\/p>\n<p>***<\/p>\n<p>Intanto, per l\u2019occasione abbiamo elaborato un progetto specifico, attualizzando un\u2019idea che ci piacerebbe entrasse a far parte delle iniziative che Lecce dispiegasse quale capitale europea della cultura 2019.<\/p>\n<p>Abbiamo il piacere di presentarvelo in anteprima.<\/p>\n<p>***<\/p>\n<p><em>La nostra idea consiste nella realizzazione a Lecce o nei territori limitrofi di una Casa dello scrittore.<\/em><\/p>\n<p><em>Essa sar\u00e0 gestita da un&#8217;associazione senza fini di lucro e si avvarr\u00e0, sia per le risorse umane necessarie, sia per le spese correnti di organizzazione, di contributi degli enti locali, di strutture convenzionate, e di sponsor privati, uno principale, altri secondari, oltre a godere di appositi finanziamenti europei.<\/em><\/p>\n<p><em>In particolare, la nostra idea consiste nell&#8217;ospitare una settimana al mese ( due volte l\u2019anno, in inverno e in estate)\u00a0 a Lecce e nel Salento, nell&#8217;apposita struttura, opportunamente individuata fra quelle restaurate, o in fase di restaurazione o recupero conservativo, uno scrittore, o poeta, o saggista, o giornalista ( che per comodit\u00e0 chiameremo semplicemente \u201cscrittore\u201d ) di fama nazionale, o internazionale, con relativo interprete, se necessario, o accompagnatore di sua scelta.<\/em><\/p>\n<p><em>Essi saranno di volta in volta indicati da un\u2019apposita votazione a maggioranza del consiglio comunale. \u00a0<\/em><\/p>\n<p><em>Nel corso della settimana, sar\u00e0 realizzata una serata di gala inaugurale nella Casa dello scrittore, cui saranno invitati gli operatori culturali presso l&#8217; Universit\u00e0 del Salento.<\/em><\/p>\n<p><em>In cambio del soggiorno, del rimborso \u2013 spese e di un \u201cgettone di presenza\u201d da quantificare, l&#8217;ospite si impegner\u00e0 in primo luogo a scrivere nella prossima sua opera, sia essa romanzo, poesia, o saggio, di Lecce e del Salento, quale ambientazione letteraria, o contenuti artistici e culturali; poi, a tenere una serie di conferenze \u2013 dibattiti, o semplici incontri, negli istituti di istruzione di primo e secondo grado del Salento e, infine, una lectio magistralis in Ateneo aperta al pubblico.\u00a0<\/em><\/p>\n<p><em>Negli altri periodi liberi,\u00a0 oltre le due settimane istituzionali organizzate, la Casa dello scrittore ospiter\u00e0 soggiorni \u201cliberi\u201d di giovani scrittori europei, o aspiranti tali, o studenti universitari, ai quali offrir\u00e0 il semplice soggiorno di vitto e alloggio per un paio di settimane\u00a0 \u201ccreative\u201d.<\/em><\/p>\n<p>***<\/p>\n<p>Questa la nostra idea di massima, che vi invitiamo a ripensare e integrare, scrivendo a <a href=\"mailto:info@leccecronaca.it\">info@leccecronaca.it<\/a><\/p>\n<p>Vi invitiamo a seguire inoltre l\u2019evolversi dell\u2019intera situazione per la candidatura di Lecce a capitale europea della cultura 2019 e a sostenerla nei tempi, modi e mezzi pi\u00f9 opportuni.<\/p>\n<p>Chi voglia approfondire in tutti i dettagli, anche specifici, gli argomenti della questione, soprattutto dal punto di vista degli adempimenti sia formali, sia sostanziali, da affrontare, pu\u00f2 consultare il file che alleghiamo qui di seguito.<\/p>\n<p><a href=\"http:\/\/annoeuropeo.files.wordpress.com\/2009\/06\/guida-per-le-citta-candidate-al-titolo-di-capitale-europea-della-cultura-doc633_it.pdf\">Download informazioni complete PDF<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/03\/lecce-candidata-a-capitale-europea-della-cultura-2019\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/03\/lecce-candidata-a-capitale-europea-della-cultura-2019\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La scorsa estate \u00e8 stata lanciata ufficialmente la candidatura di Lecce quale capitale europea della cultura per il 2019. Non tutti hanno ben chiaro di che cosa si tratti. Proviamo dunque a spiegarlo, sia pure in estrema sintesi. E a contribuire con un nostro progetto specifico.<\/p>\n","protected":false},"author":1,"featured_media":639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/638"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions"}],"predecessor-version":[{"id":6526,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions\/6526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}