{"id":64168,"date":"2025-11-09T00:01:00","date_gmt":"2025-11-08T23:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=64168"},"modified":"2025-11-08T09:46:52","modified_gmt":"2025-11-08T08:46:52","slug":"buongiorno-per-tutto-il-giorno-30","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/09\/buongiorno-per-tutto-il-giorno-30\/","title":{"rendered":"DIARIO DEL GIORNO \/ DOMENICA 9 NOVEMBRE 2025"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-129210\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/image-crop-300x194.jpeg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/image-crop-300x194.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/image-crop.jpeg 594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Buongiorno!<\/p>\n<p>Oggi \u00e8 domenica 9 novembre 2025.<\/p>\n<p>La Chiesa festeggia San Teodoro.<\/p>\n<p>Il 9 novembre 1989, crolla il Muro di Berlino, che sancisce la nascita della Germania unita ed \u00e8 considerato il simbolo della fine dei regimi comunisti in Europa.<\/p>\n<p>Data cardine della Storia.<\/p>\n<p>Il <b>Muro di Berlino<\/b> (nome ufficiale: <i>Antifaschistischer Schutzwall<\/i>, Barriera di protezione antifascista<sup id=\"cite_ref-1\" class=\"reference\"><\/sup><sup id=\"cite_ref-2\" class=\"reference\"><\/sup><sup id=\"cite_ref-jung_3-0\" class=\"reference\"><\/sup><sup id=\"cite_ref-4\" class=\"reference\"><\/sup><sup id=\"cite_ref-5\" class=\"reference\"><\/sup>) era un sistema di fortificazioni fatto costruire dal governo della Germania comunista (Repubblica Democratica Tedesca, filosovietica) per impedire che i berlinesi che erano capitati nella Germania comunista scappassero nella Germania occidentale, quella libera e democratica. \u00c8 stato considerato il simbolo della cortina di ferro, linea di confine europea tra la zona d&#8217;influenza statunitense e quella sovietica\u00a0\u00a0durante la cos\u00ec detta Guerra Fredda.<\/p>\n<p>Proverbio salentino: <strong>LU CANE SCAUTATU TIME L&#8217;ACQUA FRIDDA<\/strong><\/p>\n<p>Il cane che si \u00e8 scottato teme l&#8217;acqua fredda.<br \/>\nCos\u00ec come il cane che \u00a0scottatasi la bocca bevendo dell&#8217;acqua calda diventa diffidente e timoroso anche in presenza di quella fresca, allo stesso modo una persona che \u00e8 rimasta scottata dal comportamento di qualcuno, magari di un amico, diventa diffidente nei confronti di tutti gli amici, compresi quelli che non hanno nessuna \u00a0colpa, e che invece sono persone sulle quali si potrebbe contare in qualsiasi momento.<br \/>\nDi questo proverbio esistono diverse versione, ma a noi questa \u00e8 sembrata quella pi\u00f9 corretta, perch\u00e9 gioca su quella che a prima vista sembra una contraddizione, ossia il timore che qualcuno pu\u00f2 avere per l&#8217;acqua fresca, che disseta e rinfresca, ma dopo un attimo di riflessione il paradosso viene meno e si comprende appieno l&#8217;insegnamento di questo antico proverbio.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/09\/buongiorno-per-tutto-il-giorno-30\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/09\/buongiorno-per-tutto-il-giorno-30\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 domenica 9 novembre 2025. La Chiesa festeggia San Teodoro. Il 9 novembre 1989, crolla il Muro di Berlino, che sancisce la nascita della Germania unita ed \u00e8 considerato il simbolo della fine dei regimi comunisti in Europa. Data cardine della Storia. Il Muro di Berlino (nome ufficiale: Antifaschistischer Schutzwall, Barriera di protezione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":190645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64168"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=64168"}],"version-history":[{"count":16,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64168\/revisions"}],"predecessor-version":[{"id":251200,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64168\/revisions\/251200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/190645"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=64168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=64168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=64168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}