{"id":64606,"date":"2015-11-11T16:06:56","date_gmt":"2015-11-11T15:06:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=64606"},"modified":"2015-11-11T16:08:16","modified_gmt":"2015-11-11T15:08:16","slug":"altri-due-arresti-per-droga-a-taurisano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/11\/altri-due-arresti-per-droga-a-taurisano\/","title":{"rendered":"ALTRI DUE ARRESTI PER DROGA A TAURISANO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"469\" height=\"539\" title=\"y - A.I.\" class=\"alignleft size-full wp-image-64607\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-A.I..jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-A.I..jpg 469w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-A.I.-261x300.jpg 261w\" sizes=\"(max-width: 469px) 100vw, 469px\" \/><img decoding=\"async\" loading=\"lazy\" width=\"409\" height=\"488\" title=\"y - I.S.\" class=\"alignleft size-full wp-image-64610\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-I.S..jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-I.S..jpg 409w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/y-I.S.-251x300.jpg 251w\" sizes=\"(max-width: 409px) 100vw, 409px\" \/>(g.m.)______Due giovani di Taurisano,\u00a0Stefano Icaro, 40 anni, e Ivan Abate, 36, (nell&#8217; ordine, nelle foto) sono stati arrestati per detenzione ai fini di spaccio di sostanze stupefacenti. Questa notte, fermatala nel centro del paese,\u00a0a bordo della loro auto, un&#8217; Alfa Romeo 159, gli agenti della Polizia di Stato hanno trovato\u00a0tre panetti di hashish per quasi\u00a0trecento grammi; mezzo grammo di cocaina e 670 euro in banconote di piccolo taglio, pi\u00f9 altri 840 nei portafogli dei due.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/11\/altri-due-arresti-per-droga-a-taurisano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/11\/altri-due-arresti-per-droga-a-taurisano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Due giovani di Taurisano,\u00a0Stefano Icaro, 40 anni, e Ivan Abate, 36, (nell&#8217; ordine, nelle foto) sono stati arrestati per detenzione ai fini di spaccio di sostanze stupefacenti. Questa notte, fermatala nel centro del paese,\u00a0a bordo della loro auto, un&#8217; Alfa Romeo 159, gli agenti della Polizia di Stato hanno trovato\u00a0tre panetti di hashish per quasi\u00a0trecento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64606"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=64606"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64606\/revisions"}],"predecessor-version":[{"id":64612,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/64606\/revisions\/64612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/64610"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=64606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=64606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=64606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}