{"id":66472,"date":"2015-11-27T17:43:39","date_gmt":"2015-11-27T16:43:39","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=66472"},"modified":"2015-11-27T19:23:32","modified_gmt":"2015-11-27T18:23:32","slug":"una-giovane-egiziana-si-racconta-a-leccecronaca-ecco-la-mia-vita-da-precaria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/27\/una-giovane-egiziana-si-racconta-a-leccecronaca-ecco-la-mia-vita-da-precaria\/","title":{"rendered":"UNA GIOVANE EGIZIANA SI RACCONTA A LECCECRONACA.IT \/ Ecco la mia vita da precaria a Il Cairo"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/10410793_10154381946389966_5185414922200236927_n.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"960\" title=\"10410793_10154381946389966_5185414922200236927_n\" class=\"alignright size-full wp-image-66474\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/10410793_10154381946389966_5185414922200236927_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/10410793_10154381946389966_5185414922200236927_n.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/11\/10410793_10154381946389966_5185414922200236927_n-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a>di <strong>Rania Masoud<\/strong>_____<\/p>\n<p>(Rdl______La nostra amica e collaboratrice Rania Masoud, 34 anni, che vive a Il\u00a0Cairo, ha voluto raccontare ai nostri lettori la sua storia, fra &#8220;personale&#8221; e &#8220;politico&#8221;. La ringraziamo della sua preziosa testimonianza, che ci d\u00e0\u00a0la possibilit\u00e0 di guardare in un angolo del mondo di grande attualit\u00e0, e di confrontare le, sia pur amare, esperienze generazionali che condividiamo)______<\/p>\n<p>Dal 2011, in seguito agli episodi di terrorismo,\u00a0non c&#8217;\u00e8 pi\u00f9 tanto turismo in Egitto. Cos\u00ec sta venendo meno quella che era la\u00a0nostra vera ricchezza.<\/p>\n<p>Io mi sono laureata 2002 in lingue: italiana, inglese e arabo.<\/p>\n<p>La mia storia pubblica \u00e8 cominciata nella facolt\u00e0, dove\u00a0alcuni professori e professoresse trattavano gli studenti in modo molto strano e discriminatorio, privilegiando\u00a0gli studenti che avevano\u00a0avuto la possibilit\u00e0 di\u00a0frequentare corsi fuori dal nostro Paese: cos\u00ec\u00a0avevano occhi e cuore solamente per chi era stato in Europa, mentre per tutti gli altri no.<\/p>\n<p>Inoltre privilegiavano gli studenti provenienti da famiglie ricche e quelli di famiglie dei loro parenti.<\/p>\n<p>Io, che non ero stata all&#8217; estero, che non sono ricca e che non ho parenti importanti, ho sofferto molto la differenza\u00a0di trattamento in\u00a0facolt\u00e0.<\/p>\n<p>Nonostante tutto mi sono laureata e, subito dopo la laurea,\u00a0ho cominciato a cercare lavoro dappertutto e ho fatto di tutto\u00a0per avere un lavoro in un Paese che dipendeva essenzialmente dal turismo.\u00a0Creavo tutte le occasioni possibili per dimostrare tutte le mie capacit\u00e0.<\/p>\n<p>Finalmente ho trovato il lavoro nella galleria del papiro. Ho\u00a0mosso cos\u00ec i miei primi passi\u00a0proprio nel settore\u00a0 in\u00a0cui sognavo di lavorare.<\/p>\n<p>Studiavo, e lavoravo in due &#8211;\u00a0tre\u00a0posti diversi,\u00a0per risparmiare i soldi necessari per scrivermi nell&#8217;Istituto del turismo, \u00a0che costava un occhio nella testa.<\/p>\n<p>Ma ci sono riuscita: dopo tre anni ho\u00a0conseguito la patente di guida turistica legale.<\/p>\n<p>Inoltre, facevo anche l&#8217; insegnante di lingue nelle organizzazioni private.<\/p>\n<p>Purtroppo, dal 2011 in poi, per le ragioni cui ho accennato,\u00a0le possibilit\u00e0 si sono ridotte di molto, al massimo potevo lavorare qualche ora, due o tre volte a settimana,\u00a0in una stagione come l&#8217;inverno, specialmente nel periodo di Natale.<\/p>\n<p>Partecipavo\u00a0ad altre attivit\u00e0 culturali e di volontariato, in centri privati e pubblici.<\/p>\n<p>Cos\u00ec mi \u00e8 venuta l&#8217; idea di comprare la bicicletta per diffondere la cultura sportiva nella citt\u00e0 del Cairo.<\/p>\n<p>Avere la bicicletta in una comunit\u00e0 egiziana per una ragazza \u00e8 molto strano, addirittura\u00a0alcuni lo considerano una specie di maleducazione.<\/p>\n<p>Ho cercato di spargere i vantaggi di comprare la bicicletta invece di avere le macchine che contaminano l&#8217;aria. Ho messo le mie foto sui siti sociali come Facebook.<\/p>\n<p>Ho scritto il mio diario sulle situazioni che succedevano in strada e su come la gente considera una ragazza che gira in\u00a0bicicletta.<\/p>\n<p>Da 2010 fino\u00a0a quest&#8217; anno ho fatto di tutto per convincere la comunit\u00e0 egiziana\u00a0ad accettare questa nuova idea di mobilit\u00e0. Ho aiutato tante ragazze e donne a comprare le biciclette. Alcune hanno venduto effettivamente le loro macchine per avere le biciclette.<\/p>\n<p>Per\u00f2 poi \u00e8 successo che una di quelle donne ha rubato il mio diario e ha pubblicato\u00a0un suo libro, sia pur in modo molto superficiale. Ha\u00a0usato un canale televisivo per pubblicizzarlo, insieme all&#8217; idea che mi aveva rubato: ha copiato\u00a0tutte le mie iniziative, perfino l&#8217;idea di\u00a0centri di addestramento per donne in\u00a0bici.<\/p>\n<p>Il capitalismo diffuso dominante nella nostra comunit\u00e0 l&#8217; ha &#8216;adottata&#8217; e l&#8217; ha aiutata, certo per fare soldi, non con fini etici, o ecologici.<\/p>\n<p>E cos\u00ec \u00e8 diventato illusione anche il progetto che\u00a0avevo creato.<\/p>\n<p>La nostra rivoluzione del gennaio 2011 era proprio contro gli aspetti negativi del capitalismo dominante e dei suoi effetti devastanti\u00a0sulle tradizioni e sulla moralit\u00e0 di una comunit\u00e0 come questa egiziana.<\/p>\n<p>Qui da noi ancora adesso i giovani di modesta estrazione sociale\u00a0non vengono sostenuti ed aiutati. Ricchi e poveri non sono uguali nemmeno nei sogni: i ricchi li possono realizzare, ai poveri invece glieli rubano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/27\/una-giovane-egiziana-si-racconta-a-leccecronaca-ecco-la-mia-vita-da-precaria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/11\/27\/una-giovane-egiziana-si-racconta-a-leccecronaca-ecco-la-mia-vita-da-precaria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Rania Masoud_____ (Rdl______La nostra amica e collaboratrice Rania Masoud, 34 anni, che vive a Il\u00a0Cairo, ha voluto raccontare ai nostri lettori la sua storia, fra &#8220;personale&#8221; e &#8220;politico&#8221;. La ringraziamo della sua preziosa testimonianza, che ci d\u00e0\u00a0la possibilit\u00e0 di guardare in un angolo del mondo di grande attualit\u00e0, e di confrontare le, sia pur [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":66474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/66472"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=66472"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/66472\/revisions"}],"predecessor-version":[{"id":66478,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/66472\/revisions\/66478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/66474"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=66472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=66472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=66472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}