{"id":67655,"date":"2015-12-10T15:03:38","date_gmt":"2015-12-10T14:03:38","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=67655"},"modified":"2015-12-10T15:34:21","modified_gmt":"2015-12-10T14:34:21","slug":"alessandro-cecchi-paone-sbugiardato-da-il-tempo-e-la-storia-di-massimo-bernardini","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/alessandro-cecchi-paone-sbugiardato-da-il-tempo-e-la-storia-di-massimo-bernardini\/","title":{"rendered":"POLEMICHE TELEVISIVE \/ STUDIA, ALESSANDRO!"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/Alessandro_Cecchi_Paone_2.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"Alessandro_Cecchi_Paone_2\" class=\"alignleft size-medium wp-image-67702\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/Alessandro_Cecchi_Paone_2-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/Alessandro_Cecchi_Paone_2-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/Alessandro_Cecchi_Paone_2.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(m.v.)_____Da uno come Cecchi Paone, che ha insegnato marketing della comunicazione culturale alla Bocconi, ci si aspetterebbe un utilizzo pi\u00f9 corretto delle parole, per non parlare di quel \u00a0minimo di rispetto che si dovrebbe tenere per \u00a0la verit\u00e0 storica.<br \/>\nSe l&#8217;utilizzo di alcuni vocaboli, per ignoranza o per malafede, \u00a0avvenisse ad opera di politici \u00a0nostrani, o intrattenitori televisivi che occupano Rai e Mediaset, sarebbe normale, ma da chi si definisce divulgatore scientifico e culturale, non \u00e8 accettabile.<br \/>\nIn occasione di questo Giubileo le trasmissioni sul Papa attuale si sono sprecate.<br \/>\nOramai non c&#8217;\u00e8 trasmissione in cui si parli di chiesa cattolica, dove non venga invitato quel prete laico che \u00e8 Cecchi Paone che d\u00e0 giudizi, e \u00a0spiega, lui che \u00e8 laico, come si dovrebbero comportare gli uomini di chiesa e i fedeli.<br \/>\nNell&#8217;ultima comparsata televisiva, come al solito, con la violenza che lo contraddistingue, ha contestato tutto ci\u00f2 che la Chiesa di Roma proclama, dichiarando per\u00f2 che questo Papa gli sta simpatico, che sta facendo grandi cose, ricordando tra l&#8217;altro che\u00a0 quando era Vescovo in Argentina Bergoglio si \u00e8 battuto contro la dittatura fascista di Videla.<\/p>\n<p>Ora, uno dei primi attacchi subiti da \u00a0Bergoglio, subito dopo essere stato eletto Papa, \u00e8 stato proprio quello in cui gli veniva rimproverato di non essersi battuto con la necessaria energia contro il regime di Videla, ma a parte ci\u00f2, \u00a0se in Argentina c&#8217;\u00e8 stato un movimento politico che in qualche modo pu\u00f2 essere accostato al Fascismo italiano, questo \u00e8 il Peronismo.<br \/>\nEd \u00e8 stato proprio Videla, con la complicit\u00e0 degli Stati Uniti, che fece il colpo di stato che destitu\u00ec\u00a0Maria Estela\u00a0Martinez\u00a0Peron, eletta democraticamente, ricordiamolo, insieme al marito,\u00a0\u00a0con il 60% dei voti.<br \/>\nPer cui se Cecchi Paone avesse voluto a tutti i costi tirare in ballo il Fascismo, che con l&#8217;Argentina c&#8217;entra come \u00a0cavoli a merenda, avrebbe dovuto, paradossalmente dire, che Bergoglio si \u00e8 battuto contro il regime \u00a0dell&#8217;antifascista Videla.<br \/>\nMa la cosa pi\u00f9 simpatica \u00e8 stata che lo stesso giorno nella trasmissione che va su Rai Tre, &#8221; Il Tempo e La storia&#8221; il conduttore Massimo Bernardini insieme allo storico suo ospite, ha ripercorso correttamente quella che \u00e8 stata la vita di Papa Bergoglio, e anche della diplomazia che questi ha dovuto mettere in campo, per salvaguardare l&#8217;incolumit\u00e0 degli uomini della Chiesa argentina.<br \/>\nNoi comprendiamo che Alessandro Cecchi Paone, \u00a0massone dichiarato affiliato al Grande Oriente d&#8217;Italia, \u00a0principale obbedienza della massoneria italiana, abbia poca simpatia per la Chiesa, e nutra un\u00a0odio feroce per chi, come il Fascismo, la Massoneria sciolse, ma distorcere il significato delle parole e dei fatti non \u00e8 cosa lodevole.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/alessandro-cecchi-paone-sbugiardato-da-il-tempo-e-la-storia-di-massimo-bernardini\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/alessandro-cecchi-paone-sbugiardato-da-il-tempo-e-la-storia-di-massimo-bernardini\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(m.v.)_____Da uno come Cecchi Paone, che ha insegnato marketing della comunicazione culturale alla Bocconi, ci si aspetterebbe un utilizzo pi\u00f9 corretto delle parole, per non parlare di quel \u00a0minimo di rispetto che si dovrebbe tenere per \u00a0la verit\u00e0 storica. Se l&#8217;utilizzo di alcuni vocaboli, per ignoranza o per malafede, \u00a0avvenisse ad opera di politici \u00a0nostrani, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":67702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67655"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=67655"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67655\/revisions"}],"predecessor-version":[{"id":67705,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67655\/revisions\/67705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/67702"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=67655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=67655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=67655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}