{"id":67706,"date":"2015-12-10T16:57:42","date_gmt":"2015-12-10T15:57:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=67706"},"modified":"2015-12-10T18:48:04","modified_gmt":"2015-12-10T17:48:04","slug":"ultim-ora-menti-raffinatissime-all-opera-ecco-perche-snam-e-entrata-nell-affare-tap-con-la-benedizione-del-ministro-dello-sviluppo-economico-e-della-ditta-del-pd","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/ultim-ora-menti-raffinatissime-all-opera-ecco-perche-snam-e-entrata-nell-affare-tap-con-la-benedizione-del-ministro-dello-sviluppo-economico-e-della-ditta-del-pd\/","title":{"rendered":"ULTIM&#8217;ORA \/ &#8216;MENTI RAFFINATISSIME&#8217; ALL&#8217; OPERA, ECCO PERCHE&#8217; SNAM E&#8217; ENTRATA POCHI GIORNI FA NELL&#8217; &#8216;AFFAIRE&#8217; TAP, CON LA BENEDIZIONE DEL MINISTRO DELLO SVILUPPO ECONOMICO. E DELLA &#8216;DITTA&#8217; DEL PD"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/800px-Federica_Guidi.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"668\" height=\"1024\" title=\"800px-Federica_Guidi\" class=\"alignleft size-large wp-image-67707\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/800px-Federica_Guidi-668x1024.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/800px-Federica_Guidi-668x1024.jpg 668w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/800px-Federica_Guidi-195x300.jpg 195w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/800px-Federica_Guidi.jpg 800w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/><\/a><\/strong>di<strong> Giuseppe Puppo<\/strong>______<\/p>\n<p>Adesso forse abbiamo compreso. Forse: vogliamo condividere con i nostri amici e i nostri lettori qualche ragionamento.<\/p>\n<p>Ma forse abbiamo capito bene perch\u00e9, a distanza di anni dall&#8217; avvio del consorzio multinazionale, finanziato dagli organismi dell&#8217; alta finanza, che tolgono le materie prime ai popoli e le mettono al servizio di pochi speculatori internazionali, oltre a depredare, e a devastare i territori, come vorebbero fare col nostro Salento, solo pochi giorni fa Snam, l&#8217; azienda di distribuzione del gas in Italia, abbia acquistato una quota di Tap, o, per meglio dire, Tap abbia ceduto una quota alla Snam.<\/p>\n<p>Non l&#8217; avevamo mica capito, e invano avevamo chiesto lumi in giro, su che senso potesse avere una operazione del genere.<\/p>\n<p>Intanto \u00e8 successo che il ministero dello sviluppo economico ha inserito il tratto Melendugno \u2013 Mesagne previsto da Tap nella rete dei gasdotti nazionali, in quanto allaccerebbe cos\u00ec il metano proveniente dall&#8217; Azebaijan alla propria rete, che parte appunto da Mesagne: un&#8217; opera quindi di \u201cinteresse strategico\u201d nazionale, quindi, non pi\u00f9 privata, quindi capace con ci\u00f2 di superare le resistenze, vere o presunte, di altri organismi istituzionali, Regione Puglia in primo luogo.<\/p>\n<p>A proposito di Regione Puglia, il consigliere regionale del M5S Antonio Trevisi, al quale si deve la notizia &#8211; denuncia, rilanciata dalle agenzie da pochi minuti, la Regione avrebbe tempo fino al 19 prossimo, quindi poco pi\u00f9 di una settimana, per presentare ricorso al Tar contro la decisione del ministero, in quanto presa senza i necessari pareri autorizzativi di sua competenza.<\/p>\n<p>In realt\u00e0, la questione parte da mesi prima ed \u00e8 ben pi\u00f9 complessa, a tal punto che \u00e8 finanche impossibile farne una efficace sintesi giornalistica, uscendo da un guazzabuglio pressoch\u00e9 inestricabile di atti burocratici.<\/p>\n<p>Vera o presunta che sia stata finora l&#8217; opposizione formale, o sostanziale della Regione Puglia, rimane adesso quest&#8217; ultima verifica, che per\u00f2, ammesso e non concesso che ci si arrivi, appare al momento molto debole, di fronte all&#8217; abile forzatura operata in questi ultimi giorni dal ministro dello sviluppo economico Federica Guidi (nella foto), del Pd, imprenditrice che fa parte della Commissione Trilateral dell&#8217; alta finanza internazionale.<\/p>\n<p>Insomma, menti raffinatissime hanno operato in questi ultimi giorni un&#8217; ultima forzatura per costruire il gasdotto, voluto dal Pd, voluto da D&#8217; Alema e dai suoi in Puglia, dalle banche di cui sono attigui, dalle strutture dell&#8217; alta finanza internazionale di cui fan parte e dagli speculatori delle multinazionali di cui sono complici, visti i ritardi e le difficolt\u00e0 trovate dal progetto in fase esecutiva.<\/p>\n<p>Rimane il ruolo di Michele Emiliano e dei suoi rapporti con la ditta del suo Pd: da quanto si pu\u00f2 capire e intuire di conseguenza, tutte le sue dichiarazioni, i suoi distinguo, le sue acrobazie verbali e i suoi esercizi di dialettica in libert\u00e0 sono semplicemente un esercizio\u00a0fine a s\u00e9 stesso, utile solo a lui, perch\u00e9 dovrebbe salvargli la faccia di fronte agli elettori Pugliesi, salentini in particolare.<\/p>\n<p>Oggi, per esempio, se ne \u00e8 andato a fare turismo politico a Bruxelles,\u00a0per dire alla conferenza per il clima in corso di svolgimento che la Puglia\u00a0non utilizzer\u00e0 pi\u00f9 carbone entro dieci anni:\u00a0&#8220;<em>L&#8217;occasione ci viene dato dall&#8217;accordo internazionale che l&#8217;Italia ha siglato per l&#8217;arrivo sulle coste pugliesi del gasdotto Tap<\/em>&#8220;, ha sostenuto, quindi con un&#8217; implicita e pure esplicita accettazione, anzi, rivendicazione sostanziale, dell&#8217; &#8216;affaire&#8217; gasdotto.<\/p>\n<p>Magari il ricorso lo presenter\u00e0 pure: ma debole, e vanificato dal progetto ministeriale negli ultimi sviluppi spuntati fuori oggi, progetto di cui egli, o chi per lui, \u00e8 parte in causa e parte organica, al di l\u00e0 del sofisticato gioco delle tre tavolette burocratiche in atto.<\/p>\n<p>Poi lo perder\u00e0, ovvio: ma potr\u00e0 sempre dire \u201cIo ero contrario, io ho fatto ricorso\u201d, e concludere allo stesso modo con cui ha concluso due mesi fa la vicenda delle eradicazioni degli ulivi: \u201c<em>Non posso farci nulla<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/ultim-ora-menti-raffinatissime-all-opera-ecco-perche-snam-e-entrata-nell-affare-tap-con-la-benedizione-del-ministro-dello-sviluppo-economico-e-della-ditta-del-pd\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/10\/ultim-ora-menti-raffinatissime-all-opera-ecco-perche-snam-e-entrata-nell-affare-tap-con-la-benedizione-del-ministro-dello-sviluppo-economico-e-della-ditta-del-pd\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo______ Adesso forse abbiamo compreso. Forse: vogliamo condividere con i nostri amici e i nostri lettori qualche ragionamento. Ma forse abbiamo capito bene perch\u00e9, a distanza di anni dall&#8217; avvio del consorzio multinazionale, finanziato dagli organismi dell&#8217; alta finanza, che tolgono le materie prime ai popoli e le mettono al servizio di pochi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":67707,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67706"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=67706"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67706\/revisions"}],"predecessor-version":[{"id":67709,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/67706\/revisions\/67709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/67707"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=67706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=67706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=67706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}