{"id":69672,"date":"2015-01-01T01:01:51","date_gmt":"2015-01-01T00:01:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=69672"},"modified":"2015-12-28T17:30:14","modified_gmt":"2015-12-28T16:30:14","slug":"diario-del-giorno-dopo-musica-l-uomo-che-canta-da-tenore-ad-arnesano-sabato-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/01\/diario-del-giorno-dopo-musica-l-uomo-che-canta-da-tenore-ad-arnesano-sabato-2\/","title":{"rendered":"DIARIO DEL GIORNO DOPO \/ MUSICA \/ L&#8217; UOMO CHE CANTA DA TENORE AD ARNESANO SABATO 2"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/12299161_528967270598522_3318546708912892972_n.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"199\" title=\"12299161_528967270598522_3318546708912892972_n\" class=\"alignleft size-medium wp-image-69673\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/12299161_528967270598522_3318546708912892972_n-300x199.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/12299161_528967270598522_3318546708912892972_n-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/12\/12299161_528967270598522_3318546708912892972_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Sabato 2 gennaio, alle 19.30, ad Arnesano, presso il palazzo Marchesale, in via Giuseppe Garibaldi, ci sar\u00e0 un recital\u00a0del tenore leccese Francesco Spedicato (nella foto), in una serata promossa dall\u2019AVIS\u00a0e dalla LILT (lega italiana per la lotta contro i tumori), con la collaborazione dell\u2019associazione culturale \u201cOrpheo per l\u2019alba di domani\u201d.<\/p>\n<p>Con lui e Claudia Presicci, sul palco,\u00a0per lo spettacolo \u201cVi racconto\u2026l\u2019Uomo che canta da tenore&#8221;, Gaio Ariani (I mandolino), Lorella Falcone (II mandolino), Sergio Vacca (mand\u00f2la), che si uniscono alla chitarra di Vito Mannarini e le percussioni di Matteo Spedicato.<\/p>\n<p>Dirige il maestro Eliseo Castrignano.<\/p>\n<p>Ospite d\u2019onore la pianista salentina Beatrice Rana.<\/p>\n<p>Ingresso libero.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/01\/diario-del-giorno-dopo-musica-l-uomo-che-canta-da-tenore-ad-arnesano-sabato-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/01\/diario-del-giorno-dopo-musica-l-uomo-che-canta-da-tenore-ad-arnesano-sabato-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sabato 2 gennaio, alle 19.30, ad Arnesano, presso il palazzo Marchesale, in via Giuseppe Garibaldi, ci sar\u00e0 un recital\u00a0del tenore leccese Francesco Spedicato (nella foto), in una serata promossa dall\u2019AVIS\u00a0e dalla LILT (lega italiana per la lotta contro i tumori), con la collaborazione dell\u2019associazione culturale \u201cOrpheo per l\u2019alba di domani\u201d. Con lui e Claudia Presicci, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69673,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/69672"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=69672"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/69672\/revisions"}],"predecessor-version":[{"id":69674,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/69672\/revisions\/69674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/69673"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=69672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=69672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=69672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}