{"id":70473,"date":"2016-01-09T01:01:41","date_gmt":"2016-01-09T00:01:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=70473"},"modified":"2016-01-05T15:06:05","modified_gmt":"2016-01-05T14:06:05","slug":"diario-del-giorno-dopo-freebike-giro-del-salento-a-lecce-domenica-10","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/01\/09\/diario-del-giorno-dopo-freebike-giro-del-salento-a-lecce-domenica-10\/","title":{"rendered":"DIARIO DEL GIORNO DOPO \/ FREE BIKE \/ GIRO DEL SALENTO A LECCE DOMENICA 10"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/01\/castello_acaya.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"131\" title=\"castello_acaya\" class=\"alignleft size-medium wp-image-70474\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/01\/castello_acaya-300x131.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/01\/castello_acaya-300x131.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/01\/castello_acaya-1024x449.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/01\/castello_acaya.jpg 1400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Domenica 10 gennaio, alle 8.00, a Lecce, con partenza da Piazza Sant&#8217; Oronzo, prender\u00e0 il via la settima tappa della quarta edizione della &#8216;Free bike Salento&#8217;, organizzata dall&#8217; associazione &#8216;Salento e &#8211; cycling. Dopo aver girato il centro storico della citt\u00e0, la carovana si diriger\u00e0 verso l&#8217; oasi naturalistica delle Cesine, nel cuore della macchia mediterranea, poi verso Acaya, percorrendo le mulattiere che collegano il piccolo centro fortificato al mare, passando inoltre per le grotte ipogee usate come sepoltura dai moncai basiliani.<\/p>\n<p>Dopo la visita al castello di Acaya (nella foto), il ritorno a Lecce citt\u00e0.<\/p>\n<p>Il ricavato dalle quote di iscrizione sar\u00e0 interamente devoluto alla Lega Italiana Lotta Tumori,<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/01\/09\/diario-del-giorno-dopo-freebike-giro-del-salento-a-lecce-domenica-10\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/01\/09\/diario-del-giorno-dopo-freebike-giro-del-salento-a-lecce-domenica-10\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domenica 10 gennaio, alle 8.00, a Lecce, con partenza da Piazza Sant&#8217; Oronzo, prender\u00e0 il via la settima tappa della quarta edizione della &#8216;Free bike Salento&#8217;, organizzata dall&#8217; associazione &#8216;Salento e &#8211; cycling. Dopo aver girato il centro storico della citt\u00e0, la carovana si diriger\u00e0 verso l&#8217; oasi naturalistica delle Cesine, nel cuore della macchia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/70473"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=70473"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/70473\/revisions"}],"predecessor-version":[{"id":70476,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/70473\/revisions\/70476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/70474"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=70473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=70473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=70473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}