{"id":7092,"date":"2012-11-21T17:00:37","date_gmt":"2012-11-21T17:00:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=7092"},"modified":"2013-01-15T08:16:52","modified_gmt":"2013-01-15T08:16:52","slug":"qualche-riflessione-sul-nostro-scontento-salentino-la-situazione-e-grave","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/21\/qualche-riflessione-sul-nostro-scontento-salentino-la-situazione-e-grave\/","title":{"rendered":"Qualche riflessione sul nostro scontento salentino \/ LA SITUAZIONE E\u2019 GRAVE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/21\/qualche-riflessione-sul-nostro-scontento-salentino-la-situazione-e-grave\/1-convitto-palmieri-san-francesco-della-scarpa-lecce\/\" rel=\"attachment wp-att-7093\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/1.Convitto-Palmieri-San-Francesco-della-Scarpa-Lecce-150x150.jpg\" alt=\"\" title=\"1.Convitto-Palmieri-San-Francesco-della-Scarpa-Lecce\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-7093\" \/><\/a>(g.p.) Quando, tanti anni fa, frequentavo il \u201cPalmieri\u201d anche io e scrivevo \u2013 mutatis mutandis: sul cartaceo, ovvio &#8211; per qualcosa di simile alla rubrica \u201cSottobanco\u201d che leccecronaca.it ha creato per dar voce ai ragazzi e far raccontare da essi stessi la vita delle scuole, c\u2019era il mio compagno di banco che ogni qualvolta dovesse prendere la parola in pubblico, assemblea, o riunione che fosse, o anche per iscritto, esordiva sempre in tono solenne cominciando con la frase: \u201dLa situazione \u00e8 grave!\u201d.<\/p>\n<p>L\u2019 incipit memorabile mi viene buono adesso che scrivo \u2013 sull\u2019elettronico, ovvio \u2013 per raccontare quello che succede intorno a me, nel bene, nel male, per chiedermene i significati e per proporne, se possibile, un senso, ora che la situazione \u00e8 grave veramente.<\/p>\n<p>Tante le spie, fra pubblico e privato, che me lo indicano. Sono le parole che sento nei bar dove entro a prendere il caff\u00e8; sono i frammenti di un discorso doloroso che ascolto mentre dal tabaccaio aspetto per le sigarette e la ricarica del telefono; sono gli sguardi dell\u2019edicolante che incrocio sul marciapiede in piedi davanti alla sua \u201ccasetta\u201d verde; sono i racconti che mi fanno il mio editore, un mio amico, gli esercenti che contatto, o tento di contattare, le persone con le quali parlo per lavoro, e ancora di pi\u00f9 quelle con cui parlo per piacere, io che di economia capisco poco e punto, io che non frequento i mercati, finanziari, bens\u00ec quelli della piazza e delle piazzette la domenica, i miei osservatori privilegiati, io che non so altrimenti di borsa, se non quella della spesa.<\/p>\n<p>Una rilevazione univoca, un minimo comune denominatore, un\u2019impressione generalizzata: pochi e niente soldi in tasca, ancora meno fiducia nel cuore, tanta rabbia in corpo, in testa speranza ridotta pressoch\u00e9 a zero.<\/p>\n<p>E\u2019 quest\u2019ultimo il dato pi\u00f9 allarmante.<\/p>\n<p>Crisi significa scelta. Nei periodi di crisi bisogna scegliere, e cos\u00ec magari reagire in maniera costruttiva. Nei periodi di crisi pi\u00f9 che in altri bisogna aprirsi e cercare nuove dimensioni, nuove opportunit\u00e0, articolando risposte immediate, costruendo alternative se non altro di speranza immediata, ma che poi piano piano divengano opportunit\u00e0 e speranza per altri.<\/p>\n<p>Favorire nel senso di consentire i consumi virtuosi, delineare occasioni concrete, uscire dalla spirale della tassazione, della stretta, della recessione, del debito e dell\u2019asfissia da strangolamento del debito.<\/p>\n<p>Con qualche idea di generazione radicale, che spetterebbe alla politica trovare e indicare, per diminuire il debito pubblico di fiducia verso le istituzioni, per abbattere lo spread dello con la disperazione.<\/p>\n<p>Se no avremo e forse abbiamo gi\u00e0 non problemi di ordine pubblico, ma problemi di emergenza sociale, perch\u00e9 a questo inevitabilmente si arriva: a bloccare il traffico, a bruciare il tricolore, a lamentarsi in preda alla disperazione in seduta permanente effettiva, come quotidianamente segnalano le spie a Lecce.<\/p>\n<p>Beh, cosa fa la politica mentre queste spie si accendono e lampeggiano in maniera sempre pi\u00f9 allarmante?<\/p>\n<p>Mentre a Roma si discute sulla prossima legge elettorale, a Lecce le famiglie non hanno soldi per campare.<\/p>\n<p>Cosa volete che importi di premi di maggioranza e quorum a chi \u00e8 assillato dal mutuo cui non riesce pi\u00f9 a far fronte?<\/p>\n<p>Mentre a Roma e a Lecce si aprono i comitati elettorali per le primarie, le esigenze primarie degli Italiani vengono di giorno in giorno sempre di pi\u00f9 negate.<\/p>\n<p>Il regime della casta pensa soltanto a s\u00e9 stesso ed \u00e8 diviso solamente su chi prima e meglio debba occupare le poltrone del potere: la tristosa macchina da guerra del Pd, che, pur divisa in maniera insanabile nei tronconi di osservanza, di falso rinnovamento e di utopica affabulazione, conta di vincere; o l\u2019improponibile apparato di quel che resta del Pdl. Sullo sfondo la nuova formazione che con l\u2019ennesimo scimmiottamento di quel partito comunque serio che era la Dc, uniti ai pierferdinandi e ai gianfranchi alle prese con il compito ingrato di sopravvivere a s\u00e9 stessi, ai tanti disastri combinati.<\/p>\n<p>Stando cos\u00ec le cose, dobbiamo tutti allora cercare quella risposta che non arriva dalla politica dentro di noi. C\u2019\u00e8 ancora tempo per decidere se andare a votare per Beppe Grillo, se non andare a votare proprio, o se scendere per strada nella rivolta epocale.<\/p>\n<p>Ancora qualche mese per valutare quelle che sembrano le uniche opzioni concrete, per decidere quale attuare.<\/p>\n<p>Intanto, cerchiamo dentro noi stessi, impariamo a pensare in maniera creativa, diamo fondo al coraggio e all\u2019intraprendenza. Noi di leccecronaca.it per quel po\u2019 che sappiamo fare, in quel po\u2019 in cui siamo competenti, ci stiamo provando. Non \u00e8 soltanto informazione ( riflessione ricerca documentazione) quella che ogni giorno vi proponiamo. E\u2019 un messaggio di speranza e un invito di coraggio che con ogni nostro articolo vi mandiamo, sperando di poter stringere la mano di ognuno di voi e da voi di poter ricevere una pacca sulla spalla, dietro ai vostri clic quotidiani.<\/p>\n<p>p.s.<\/p>\n<p>Clic quotidiani che fra l\u2019altro \u2013 ci permettiamo di comunicarvelo con soddisfazione, tanto per chiudere almeno con una cosa bella \u2013 sono sempre di pi\u00f9, per numero di singoli accessi e per numero di pagine viste, ogni giorno meglio di quello precedente.<\/p>\n<p>Ne gioiamo insieme a voi, ma solo per un attimo. Cominciamo adesso. E poi appunto insieme a voi vogliamo continuare, voi, siete voi, non i lettori, siete voi, solo voi i protagonisti, nella nostra comunit\u00e0, o community che dir si voglia. Insieme\u2026Siamo una squadra fortissimi.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/21\/qualche-riflessione-sul-nostro-scontento-salentino-la-situazione-e-grave\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/21\/qualche-riflessione-sul-nostro-scontento-salentino-la-situazione-e-grave\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) Quando, tanti anni fa, frequentavo il \u201cPalmieri\u201d anche io e scrivevo \u2013 mutatis mutandis: sul cartaceo, ovvio &#8211; per qualcosa di simile alla rubrica \u201cSottobanco\u201d che leccecronaca.it ha creato per dar voce ai ragazzi e far raccontare da essi stessi la vita delle scuole, c\u2019era il mio compagno di banco che ogni qualvolta dovesse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7092"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=7092"}],"version-history":[{"count":15,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7092\/revisions"}],"predecessor-version":[{"id":9887,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7092\/revisions\/9887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/7093"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=7092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=7092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=7092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}