{"id":720,"date":"2012-05-12T09:08:39","date_gmt":"2012-05-12T09:08:39","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/?p=720"},"modified":"2012-05-15T17:14:33","modified_gmt":"2012-05-15T17:14:33","slug":"da-fiumicino-a-calalzo-cancelliamo-equitalia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/12\/da-fiumicino-a-calalzo-cancelliamo-equitalia\/","title":{"rendered":"Da Fiumicino a Calalzo, cancelliamo Equitalia"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/images.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft  wp-image-675\" title=\"images\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/images.jpg\" alt=\"\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/images.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/05\/images-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a>Forte e chiara presa di posizione al consiglio comunale di Fiumicino.<\/p>\n<p>Riportiamo le parole del capogruppo di \u201dNoi insieme\u201d Luigi Satta per la loro semplicit\u00e0, ma al tempo stesso per la loro determinazione, superiori a quelle delle pur numerose dichiarazioni di altri politici, o atti pubblici ufficiali, di cui abbiamo avuto riscontro negli ultimi mesi.<!--more--><\/p>\n<p>Mettono a fuoco la questione in maniera pressoch\u00e9 perfetta.<\/p>\n<p>&lt;Da mesi Equitalia spa \u00e8 al centro di un forte dibattito.<\/p>\n<p>Da molti viene indicata come la principale causa dei problemi economici che stanno attraversando famiglie e imprenditori a causa dei metodi adottati e gli altissimi interessi applicati nella riscossione. Qui non si discute il diritto dovere di ogni cittadini a pagare i tributi, ma la metodologia di Equitalia che molto spesso condanna il piccolo contribuente al tracollo finanziario.<\/p>\n<p>Le notizie che quotidianamente vengono pubblicate dai media sono allarmanti.<\/p>\n<p>I suicidi di imprenditori e cittadini strozzati dal sistema messo in campo da Equitalia sono preoccupanti e generano uno sconforto tale da paragonare queste metodologie a quelle praticate dagli usurai.<\/p>\n<p><strong>Considerato che la legge dello stato italiano n. 388\/2000 art 36 e legge n.106\/2011 prevede che tutti i comuni possano riscuotere direttamente i crediti vantati nei confronti dei cittadini e delle imprese senza delegare Equitalia, <\/strong>auspico che\u00a0 tutte le forze politiche convengano sulla necessit\u00e0 di recedere da tutti i contratti stipulati con Equitalia&gt;<\/p>\n<p>_______________________________________________________<\/p>\n<p>Cancellare Equitalia si pu\u00f2. Guadagnandoci, per giunta, da parte degli enti pubblici creditori.<\/p>\n<p>Si pu\u00f2 pure assicurare alle famiglie italiane, di cui tutti i politici si riempiono la bocca, di fumo senza arrosto, un livello migliore di assistenza sociale, non dico come in Svezia, o in Francia, o altri esempi virtuosi, ma almeno decente: e oggi le politiche sociali italiane sono nettamente indecenti.<\/p>\n<p>L\u2019esempio viene da Calalzo del Cadore.<\/p>\n<p><em>\u00a0\u00abAi genitori abbiamo dato un buono beb\u00e8 da trecento euro. Agli studenti di prima media e prima superiore un contributo di centocinquanta euro per i libri di testo. A coloro che devono andare a scuola a Belluno una partecipazione di trecento euro sui cinquecentocinquanta del costo dell\u2019abbonamento del pullman. Questi sono i benefici per i nostri cittadini grazie al risparmio di tredicimila euro\u00bb.\u00a0<\/em><\/p>\n<p>L\u2019elenco virtuoso riempie di orgoglio Luca De Carlo, trentanove anni, del Pdl, agente di commercio che dal 2009 fa il sindaco di Calalzo a tempo pieno.<\/p>\n<p>Adesso tutti citano la sua mossa anticipatrice che lo ha portato alla fine del 2010 a dare il benservito ad Equitalia.<\/p>\n<p>\u00c8 diventato un modello, un esempio da seguire. \u00a0.<\/p>\n<p>Cos\u00ec la racconta in breve il sindaco De Carlo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Com\u2019\u00e8 cominciata questa storia?<\/strong><\/p>\n<p>\u00abHo parlato con i dipendenti e abbiamo verificato la possibilit\u00e0 di farci carico delle notifiche ordinarie delle cartelle Tarsu e Ici. E cos\u00ec ho predisposto una delibera che poneva in carico al Comune questo servizio\u00bb.<\/p>\n<p><strong>Il risparmio?<\/strong><\/p>\n<p>\u00ab\u00c8 derivato dalla cifra che Equitalia si trattiene per ogni pratica e che varia secondo alcuni parametri. Abbiamo calcolato di aver avuto un guadagno di circa sei euro per ciascuno dei duemiladuecentoquaranta abitanti di Calalzo. E abbiamo predisposto un apposito capitolo per l\u2019uso di queste risorse\u00bb.<\/p>\n<p><strong>E per le riscossioni coattive nei confronti di chi \u00e8 in mora?<\/strong><\/p>\n<p>\u00abIn questo caso abbiamo fatto una scelta politica. Non volevamo pi\u00f9 continuare ad essere complici di un sistema troppo aggressivo nei confronti del cittadino. Per questo servizio ci siamo avvalsi della Comunit\u00e0 Montana Valbelluna che era gi\u00e0 strutturata per effettuarlo\u00bb.<\/p>\n<p><strong>I risultati?<\/strong><\/p>\n<p>\u00abAbbiamo recuperato con il cittadino un rapporto pi\u00f9 umano nella riscossione delle tasse. E lui ha risparmiato sui costi aggiuntivi imposti da Equitalia. Padoa Schioppa diceva che pagare le tasse \u00e8 bello. Per me non \u00e8 cos\u00ec, ma almeno il cittadino ha dimostrato di pagarle pi\u00f9 volentieri, visto che c\u2019\u00e8 stato un aumento del 16% dei versamenti regolari\u00bb.<\/p>\n<p><strong>Che cosa ha insegnato l\u2019esperienza di Calalzo?<\/strong><\/p>\n<p>\u00abAbbiamo anticipato di un anno e mezzo la situazione che si dovrebbe creare dal gennaio 2013 per tutti. Ma sollevando un vero polverone &#8211; che \u00e8 consistito semplicemente nell\u2019applicare una legge dello Stato &#8211; abbiamo evitato che ci possano essere altre proroghe nell\u2019assegnare ai Comuni i compiti di riscossione di Equitalia\u00bb.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/12\/da-fiumicino-a-calalzo-cancelliamo-equitalia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/12\/da-fiumicino-a-calalzo-cancelliamo-equitalia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Forte e chiara presa di posizione al consiglio comunale di Fiumicino. Riportiamo le parole del capogruppo di \u201dNoi insieme\u201d Luigi Satta per la loro semplicit\u00e0, ma al tempo stesso per la loro determinazione, superiori a quelle delle pur numerose dichiarazioni di altri politici, o atti pubblici ufficiali, di cui abbiamo avuto riscontro negli ultimi mesi.<\/p>\n","protected":false},"author":1,"featured_media":675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/720"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":14,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/720\/revisions"}],"predecessor-version":[{"id":724,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/720\/revisions\/724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/675"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}