{"id":73423,"date":"2016-02-02T20:48:41","date_gmt":"2016-02-02T19:48:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=73423"},"modified":"2016-02-02T20:49:24","modified_gmt":"2016-02-02T19:49:24","slug":"giornata-nel-salento-per-il-comandante-generale-dell-arma-dei-carabinieri-tullio-de-sette-reportage-fotografico","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/02\/02\/giornata-nel-salento-per-il-comandante-generale-dell-arma-dei-carabinieri-tullio-de-sette-reportage-fotografico\/","title":{"rendered":"GIORNATA A LECCE E NEL SALENTO PER IL COMANDANTE GENERALE DELL&#8217; ARMA DEI CARABINIERI TULLIO DE SETTE &#8211; reportage fotografico"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7126.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1056\" height=\"704\" title=\"DSC_7126\" class=\"alignleft size-full wp-image-73424\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7126.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7126.jpg 1056w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7126-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7126-1024x682.jpg 1024w\" sizes=\"(max-width: 1056px) 100vw, 1056px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7352.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1440\" height=\"960\" title=\"DSC_7352\" class=\"alignleft size-full wp-image-73425\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7352.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7352.jpg 1440w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7352-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7352-1024x682.jpg 1024w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7436.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1160\" height=\"773\" title=\"DSC_7436\" class=\"alignleft size-full wp-image-73426\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7436.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7436.jpg 1160w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7436-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/02\/DSC_7436-1024x682.jpg 1024w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a>(g.m.)______Il Comandante Generale dell\u2019Arma dei Carabinieri Tullio Del Sette ha visitato oggi\u00a0il Comando Provinciale di Lecce. Accolto dal Comandante Provinciale, Colonnello Nicodemo Macr\u00ec ed accompagnato dal Comandante della Legione Carabinieri Puglia, Generale di Brigata, Giovanni Cataldo, il Comandante Generale ha incontrato rappresentanze del personale dell\u2019Arma, delegati degli organi di rappresentanza, nonch\u00e9 il coordinatore provinciale e alcuni presidenti delle Sezioni dell\u2019Associazione Nazionale Carabinieri, oltre che\u00a0con gli insigniti e i parenti di medaglie d\u2019oro dell\u2019Arma residenti in Lecce e provincia.<\/p>\n<p>Il Comandante Generale ha espresso la sua soddisfazione per l\u2019impegno profuso nei diversificati ambiti di lavoro caratterizzati sia dalla criminalit\u00e0 comune che da quella organizzata ed ha poi esortato a continuare a operare con rinnovato slancio e incisivit\u00e0, assicurando sempre quella vicinanza al cittadino che, da sempre, \u00e8 prerogativa di ciascun Carabiniere.<\/p>\n<p>Il Comandante Generale ha proseguito la visita presso le Compagnia Carabinieri di Maglie, Tricase e Gallipoli per poi ripartire alla volta di Roma.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/02\/02\/giornata-nel-salento-per-il-comandante-generale-dell-arma-dei-carabinieri-tullio-de-sette-reportage-fotografico\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/02\/02\/giornata-nel-salento-per-il-comandante-generale-dell-arma-dei-carabinieri-tullio-de-sette-reportage-fotografico\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Il Comandante Generale dell\u2019Arma dei Carabinieri Tullio Del Sette ha visitato oggi\u00a0il Comando Provinciale di Lecce. Accolto dal Comandante Provinciale, Colonnello Nicodemo Macr\u00ec ed accompagnato dal Comandante della Legione Carabinieri Puglia, Generale di Brigata, Giovanni Cataldo, il Comandante Generale ha incontrato rappresentanze del personale dell\u2019Arma, delegati degli organi di rappresentanza, nonch\u00e9 il coordinatore provinciale e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73424,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73423"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=73423"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73423\/revisions"}],"predecessor-version":[{"id":73429,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73423\/revisions\/73429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/73424"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=73423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=73423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=73423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}