{"id":73995,"date":"2026-02-09T00:01:00","date_gmt":"2026-02-08T23:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=73995"},"modified":"2026-02-07T11:19:34","modified_gmt":"2026-02-07T10:19:34","slug":"buongiorno-per-tutto-il-giorno-90","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/09\/buongiorno-per-tutto-il-giorno-90\/","title":{"rendered":"DIARIO DEL GIORNO \/ LUNEDI&#8217; 9 FEBBRAIO 2026"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-194798 size-large\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Inaugurazione_Metropolitana_di_Roma_-_1955_imagefullwide-1024x819.jpg\" alt=\"\" width=\"1024\" height=\"819\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Inaugurazione_Metropolitana_di_Roma_-_1955_imagefullwide-1024x819.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Inaugurazione_Metropolitana_di_Roma_-_1955_imagefullwide-300x240.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Inaugurazione_Metropolitana_di_Roma_-_1955_imagefullwide-768x614.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Inaugurazione_Metropolitana_di_Roma_-_1955_imagefullwide.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Buongiorno!<\/p>\n<p>Oggi \u00e8 luned\u00ec 9 febbraio 2026.<\/p>\n<p>San Sabino.<\/p>\n<p>Da questo pomeriggio siamo in Luna in Ultimo Quarto.<\/p>\n<p>Questa fase \u00e8 un momento di consolidamento, bisogna lasciarsi alle spalle quanto acquisito per avanzare; \u00e8 un buon periodo per rompere le relazioni e i contratti d\u2019affari, disintossicarsi e depurarsi.<\/p>\n<p>Il corpo dispensa energia; si tende a non ingrassare anche se si mangia di pi\u00f9, le operazioni riescono meglio, le faccende di casa pure, in particolare quelle che hanno a che fare con il pulire, il lavare, lo sciacquare.<\/p>\n<p>E\u2019\u00a0il momento giusto per dipingere e laccare (i colori si asciugano meglio), nonch\u00e9 per effettuare tagli ritardanti dei capelli (compresa la depilazione) e per i massaggi rilassanti e disintossicanti.<br \/>\nAl contrario, nel mondo vegetale i succhi si ritirano verso la radice, la terra \u00e8 pi\u00f9 ricettiva: per questo vanno piantate o seminate in luna calante le verdure che crescono sotto terra.<\/p>\n<p>Sono i giorni giusti per effettuare i trattamenti contro i parassiti e contro le erbacce; anche le potature sono favorite; se una pianta o albero non cresce pi\u00f9 o \u00e8 malato, in luna calante si taglia la cima (meglio se verso la luna nuova). Le verdure a foglia (insalate, spinaci, cavolo bianco e rosso) vanno piantate in questa fase.<br \/>\nLo stesso tipo di energie della luna calante si ritrovano nella fase che segue l\u2019ovulazione, in cui l\u2019ovulo \u00e8 stato rilasciato, ma non fecondato; \u00e8 un fase caratterizzata da un enorme rilascio di energia all\u2019interno di s\u00e9, che se non viene positivamente incanalata pu\u00f2 anche sfociare in una crescente irrequietezza, distruttivit\u00e0, rabbia e frustrazione.<\/p>\n<p>Per chi ha il pollice verde ricordiamo nello specifico i lavori da dedicare all&#8217;orto e al giardino in questo mese appena cominciato.<br \/>\nRincalzate fave, piselli, agli e cipolle seminate nell\u2019autunno precedente. Procedete alle nuove semine, facendo attenzione ai ritorni di freddo. Semine in ambiente protetto: lattughe primaverili, cicorie, radicchi, indivie; cavoli estivi, bieta da taglio; peperoni, melanzane, pomodori; sedano, basilico, prezzemolo. Semine in terreno aperto: aglio, cipolle, carote, bieta da taglio; cicorie da taglio; agretti, asparagi, piselli, spinaci, fave.<br \/>\nPotate rose ed arbusti da giardino. Tagliate i vecchi gerani a circa 10 cm dal colletto e rinvasateli. Preparate le marze per gli innesti, tenendole o nella sabbia al freddo, o in una busta di nylon in frigo. Mettete a dimora i bulbi a fioritura primaverile. Rinfoltite il tappeto erboso concimandolo.<\/p>\n<p>9 febbraio 1956, settanta anni fa, a Roma il presidente della Repubblica Luigi Einaudi inaugura la prima linea metropolitana italiana, fra la stazione Termini e il quartiere Eur.<\/p>\n<p>Proverbio salentino: <strong>CI OLE BISCIA NNA BONA ANNATA, NATALE SCIUTTU E PASCA BAGNATA.<\/strong><br \/>\nChi vuol vedere una buona annata, Natale asciutto e Pasqua bagnata.<br \/>\nI contadini salentini ritengono che un inverno asciutto permetta ai semi interrati di meglio radicarsi, e la pioggia primaverile aiuter\u00e0 le piante a dare un abbondante raccolto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/09\/buongiorno-per-tutto-il-giorno-90\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/09\/buongiorno-per-tutto-il-giorno-90\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 luned\u00ec 9 febbraio 2026. San Sabino. Da questo pomeriggio siamo in Luna in Ultimo Quarto. Questa fase \u00e8 un momento di consolidamento, bisogna lasciarsi alle spalle quanto acquisito per avanzare; \u00e8 un buon periodo per rompere le relazioni e i contratti d\u2019affari, disintossicarsi e depurarsi. Il corpo dispensa energia; si tende a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":194798,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73995"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=73995"}],"version-history":[{"count":26,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73995\/revisions"}],"predecessor-version":[{"id":255040,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/73995\/revisions\/255040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/194798"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=73995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=73995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=73995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}