{"id":7892,"date":"2012-12-03T14:56:08","date_gmt":"2012-12-03T14:56:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=7892"},"modified":"2013-01-15T08:15:26","modified_gmt":"2013-01-15T08:15:26","slug":"linferno-vicino-a-noi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/03\/linferno-vicino-a-noi\/","title":{"rendered":"L\u2019INFERNO VICINO A NOI"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/03\/linferno-vicino-a-noi\/fumi\/\" rel=\"attachment wp-att-7893\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/fumi-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-7893\" \/><\/a>(g.p.)<\/strong> Dice: <strong>tanto si sapeva<\/strong>. Sapevano tutti a Taranto in qualche modo, e hanno taciuto, i pi\u00f9 in cambio del posto fisso, stipendio sicuro, liquidazione e pensione assicura, come se gi\u00e0 quel lavoro non fosse una vera e propria\u00a0 rappresentazione della condanna biblica e dovesse diventare pure un\u2019alternativa alla salute; gli altri, tutti gli altri, dai servitori dello Stato ai servitori di Dio, giornalisti compresi ed \u00e8 una vergogna nella vergogna, in cambio di mazzette, vantaggi mafiosi, carriere, favori .<\/p>\n<p>Dice: ma <strong>tanto era gi\u00e0 inquinata<\/strong>, dai tempi dell\u2019 arsenale militare all\u2019amianto, dell\u2019Italsider, dell\u2019ospedale per la cura dei tumori appositamente previsto e saggiamente sistemato a 20 km e pure in tutt\u2019altra direzione anti \u2013 correnti aeree: come se al peggio non debba per forza esserci mai fine e qualcosa che \u00e8 pericolosa non possa essere risanata, ma debba essere fatta diventare letale, la rappresentazione dell\u2019altra condanna divina, della morte sicura anticipata, a credito e a saldo di una vita appena elevata\u00a0 a quelle soglie minimo di benessere, da ceto medio vecchio stampo, quel ceto medio che prima era emergente e ora \u00e8 immerso e anzi affondato,\u00a0 pagato a caro prezzo.<\/p>\n<p>Dice: <strong>ma a Lecce che ce ne frega<\/strong>, fino a Taranto sono 78 km e poi quelli hanno un altro passato, un presente diverso e niente futuro. Come se i fumi e gli scarichi velenosi della E321, l\u2019altissima ciminiera di ben 210 metri, non arrivassero anche nel Salento, magari unendosi a quelli della centrale di Cerano dall\u2019altro lato. Come se la vicenda non fosse una vera e propria rappresentazione emblematica della fine della nostra Seconda Repubblica: ritengo infatti,\u00a0 pur senza voler fare il profeta da strapazzo, comunque scusatemi se ipotizzo, che <strong>come Tangentopoli distrusse la prima, cos\u00ec Ilvopoli distrugger\u00e0 la seconda, anzi, l\u2019ha gi\u00e0 minata nelle fondamenta su cui si reggeva.<\/strong><\/p>\n<p><span style=\"text-decoration: underline\">E cos\u00ec ora ne sappiamo abbastanza. Avevamo fatto cattivi pensieri, ma la realt\u00e0 si \u00e8 rivelata peggiore<\/span>.<\/p>\n<p>C\u2019\u00e8 un\u2019azienda di importanza strategica che invece di essere risanata, resa compatibile con l\u2019ambiente e valorizzata, viene ceduta dallo Stato, che si accolla i debiti, a un privato, che si accolla gli utili: ok, il prezzo \u00e8 giusto. Correva l\u2019anno 1995: lo Stato era, agli inizi gi\u00e0 abortiti della seconda Repubblica, il presidente del consiglio Lamberto Dini, il privato che acquista a credito e in comode rate un suo parente acquisito, l\u2019industriale di lungo corso Emilio Riva.<\/p>\n<p>L\u2019inferno, invece che essere regolato, si surriscalda. Nel mondo impianti simili vengono messi a norma, perch\u00e9 l\u2019acciaio \u00e8 strategico per tutti, anche se cos\u00ec il costo di produzione aumenta; a\u00a0 Taranto non si investe n\u00e9 in sicurezza n\u00e9 in bonifica, in maniera da rendere il prezzo del prodotto finito competitivo sul mercato internazionale, nella logica dell\u2019aziendalizzazione che tanti danni e anzi sconquassi ha prodotto nell\u2019epoca nostra.<\/p>\n<p>Gli altri altoforni chiudono, quelli di Taranto aumentano, come i profitti del gruppo, che vanno a occultarsi chiss\u00e0 dove, ma che stime attendibili, le ultime disponibili, quantificano in un\u2019entit\u00e0 in euro compresa fra un miliardo e un miliardo e mezzo negli ultimi tre anni, una cifra, scusatemi, che non\u00a0 solo non riesco a scrivere, ma non riesco nemmeno a concepire. Concepisco per\u00f2 quello che sta emergendo adesso, in questi giorni, di ore in ore: soldi pagati a tutti, in primis i politici della casta, di tutti e due gli schieramenti, e tutti coinvolti, tutti\u00a0 asserviti, in un modo o nell\u2019altro, dai vertici aziendali, di cui come l\u2019ex prefetto Ferrante alcuni provengono: da quella sinistra per giunta considerata nuova e bella, che nella migliore delle ipotesi ha assecondato in buona e cattiva fede, ai vertici istituzionali, dai ministeri interessati, dall\u2019industria, all\u2019ambiente, a quelli regionali, agli enti locali.<\/p>\n<p><strong>Tutti sapevano, tutti coinvolti. <\/strong><\/p>\n<p>Mentre a Taranto si muore e ci si ammala molto di pi\u00f9 che in ogni altra parte, non solo e non voglio mettermi a giocare con le cifre e cola la medicina: fosse soltanto una vita in pi\u00f9, rispetto alle cause chiamiamole naturali, non varrebbe un miliardo e mezzo di euro di profitto di Emilio Riva, e purtroppo non \u00e8 una sola, sono decine, centinaia nel corso degli anni, migliaia oramai fra trascorsi e prospettive, come le malattie degenerative chiaramente e direttamente indotte dalla fabbrica dei veleni. Mentre a Taranto la fabbrica dei veleni continua a riversare nell\u2019atmosfera sostanze altamente nocive, tossiche , letali e le correnti aeree le spargono ai quattro venti, compresi \u00a0quelli che le portano qui nel Salento.<\/p>\n<p>Il Ministro dell&#8217;Ambiente Corrado Clini, ha recentemente dichiarato che <em>\u201di dati sulla mortalit\u00e0 per tumore pubblicati dall&#8217;Istituto superiore di sanit\u00e0 e dall&#8217; osservatorio dei tumori della Puglia proverebbero che la mortalit\u00e0 per tumore della citt\u00e0 di Lecce \u00e8 superiore a quella di Taranto<\/em>\u201d; il presidente dell&#8217;Ilva Bruno Ferrante che \u201c<em>la citt\u00e0 di Lecce \u00e8 pi\u00f9 inquinata di Taranto<\/em>&#8220;.<\/p>\n<p>Dichiarazioni che ove corrispondessero a verit\u00e0 dovrebbero far balzare tutti dalle sedie, e che invece a Lecce sono state accolte col solito pressappochismo, o menefreghismo, come se fossero le polemiche sulla squadra di calcio. L\u2019unico ad allarmarsi \u00e8 stato il consigliere Carlo Salvemini, che ha chiesto e ottenuto un consiglio comunale monotematico e\u00a0 aperto, con la partecipazione di esperti e periti, per discutere la situazione e i pericoli sulle popolazioni salentine.<\/p>\n<p>Sono passati due mesi e di questo fantomatico consiglio, del consigliere che l\u2019aveva sollecitato e del sindaco che l\u2019aveva concesso, non se ne sa pi\u00f9 nulla.<\/p>\n<p>Il prossimo consiglio comunale \u00e8 previsto per il 10 dicembre: \u00e8 convocato su undici punti, su questioni che abbracciano l\u2019universo modo, ma non su quella che dovrebbe avere la priorit\u00e0 e l\u2019esclusiva.<\/p>\n<p>Infatti ricordo che il sindaco ha fra i suoi poteri, ma anche fra i suoi doveri, quelli di adottare le ordinanze contingibili e \u00a0urgenti in caso di emergenze\u00a0<em>sanitarie<\/em>\u00a0o di igiene pubblica.<\/p>\n<p>Per tutti questi motivi l\u2019inferno ci \u00e8 vicino e lo seguiremo attentamente tutto quanto, perch\u00e9 c\u2019\u00e8 la necessita urgentissima di capire e far capire, seguire e far intervenire, in quelli che saranno i dirompenti sviluppi, fino \u2013 perch\u00e9 dobbiamo farcela, tutti assieme- a uscirne fuori, in un modo o nell\u2019altro.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/03\/linferno-vicino-a-noi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/03\/linferno-vicino-a-noi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) Dice: tanto si sapeva. Sapevano tutti a Taranto in qualche modo, e hanno taciuto, i pi\u00f9 in cambio del posto fisso, stipendio sicuro, liquidazione e pensione assicura, come se gi\u00e0 quel lavoro non fosse una vera e propria\u00a0 rappresentazione della condanna biblica e dovesse diventare pure un\u2019alternativa alla salute; gli altri, tutti gli altri, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7892"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=7892"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7892\/revisions"}],"predecessor-version":[{"id":9861,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/7892\/revisions\/9861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/7893"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=7892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=7892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=7892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}